{"id":17502,"count":3,"description":"","link":"https:\/\/eltecolote.org\/content\/en\/tag\/sf-public-bank-coalition\/","name":"SF Public Bank Coalition","slug":"sf-public-bank-coalition","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SF Public Bank Coalition Archives - El Tecolote<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltecolote.org\/content\/en\/tag\/sf-public-bank-coalition\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SF Public Bank Coalition Archives - El Tecolote\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltecolote.org\/content\/en\/tag\/sf-public-bank-coalition\/\" \/>\n<meta property=\"og:site_name\" content=\"El Tecolote\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/10\/facebook.png?fit=8672%2C4960&quality=80&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"8672\" \/>\n\t<meta property=\"og:image:height\" content=\"4960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@eltecolotesf\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/en\\\/tag\\\/sf-public-bank-coalition\\\/\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/en\\\/tag\\\/sf-public-bank-coalition\\\/\",\"name\":\"SF Public Bank Coalition Archives - El Tecolote\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\"},\"inLanguage\":\"en\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"name\":\"El Tecolote\",\"description\":\"San Francisco's Latinx newspaper since 1970\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\",\"name\":\"El Tecolote\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"width\":400,\"height\":400,\"caption\":\"El Tecolote\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTecoloteSF\\\/\",\"https:\\\/\\\/x.com\\\/eltecolotesf\",\"https:\\\/\\\/www.instagram.com\\\/eltecolotesf\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SF Public Bank Coalition Archives - El Tecolote","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltecolote.org\/content\/en\/tag\/sf-public-bank-coalition\/","og_locale":"en_US","og_type":"article","og_title":"SF Public Bank Coalition Archives - El Tecolote","og_url":"https:\/\/eltecolote.org\/content\/en\/tag\/sf-public-bank-coalition\/","og_site_name":"El Tecolote","og_image":[{"width":8672,"height":4960,"url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/10\/facebook.png?fit=8672%2C4960&quality=80&ssl=1","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@eltecolotesf","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/eltecolote.org\/content\/en\/tag\/sf-public-bank-coalition\/","url":"https:\/\/eltecolote.org\/content\/en\/tag\/sf-public-bank-coalition\/","name":"SF Public Bank Coalition Archives - El Tecolote","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/#website"},"inLanguage":"en"},{"@type":"WebSite","@id":"https:\/\/eltecolote.org\/content\/#website","url":"https:\/\/eltecolote.org\/content\/","name":"El Tecolote","description":"San Francisco's Latinx newspaper since 1970","publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltecolote.org\/content\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en"},{"@type":"Organization","@id":"https:\/\/eltecolote.org\/content\/#organization","name":"El Tecolote","url":"https:\/\/eltecolote.org\/content\/","logo":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","width":400,"height":400,"caption":"El Tecolote"},"image":{"@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTecoloteSF\/","https:\/\/x.com\/eltecolotesf","https:\/\/www.instagram.com\/eltecolotesf\/"]}]}},"_links":{"self":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/tags\/17502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts?tags=17502"},{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/newspack_nl_cpt?tags=17502"},{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/newspack_popups_cpt?tags=17502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}