{"id":54492,"date":"2023-01-12T16:00:53","date_gmt":"2023-01-13T00:00:53","guid":{"rendered":"https:\/\/eltecolote.org\/content\/?p=54492"},"modified":"2023-01-12T16:00:56","modified_gmt":"2023-01-13T00:00:56","slug":"demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis","status":"publish","type":"post","link":"https:\/\/eltecolote.org\/content\/es\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\/","title":{"rendered":"Demandar m\u00e1s a los funcionarios electos, especialmente en tiempos de crisis"},"content":{"rendered":"\n<p><em>[por Christian Medina Beltz y Kate Bueler]<\/em><\/p>\n\n\n\n<p><em>Nota del Editor: Las opiniones expresadas en este comentario son responsabilidad de los autores y no necesariamente reflejan las de sus empleadores.&nbsp;<\/em><\/p>\n\n\n\n<p>\u00bfY si nosotros, el pueblo, decidimos todos exigir m\u00e1s?<\/p>\n\n\n\n<p>De nuestro gobierno. De nuestros funcionarios electos.<\/p>\n\n\n\n<p>De nuestros servidores sociales, que est\u00e1n destinados a protegernos.<\/p>\n\n\n\n<p>Y lo m\u00e1s importante de nuestro alcalde, London Breed.<\/p>\n\n\n\n<p>La alcaldesa London Breed es la mejor pagada del pa\u00eds, con ingresos anuales de $430 mil. Le pagan m\u00e1s que a Gavin Newsom. S\u00ed, ha le\u00eddo bien, ella gana sustancialmente m\u00e1s que el gobernador de California.<\/p>\n\n\n\n<p>Breed ha resistido la tormenta de liderar una pandemia, el malestar social, la recesi\u00f3n econ\u00f3mica y las duras realidades ante las que nuestros sistemas locales y nacionales se est\u00e1n desmoronando. Tambi\u00e9n ha afrontado algunas tormentas pol\u00edticas propias: violaciones \u00e9ticas y multas en las que us\u00f3 su cargo para su propio beneficio, m\u00e1s recientemente la revelaci\u00f3n de al menos 48 cartas de renuncia sin fecha requeridas a su propio personal, as\u00ed como los comentarios abiertamente racistas contra la comunidad latinx, emitidos en una entrevista.<\/p>\n\n\n\n<p>Ser alcalde durante una pandemia es algo que cualquiera puede entender, nada f\u00e1cil. Pero vivir aqu\u00ed, en San Francisco, como residente es a\u00fan m\u00e1s dif\u00edcil, especialmente cuando se tiene en cuenta el privilegio y el poder, la raza y la clase, el capital social, pol\u00edtico y cultural.<\/p>\n\n\n\n<p>Estamos viviendo tiempos hist\u00f3ricos y lo hemos estado desde 2020. Colectivamente, estamos agotados, dolidos y necesitados de protecci\u00f3n. Ya hemos sobrevivido a tantas tormentas. El 24 de diciembre llovi\u00f3. Llovi\u00f3 m\u00e1s y m\u00e1s r\u00e1pido y m\u00e1s fuerte. Precipitaciones hist\u00f3ricas causaron inundaciones.<\/p>\n\n\n\n<p>Ninguna publicaci\u00f3n en las redes sociales por parte de London Breed advirti\u00f3 sobre c\u00f3mo navegar las inundaciones, ni alguna informaci\u00f3n de emergencia, apoyo para personas sin hogar, refugios de emergencia. Su equipo de 31, a los que se les paga $200 mil al a\u00f1o (un total de al menos $6 millones) permanecieron en silencio. Mientras los servicios de emergencia nos pidieron no salir a las calles, Breed acudi\u00f3 a su fiesta de A\u00f1o Nuevo, publicada por otros en las redes sociales.<\/p>\n\n\n\n<p>No hubo informaci\u00f3n, anuncio o apoyo por parte de la oficina de la alcald\u00eda. No supimos de la alcaldesa hasta el lunes despu\u00e9s de su sesi\u00f3n informativa para prepararnos para la pr\u00f3xima serie de tormentas hist\u00f3ricas. Ella culp\u00f3 al Servicio Meteorol\u00f3gico Nacional de no prepararla y de ser la raz\u00f3n de su inacci\u00f3n tras la tormenta durante la v\u00edspera de a\u00f1o nuevo.<\/p>\n\n\n\n<p>Minti\u00f3. Sab\u00eda que ment\u00eda, incluso al saber que hab\u00eda registro de ello: el Servicio Meteorol\u00f3gico Nacional proporcion\u00f3 pruebas de informarle con 10 d\u00edas de anticipaci\u00f3n y estuvo presente en una reuni\u00f3n de preparaci\u00f3n.<\/p>\n\n\n\n<p>Nuestra alcaldesa tuvo con antelaci\u00f3n informaci\u00f3n sobre c\u00f3mo protegernos, pero no la comparti\u00f3 y luego minti\u00f3 al respecto. Deja que eso se hunda.<\/p>\n\n\n\n<p>D\u00edas despu\u00e9s nos enteramos por qu\u00e9 no la vimos en las calles de nuestra ciudad brindando apoyo de emergencia, ni para una conferencia de prensa, ni siquiera para una publicaci\u00f3n en las redes sociales. Estaba demasiado ocupada: Despu\u00e9s de su fiesta de a\u00f1o nuevo, vol\u00f3 a Las Vegas para ver a los amados 49 desde un palco de lujo con E-40, un rapero muy conocido del \u00c1rea de la Bah\u00eda. Sonriente y festejando en las redes sociales para que todos lo vean. Estuvo ausente, mientras su ciudad m\u00e1s la necesitaba.<\/p>\n\n\n\n<p>Actu\u00f3 al estilo Ted Cruz, un acto del que los liberales todav\u00eda se burlan. Si le exigimos responsabilidad a un conservador fuera de nuestro estado, \u00bfqu\u00e9 le pedimos a nuestra alcaldesa de nuestra ciudad \u201cliberal\u201d?<\/p>\n\n\n\n<p>Si no puede prepararnos, estar con nosotros durante y ayudarnos despu\u00e9s de una emergencia, entonces, \u00bfcu\u00e1l es su funci\u00f3n? Hay seis art\u00edculos sobre el papel del rol del alcalde durante una emergencia de poder y deberes con incisos, entre los que se destacan:<\/p>\n\n\n\n<p>\u201c. . . el Alcalde queda facultado y ser\u00e1 su deber:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Elaborar y expedir normas y reglamentos sobre asuntos razonablemente relacionados con la protecci\u00f3n de la vida y los bienes afectados por dicha emergencia;<\/li>\n\n\n\n<li>Para obtener suministros vitales, equipo y otras propiedades que se encuentren faltantes y necesarias para la protecci\u00f3n de la vida y la propiedad y obligar a la Ciudad y al Condado por el valor justo de los mismos y, si es necesario, apoderarse inmediatamente de los mismos para uso p\u00fablico. . .\u201d<\/li>\n<\/ol>\n\n\n\n<p>Esto es inaceptable, imprudente como m\u00ednimo y negligente en gravedad. Merecemos una alcaldesa que nos diga la verdad. Merecemos una que nos apoye en cualquier emergencia que amenace la vida. La necesitamos en las calles arremang\u00e1ndose o sacando la chaqueta junto a nosotros limpiando los desag\u00fces pluviales, controlando los da\u00f1os por inundaciones en nuestros hogares y apoyando a los muchos peque\u00f1os negocios afectados con ayuda econ\u00f3mica y, como m\u00ednimo, una aut\u00e9ntica disculpa. La necesitamos en nuestro barco liderando el camino y manteni\u00e9ndonos tranquilos con informaci\u00f3n y apoyo. Necesitamos la verdad.<\/p>\n\n\n\n<p>Cancele todos sus cortes de cinta. Cancela todos tus eventos. Cancele toda la pelusa en este trabajo y pres\u00e9ntese ante nosotros. Este es el evento en el que debe estar. Hizo una promesa de protegernos.<\/p>\n\n\n\n<p>A\u00fan no hay comentarios por parte de la oficina de la alcald\u00eda. Ninguna disculpa por volar a su suite de lujo cuando la necesit\u00e1bamos. Duele. Al igual que la ciudad que ama, se hace fantasma y se deja en lectura. Debemos exigir m\u00e1s para obtener lo que nos merecemos.<\/p>\n\n\n\n<p>Exijamos m\u00e1s. Nosotros, el pueblo, lo merecemos.<\/p>\n\n\n\n<p>Christian Medina Beltz es un narrador en muchos medios, que utiliza su plataforma como un medio de progreso e inclusi\u00f3n cultural.<\/p>\n\n\n\n<p>Kate Bueler es una consejera universitaria; recauda&nbsp; fondos para nuestros ni\u00f1os y j\u00f3venes en la ciudad, que usa las redes sociales para el activismo en el trato de la esperanza y la creaci\u00f3n de sue\u00f1os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[por Christian Medina Beltz y Kate Bueler] Nota del Editor: Las opiniones expresadas en este comentario son responsabilidad de los autores y no necesariamente reflejan las de sus empleadores.&nbsp; \u00bfY si nosotros, el pueblo, decidimos todos exigir m\u00e1s? De nuestro gobierno. De nuestros funcionarios electos. De nuestros servidores sociales, que est\u00e1n destinados a protegernos. Y [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":54494,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_popups_has_disabled_popups":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3519],"tags":[],"coauthors":[18445],"class_list":["post-54492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Demandar m\u00e1s a los funcionarios electos, especialmente en tiempos de crisis - El Tecolote<\/title>\n<meta name=\"description\" content=\"Nota del Editor: Las opiniones expresadas en este comentario son responsabilidad de los autores y no necesariamente reflejan las de sus empleadores.&nbsp;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltecolote.org\/content\/es\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Demandar m\u00e1s a los funcionarios electos, especialmente en tiempos de crisis - El Tecolote\" \/>\n<meta property=\"og:description\" content=\"Nota del Editor: Las opiniones expresadas en este comentario son responsabilidad de los autores y no necesariamente reflejan las de sus empleadores.&nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltecolote.org\/content\/es\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\/\" \/>\n<meta property=\"og:site_name\" content=\"El Tecolote\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTecoloteSF\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-13T00:00:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-13T00:00:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eltecolote.org\/content\/wp-content\/uploads\/2023\/01\/Demand-more-commentary-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"El Tecolote Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:site\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Tecolote Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\\\/\"},\"author\":{\"name\":\"El Tecolote Staff\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\"},\"headline\":\"Demandar m\u00e1s a los funcionarios electos, especialmente en tiempos de crisis\",\"datePublished\":\"2023-01-13T00:00:53+00:00\",\"dateModified\":\"2023-01-13T00:00:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\\\/\"},\"wordCount\":1049,\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Demand-more-commentary-1.jpeg?fit=800%2C600&quality=89&ssl=1\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\\\/\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\\\/\",\"name\":\"Demandar m\u00e1s a los funcionarios electos, especialmente en tiempos de crisis - El Tecolote\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Demand-more-commentary-1.jpeg?fit=800%2C600&quality=89&ssl=1\",\"datePublished\":\"2023-01-13T00:00:53+00:00\",\"dateModified\":\"2023-01-13T00:00:56+00:00\",\"description\":\"Nota del Editor: Las opiniones expresadas en este comentario son responsabilidad de los autores y no necesariamente reflejan las de sus empleadores.&nbsp;\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Demand-more-commentary-1.jpeg?fit=800%2C600&quality=89&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Demand-more-commentary-1.jpeg?fit=800%2C600&quality=89&ssl=1\",\"width\":800,\"height\":600},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"name\":\"El Tecolote\",\"description\":\"San Francisco&#039;s Latinx newspaper since 1970\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\",\"name\":\"El Tecolote\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"width\":400,\"height\":400,\"caption\":\"El Tecolote\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTecoloteSF\\\/\",\"https:\\\/\\\/x.com\\\/eltecolotesf\",\"https:\\\/\\\/www.instagram.com\\\/eltecolotesf\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\",\"name\":\"El Tecolote Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"caption\":\"El Tecolote Staff\"},\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/author\\\/web-editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Demandar m\u00e1s a los funcionarios electos, especialmente en tiempos de crisis - El Tecolote","description":"Nota del Editor: Las opiniones expresadas en este comentario son responsabilidad de los autores y no necesariamente reflejan las de sus empleadores.&nbsp;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltecolote.org\/content\/es\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\/","og_locale":"en_US","og_type":"article","og_title":"Demandar m\u00e1s a los funcionarios electos, especialmente en tiempos de crisis - El Tecolote","og_description":"Nota del Editor: Las opiniones expresadas en este comentario son responsabilidad de los autores y no necesariamente reflejan las de sus empleadores.&nbsp;","og_url":"https:\/\/eltecolote.org\/content\/es\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\/","og_site_name":"El Tecolote","article_publisher":"https:\/\/www.facebook.com\/ElTecoloteSF\/","article_published_time":"2023-01-13T00:00:53+00:00","article_modified_time":"2023-01-13T00:00:56+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/eltecolote.org\/content\/wp-content\/uploads\/2023\/01\/Demand-more-commentary-1.jpeg","type":"image\/jpeg"}],"author":"El Tecolote Staff","twitter_card":"summary_large_image","twitter_creator":"@eltecolotesf","twitter_site":"@eltecolotesf","twitter_misc":{"Written by":"El Tecolote Staff","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/eltecolote.org\/content\/es\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\/#article","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/es\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\/"},"author":{"name":"El Tecolote Staff","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e"},"headline":"Demandar m\u00e1s a los funcionarios electos, especialmente en tiempos de crisis","datePublished":"2023-01-13T00:00:53+00:00","dateModified":"2023-01-13T00:00:56+00:00","mainEntityOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\/"},"wordCount":1049,"publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2023\/01\/Demand-more-commentary-1.jpeg?fit=800%2C600&quality=89&ssl=1","articleSection":["Noticias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/eltecolote.org\/content\/es\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\/","url":"https:\/\/eltecolote.org\/content\/es\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\/","name":"Demandar m\u00e1s a los funcionarios electos, especialmente en tiempos de crisis - El Tecolote","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\/#primaryimage"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2023\/01\/Demand-more-commentary-1.jpeg?fit=800%2C600&quality=89&ssl=1","datePublished":"2023-01-13T00:00:53+00:00","dateModified":"2023-01-13T00:00:56+00:00","description":"Nota del Editor: Las opiniones expresadas en este comentario son responsabilidad de los autores y no necesariamente reflejan las de sus empleadores.&nbsp;","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltecolote.org\/content\/es\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eltecolote.org\/content\/es\/demandar-mas-a-los-funcionarios-electos-especialmente-en-tiempos-de-crisis\/#primaryimage","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2023\/01\/Demand-more-commentary-1.jpeg?fit=800%2C600&quality=89&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2023\/01\/Demand-more-commentary-1.jpeg?fit=800%2C600&quality=89&ssl=1","width":800,"height":600},{"@type":"WebSite","@id":"https:\/\/eltecolote.org\/content\/#website","url":"https:\/\/eltecolote.org\/content\/","name":"El Tecolote","description":"San Francisco&#039;s Latinx newspaper since 1970","publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltecolote.org\/content\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/eltecolote.org\/content\/#organization","name":"El Tecolote","url":"https:\/\/eltecolote.org\/content\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","width":400,"height":400,"caption":"El Tecolote"},"image":{"@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTecoloteSF\/","https:\/\/x.com\/eltecolotesf","https:\/\/www.instagram.com\/eltecolotesf\/"]},{"@type":"Person","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e","name":"El Tecolote Staff","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d","url":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","caption":"El Tecolote Staff"},"url":"https:\/\/eltecolote.org\/content\/author\/web-editor\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"El Tecolote","distributor_original_site_url":"https:\/\/eltecolote.org\/content","push-errors":false,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2023\/01\/Demand-more-commentary-1.jpeg?fit=800%2C600&quality=89&ssl=1","_links":{"self":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/54492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/comments?post=54492"}],"version-history":[{"count":1,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/54492\/revisions"}],"predecessor-version":[{"id":54495,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/54492\/revisions\/54495"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media\/54494"}],"wp:attachment":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media?parent=54492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/categories?post=54492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/tags?post=54492"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/coauthors?post=54492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}