{"id":52593,"date":"2022-08-11T16:45:50","date_gmt":"2022-08-11T23:45:50","guid":{"rendered":"https:\/\/eltecolote.org\/content\/?p=52593"},"modified":"2022-08-11T16:46:04","modified_gmt":"2022-08-11T23:46:04","slug":"san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono","status":"publish","type":"post","link":"https:\/\/eltecolote.org\/content\/es\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\/","title":{"rendered":"San Francisco declarar emergencia de salud p\u00fablica local por la viruela del mono"},"content":{"rendered":"\n<p>SAN FRANCISCO DECLARAR\u00c1 EMERGENCIA DE SALUD P\u00daBLICA LOCAL POR VIRUELA DEL MONO<\/p>\n\n\n\n<p>** COMUNICADO DE PRENSA *** \u202f&nbsp;<\/p>\n\n\n\n<p>San Francisco, CA. La alcaldesa London N. Breed y el Departamento de Salud P\u00fablica de San Francisco (SFDPH, por sus siglas en ingl\u00e9s) anunciaron el 28 de junio una declaraci\u00f3n de emergencia local para fortalecer la preparaci\u00f3n y respuesta de la ciudad ante el r\u00e1pido aumento de casos de viruela del mono. Esta acci\u00f3n acelerar\u00e1 y agilizar\u00e1 la disponibilidad de recursos para responder de mejor manera a esta emergencia de salud.<\/p>\n\n\n\n<p>Dicha declaraci\u00f3n es una acci\u00f3n legal para movilizar los recursos de la Ciudad, acelerar la planificaci\u00f3n de emergencias, optimizar la dotaci\u00f3n de personal, coordinar las agencias en toda la ciudad, permitir el reembolso futuro por parte de los gobiernos estatal y federal y crear conciencia en todo San Francisco sobre c\u00f3mo detener la propagaci\u00f3n de la viruela del mono en nuestra comunidad. Entrar\u00e1 en vigor el 1 de agosto.<\/p>\n\n\n\n<p>\u201cSan Francisco demostr\u00f3 durante la COVID que la acci\u00f3n temprana es esencial para proteger la salud p\u00fablica\u201d, dijo la Alcaldesa London Breed.\u201cSabemos que este virus afecta a todos por igual, pero tambi\u00e9n sabemos que aquellos en nuestra comunidad LGBTQ+ corren un mayor riesgo en este momento. Muchas personas en nuestra comunidad LGBTQ+ est\u00e1n asustadas y frustradas. Esta emergencia local nos permitir\u00e1 continuar apoyando a los que est\u00e1n en mayor riesgo, al mismo tiempo que nos preparamos mejor para lo que est\u00e1 por venir\u201d.<\/p>\n\n\n\n<p>Actualmente, el SFDPH ha confirmado 261 casos de viruela del mono en San Francisco. Seg\u00fan se informa, hay 799 casos en California, m\u00e1s de 4,600 casos en los EEUU y m\u00e1s de 19 mil casos en todo el mundo (en 76 pa\u00edses).<\/p>\n\n\n\n<p>\u201cNecesitamos estar preparados y esta declaraci\u00f3n nos permitir\u00e1 servir mejor a la ciudad\u201d, declar\u00f3 el Director de Salud, el m\u00e9dico Grant Colfax. \u201cNuestra respuesta a la COVID-19 nos ha ense\u00f1ado que es imperativo que movilicemos los recursos de la ciudad. La declaraci\u00f3n nos ayuda a asegurar que tenemos todas las herramientas disponibles para aumentar nuestro alcance, pruebas y tratamiento, especialmente para las personas LGBTQ+ que siguen teniendo el mayor riesgo de contraer la viruela del mono\u201d.<\/p>\n\n\n\n<p>\u201cSan Francisco es un epicentro para el pa\u00eds. El treinta por ciento de todos los casos en California est\u00e1n en San Francisco\u201d, dijo la m\u00e9dico Susan Philip, Oficial de Salud P\u00fablica de San Francisco. &#8220;Siempre hemos estado a la vanguardia de la defensa y la acci\u00f3n para la salud LGBTQ+ y estoy emitiendo esta declaraci\u00f3n para reafirmar nuestro compromiso con el bienestar de estas comunidades y permitirnos avanzar m\u00e1s r\u00e1pidamente para obtener y distribuir los recursos necesarios para ayudar a esos impactado de manera desproporcionada\u201d.<\/p>\n\n\n\n<p>A medida que los casos de viruela del mono contin\u00faan aumentando en San Francisco, la demanda de vacunas sigue siendo alta y se necesita un suministro adicional para detener su propagaci\u00f3n. Esta semana, se espera que San Francisco reciba 4,220 dosis de la vacuna contra la viruela del mono. El SFDPH inicialmente solicit\u00f3 35 mil dosis para satisfacer las necesidades de los habitantes de San Francisco. Incluyendo la asignaci\u00f3n de esta semana, hasta la fecha la Ciudad solo ha recibido aproximadamente 12 mil dosis.<\/p>\n\n\n\n<p>&#8220;Estoy agradecido de que San Francisco, bajo el liderazgo de la alcaldesa Breed, entiende la profunda amenaza para la salud p\u00fablica que representa la viruela del mono\u201d, dijo el senador Scott Wiener. \u201cSan Francisco estuvo a la vanguardia de las respuestas de salud p\u00fablica al VIH y al COVID-19, y estaremos a la vanguardia en lo que respecta a la viruela del mono. No podemos ni dejaremos desprotegida a la comunidad LGTBQ+.<\/p>\n\n\n\n<p>\u201cSi bien el virus Monkeypox afecta a todas las personas, los datos muestran una propagaci\u00f3n significativa entre la comunidad LGTBQ+ de San Francisco a tasas m\u00e1s altas. Sin embargo, cualquier persona, independientemente de su orientaci\u00f3n sexual o identidad de g\u00e9nero, puede infectarse y propagarla. La declaraci\u00f3n de emergencia local tambi\u00e9n brindar\u00e1 un apoyo adecuado a la poblaci\u00f3n LGTBQ+ de San Francisco.<\/p>\n\n\n\n<p>\u201cEstoy agradecido con nuestra Oficial de Salud P\u00fablica, la m\u00e9dico Susan Philip, por declarar este estado de emergencia\u201d, dijo el supervisor Rafael Mandelman. \u201cFrente a una respuesta federal frustrantemente lenta, es a\u00fan m\u00e1s importante que podamos movilizar todos los recursos locales disponibles para llevar las vacunas a las armas de la manera m\u00e1s r\u00e1pida y equitativa posible\u201d.<\/p>\n\n\n\n<p>\u201cApoyo firmemente la decisi\u00f3n de nuestras autoridades locales de salud p\u00fablica de declarar una emergencia de salud p\u00fablica por la viruela del mono, y creo que es importante que los habitantes de San Francisco comprendan que no se trata de alarmismo sino de preparaci\u00f3n\u201d, declar\u00f3 el supervisor Matt Dorsey. \u201cEs un paso prudente, que se alinea con los movimientos recientes de la Organizaci\u00f3n Mundial de la Salud y el Departamento de Salud y Servicios Humanos de los EEUU. Creo que tambi\u00e9n refleja el &#8216;Modelo de San Francisco&#8217; de atenci\u00f3n, que tiene sus ra\u00edces en la respuesta temprana de nuestra ciudad a la crisis del SIDA hace una generaci\u00f3n, y que nos coloc\u00f3 muy por delante de la respuesta de otras ciudades al COVID-19 en 2020. Prioriza la salud y la seguridad de las poblaciones en riesgo en San Francisco, y lo apoyar\u00e9 en la Junta de Supervisores\u201d.<\/p>\n\n\n\n<p>La Ciudad ha estado trabajando diligentemente para aumentar la implementaci\u00f3n de pruebas, tratamientos y distribuci\u00f3n de vacunas en respuesta a la propagaci\u00f3n del virus de la viruela del mono. San Francisco tiene una cantidad significativa de casos y carece de suficiente suministro de vacunas para la cantidad de personas que la necesitan. El SFDPH continuar\u00e1 solicitando asignaciones adicionales de vacunas del estado y distribuir\u00e1 a cl\u00ednicas comunitarias, sistemas de salud y otros lugares donde se necesiten.<\/p>\n\n\n\n<p>Adem\u00e1s, ese departamente tambi\u00e9n se est\u00e1 acercando a las comunidades para crear conciencia y educar sobre esta viruela, la respuesta de la ciudad y garantizar que los m\u00e9dicos est\u00e9n bien informados sobre las pruebas, el control de infecciones y su manejo a medida que se desarrolla la emergencia de salud.<\/p>\n\n\n\n<p>La viruela del mono se propaga a trav\u00e9s del contacto prolongado de piel con piel, que incluye sexo, besos, respiracion cercana y por compartir ropa de cama y ropa en general.<\/p>\n\n\n\n<p>Si bien el SFDPH contin\u00faa abogando por m\u00e1s vacunas para nuestra ciudad, aqu\u00ed hay algunas medidas preventivas adicionales que puede tomar para reducir su riesgo de infecci\u00f3n:<\/p>\n\n\n\n<p>\u2022Considere limitar las situaciones que lo pongan en estrecho contacto piel con piel con otras personas.<\/p>\n\n\n\n<p>\u2022Qu\u00e9dese en casa si no se siente bien y anime a sus amistades a hacer lo mismo.<\/p>\n\n\n\n<p>\u2022 Llame a su m\u00e9dico si presenta o desarrolla sarpullido o llagas.<\/p>\n\n\n\n<p>\u2022Hable con sus parejas sexuales sobre la suya y la de ellos<\/p>\n\n\n\n<p>Si presenta s\u00edntomas:<\/p>\n\n\n\n<p>\u2022Hable con un proveedor de atenci\u00f3n m\u00e9dica lo antes posible.<\/p>\n\n\n\n<p>\u2022Evite el contacto piel con piel o el contacto cercano con otras personas.<\/p>\n\n\n\n<p>\u2022Evite compartir su cama.<\/p>\n\n\n\n<p>\u2022Haga todo lo posible para mantener una distancia razonable de los dem\u00e1s.<\/p>\n\n\n\n<p>Para encontrar orientaci\u00f3n adicional sobre la viruela del mono, incluidos las cifras de casos locales y actualizaciones sobre el suministro de vacunas, visite <a href=\"https:\/\/sf.gov\/es\/node\/sf.gov\/monkeypox\">sf.gov\/monkeypox<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAN FRANCISCO DECLARAR\u00c1 EMERGENCIA DE SALUD P\u00daBLICA LOCAL POR VIRUELA DEL MONO ** COMUNICADO DE PRENSA *** \u202f&nbsp; San Francisco, CA. La alcaldesa London N. Breed y el Departamento de Salud P\u00fablica de San Francisco (SFDPH, por sus siglas en ingl\u00e9s) anunciaron el 28 de junio una declaraci\u00f3n de emergencia local para fortalecer la preparaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":52493,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_popups_has_disabled_popups":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3519,3572],"tags":[],"coauthors":[18445],"class_list":["post-52593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-salud-noticias","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>San Francisco declarar emergencia de salud p\u00fablica local por la viruela del mono - El Tecolote<\/title>\n<meta name=\"description\" content=\"SAN FRANCISCO DECLARAR\u00c1 EMERGENCIA DE SALUD P\u00daBLICA LOCAL POR VIRUELA DEL MONO ** COMUNICADO DE PRENSA *** \u202f&nbsp; San Francisco, CA. La alcaldesa London\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltecolote.org\/content\/es\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"San Francisco declarar emergencia de salud p\u00fablica local por la viruela del mono - El Tecolote\" \/>\n<meta property=\"og:description\" content=\"SAN FRANCISCO DECLARAR\u00c1 EMERGENCIA DE SALUD P\u00daBLICA LOCAL POR VIRUELA DEL MONO ** COMUNICADO DE PRENSA *** \u202f&nbsp; San Francisco, CA. La alcaldesa London\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltecolote.org\/content\/es\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\/\" \/>\n<meta property=\"og:site_name\" content=\"El Tecolote\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTecoloteSF\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-11T23:45:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-11T23:46:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2022\/08\/monkeypox-virus-test-it-is-also-known-as-moneypox-virus-is-doublestranded-dna-zoonotic-virus-species-genus-orthopoxvirus-family-poxviridae_657921-1557_WEB.jpg?fit=2000%2C1333&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"El Tecolote Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:site\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Tecolote Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\\\/\"},\"author\":{\"name\":\"El Tecolote Staff\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\"},\"headline\":\"San Francisco declarar emergencia de salud p\u00fablica local por la viruela del mono\",\"datePublished\":\"2022-08-11T23:45:50+00:00\",\"dateModified\":\"2022-08-11T23:46:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\\\/\"},\"wordCount\":1255,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/monkeypox-virus-test-it-is-also-known-as-moneypox-virus-is-doublestranded-dna-zoonotic-virus-species-genus-orthopoxvirus-family-poxviridae_657921-1557_WEB.jpg?fit=2000%2C1333&quality=89&ssl=1\",\"articleSection\":[\"Noticias\",\"Salud\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\\\/\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\\\/\",\"name\":\"San Francisco declarar emergencia de salud p\u00fablica local por la viruela del mono - El Tecolote\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/monkeypox-virus-test-it-is-also-known-as-moneypox-virus-is-doublestranded-dna-zoonotic-virus-species-genus-orthopoxvirus-family-poxviridae_657921-1557_WEB.jpg?fit=2000%2C1333&quality=89&ssl=1\",\"datePublished\":\"2022-08-11T23:45:50+00:00\",\"dateModified\":\"2022-08-11T23:46:04+00:00\",\"description\":\"SAN FRANCISCO DECLARAR\u00c1 EMERGENCIA DE SALUD P\u00daBLICA LOCAL POR VIRUELA DEL MONO ** COMUNICADO DE PRENSA *** \u202f&nbsp; San Francisco, CA. La alcaldesa London\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/monkeypox-virus-test-it-is-also-known-as-moneypox-virus-is-doublestranded-dna-zoonotic-virus-species-genus-orthopoxvirus-family-poxviridae_657921-1557_WEB.jpg?fit=2000%2C1333&quality=89&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/monkeypox-virus-test-it-is-also-known-as-moneypox-virus-is-doublestranded-dna-zoonotic-virus-species-genus-orthopoxvirus-family-poxviridae_657921-1557_WEB.jpg?fit=2000%2C1333&quality=89&ssl=1\",\"width\":2000,\"height\":1333},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"name\":\"El Tecolote\",\"description\":\"San Francisco&#039;s Latinx newspaper since 1970\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\",\"name\":\"El Tecolote\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"width\":400,\"height\":400,\"caption\":\"El Tecolote\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTecoloteSF\\\/\",\"https:\\\/\\\/x.com\\\/eltecolotesf\",\"https:\\\/\\\/www.instagram.com\\\/eltecolotesf\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\",\"name\":\"El Tecolote Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"caption\":\"El Tecolote Staff\"},\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/author\\\/web-editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"San Francisco declarar emergencia de salud p\u00fablica local por la viruela del mono - El Tecolote","description":"SAN FRANCISCO DECLARAR\u00c1 EMERGENCIA DE SALUD P\u00daBLICA LOCAL POR VIRUELA DEL MONO ** COMUNICADO DE PRENSA *** \u202f&nbsp; San Francisco, CA. La alcaldesa London","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltecolote.org\/content\/es\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\/","og_locale":"en_US","og_type":"article","og_title":"San Francisco declarar emergencia de salud p\u00fablica local por la viruela del mono - El Tecolote","og_description":"SAN FRANCISCO DECLARAR\u00c1 EMERGENCIA DE SALUD P\u00daBLICA LOCAL POR VIRUELA DEL MONO ** COMUNICADO DE PRENSA *** \u202f&nbsp; San Francisco, CA. La alcaldesa London","og_url":"https:\/\/eltecolote.org\/content\/es\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\/","og_site_name":"El Tecolote","article_publisher":"https:\/\/www.facebook.com\/ElTecoloteSF\/","article_published_time":"2022-08-11T23:45:50+00:00","article_modified_time":"2022-08-11T23:46:04+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2022\/08\/monkeypox-virus-test-it-is-also-known-as-moneypox-virus-is-doublestranded-dna-zoonotic-virus-species-genus-orthopoxvirus-family-poxviridae_657921-1557_WEB.jpg?fit=2000%2C1333&ssl=1","type":"image\/jpeg"}],"author":"El Tecolote Staff","twitter_card":"summary_large_image","twitter_creator":"@eltecolotesf","twitter_site":"@eltecolotesf","twitter_misc":{"Written by":"El Tecolote Staff","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/eltecolote.org\/content\/es\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\/#article","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/es\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\/"},"author":{"name":"El Tecolote Staff","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e"},"headline":"San Francisco declarar emergencia de salud p\u00fablica local por la viruela del mono","datePublished":"2022-08-11T23:45:50+00:00","dateModified":"2022-08-11T23:46:04+00:00","mainEntityOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\/"},"wordCount":1255,"commentCount":0,"publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2022\/08\/monkeypox-virus-test-it-is-also-known-as-moneypox-virus-is-doublestranded-dna-zoonotic-virus-species-genus-orthopoxvirus-family-poxviridae_657921-1557_WEB.jpg?fit=2000%2C1333&quality=89&ssl=1","articleSection":["Noticias","Salud"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eltecolote.org\/content\/es\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eltecolote.org\/content\/es\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\/","url":"https:\/\/eltecolote.org\/content\/es\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\/","name":"San Francisco declarar emergencia de salud p\u00fablica local por la viruela del mono - El Tecolote","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\/#primaryimage"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2022\/08\/monkeypox-virus-test-it-is-also-known-as-moneypox-virus-is-doublestranded-dna-zoonotic-virus-species-genus-orthopoxvirus-family-poxviridae_657921-1557_WEB.jpg?fit=2000%2C1333&quality=89&ssl=1","datePublished":"2022-08-11T23:45:50+00:00","dateModified":"2022-08-11T23:46:04+00:00","description":"SAN FRANCISCO DECLARAR\u00c1 EMERGENCIA DE SALUD P\u00daBLICA LOCAL POR VIRUELA DEL MONO ** COMUNICADO DE PRENSA *** \u202f&nbsp; San Francisco, CA. La alcaldesa London","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltecolote.org\/content\/es\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eltecolote.org\/content\/es\/san-francisco-declarar-emergencia-de-salud-publica-local-por-la-viruela-del-mono\/#primaryimage","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2022\/08\/monkeypox-virus-test-it-is-also-known-as-moneypox-virus-is-doublestranded-dna-zoonotic-virus-species-genus-orthopoxvirus-family-poxviridae_657921-1557_WEB.jpg?fit=2000%2C1333&quality=89&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2022\/08\/monkeypox-virus-test-it-is-also-known-as-moneypox-virus-is-doublestranded-dna-zoonotic-virus-species-genus-orthopoxvirus-family-poxviridae_657921-1557_WEB.jpg?fit=2000%2C1333&quality=89&ssl=1","width":2000,"height":1333},{"@type":"WebSite","@id":"https:\/\/eltecolote.org\/content\/#website","url":"https:\/\/eltecolote.org\/content\/","name":"El Tecolote","description":"San Francisco&#039;s Latinx newspaper since 1970","publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltecolote.org\/content\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/eltecolote.org\/content\/#organization","name":"El Tecolote","url":"https:\/\/eltecolote.org\/content\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","width":400,"height":400,"caption":"El Tecolote"},"image":{"@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTecoloteSF\/","https:\/\/x.com\/eltecolotesf","https:\/\/www.instagram.com\/eltecolotesf\/"]},{"@type":"Person","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e","name":"El Tecolote Staff","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d","url":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","caption":"El Tecolote Staff"},"url":"https:\/\/eltecolote.org\/content\/author\/web-editor\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"El Tecolote","distributor_original_site_url":"https:\/\/eltecolote.org\/content","push-errors":false,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2022\/08\/monkeypox-virus-test-it-is-also-known-as-moneypox-virus-is-doublestranded-dna-zoonotic-virus-species-genus-orthopoxvirus-family-poxviridae_657921-1557_WEB.jpg?fit=2000%2C1333&quality=89&ssl=1","_links":{"self":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/52593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/comments?post=52593"}],"version-history":[{"count":1,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/52593\/revisions"}],"predecessor-version":[{"id":52594,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/52593\/revisions\/52594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media\/52493"}],"wp:attachment":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media?parent=52593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/categories?post=52593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/tags?post=52593"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/coauthors?post=52593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}