{"id":52586,"date":"2022-08-11T16:23:27","date_gmt":"2022-08-11T23:23:27","guid":{"rendered":"https:\/\/eltecolote.org\/content\/?p=52586"},"modified":"2022-08-11T16:23:36","modified_gmt":"2022-08-11T23:23:36","slug":"no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos","status":"publish","type":"post","link":"https:\/\/eltecolote.org\/content\/es\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\/","title":{"rendered":"No es momento de bajar la guardia ante el COVID-19, afirman expertos"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>No es el momento de bajar la guardia ante el COVID-19, afirman expertos<\/p>\n\n\n\n<p>Expertos en salud afirman que, aunque m\u00e1s personas se vacunen con refuerzos, el coronavirus ha llegado para quedarse. Y advierten que las futuras variantes probablemente mantendr\u00e1n en vilo a los m\u00e9dicos e investigadores que trabajan para mantener a raya tanto las infecciones como su gravedad.&nbsp;<\/p>\n\n\n\n<p>Su mensaje al p\u00fablico es que no hay que bajar la guardia: &#8220;El COVID va a estar con nosotros en el futuro inmediato&#8221;, dijo el m\u00e9dico William Schaffner, profesor de medicina en la Divisi\u00f3n de Enfermedades Infecciosas de la Facultad de Medicina de la Universidad de Vanderbilt. &#8220;Nos esforzamos por averiguar c\u00f3mo podemos mantener este virus a raya y minimizar sus da\u00f1os, y seguir disfrutando al mismo tiempo de una vida razonablemente normal&#8221;.<\/p>\n\n\n\n<p>Schaffner fue uno de los ponentes de una rueda de prensa organizada el 29 de julio por Ethnic Media Services sobre la \u00faltima variante del COVID-19, y las crecientes interrogantes en torno a la pandemia y la eficacia de la vacuna.&nbsp;<\/p>\n\n\n\n<p>Los casos, las muertes y las hospitalizaciones por este virus vuelven a aumentar en los EEUU. M\u00e1s de dos tercios de los estadounidenses han dado positivo en la prueba, incluido el presidente Joe Biden, por segunda vez. La variante BA5 de Omicron es ahora responsable de m\u00e1s del 78% de las infecciones en el pa\u00eds, seg\u00fan datos de los Centros para el Control y la Prevenci\u00f3n de Enfermedades (CDC).&nbsp;<\/p>\n\n\n\n<p>Pero los expertos en salud p\u00fablica afirman que las cifras podr\u00edan representar un grave subregistro, ya que muchas personas no informan sus resultados positivos de las pruebas caseras.&nbsp;<\/p>\n\n\n\n<p>Shaffner subray\u00f3 que las vacunas seguir\u00e1n siendo una parte esencial de la estrategia m\u00e1s amplia: &#8220;Necesitamos una protecci\u00f3n m\u00e1s duradera y a largo plazo contra un conjunto m\u00e1s amplio de variantes diferentes, las que conocemos y las que a\u00fan no conocemos. Queremos vacunas que prevengan la infecci\u00f3n real en la superficie de las mucosas, no s\u00f3lo vacunas que protejan contra la enfermedad grave&#8221;.<\/p>\n\n\n\n<p>Las vacunas nasales, que pueden administrarse a trav\u00e9s de un aerosol o un gotero, est\u00e1n ganando m\u00e1s atenci\u00f3n entre los investigadores cl\u00ednicos y podr\u00edan ofrecer otra v\u00eda para aumentar las tasas de vacunaci\u00f3n. La vacuna NovaVax, autorizada recientemente por la Administraci\u00f3n de Alimentos y Medicamentos (FDA, por sus siglas en ingl\u00e9s), fue autorizada para una serie inicial de dos dosis, m\u00e1s no para un refuerzo.&nbsp;<\/p>\n\n\n\n<p>Pero el m\u00e9dico Ben Neuman, profesor de biolog\u00eda y vir\u00f3logo jefe del Complejo de Investigaci\u00f3n de Salud Global de la Universidad de Texas A&amp;M, tiene sus dudas: &#8220;La vacuna NovaVax est\u00e1 bien, pero llega unos dos a\u00f1os tarde&#8221;, dijo, y a\u00f1adi\u00f3 que el medicamento no replica el virus con tanta eficacia como otras vacunas. &#8220;NovaVax tiene una prote\u00edna de espiga muy delicada que se transporta y se protege con mucho cuidado; solo un poco sobrevive para entrar en el cuerpo&#8230; Con la vacuna de ARNm, se obtienen espigas perfectas y pr\u00edstinas, exactamente de la forma en que la naturaleza las concibi\u00f3&#8221;.<\/p>\n\n\n\n<p>De acuerdo a Neuman, hasta la fecha se han producido 15 mutaciones de la variante Omicron, incluidas las subvariantes m\u00e1s recientes BA.5 y BA2.75, para las que las vacunas actuales parecen ser menos eficaces: &#8220;Seguimos vacunando contra el virus de 2019 y ya estamos a finales de 2022. Tenemos un problema&#8221;.<\/p>\n\n\n\n<p>Casi un tercio de los estadounidenses siguen sin vacunarse, mientras que la mayor\u00eda de las muertes relacionadas con este virus se est\u00e1n produciendo entre personas de 65 a\u00f1os o m\u00e1s, incluidas las que han sido vacunadas.&nbsp;<\/p>\n\n\n\n<p>Los participantes en esta rueda de prensa destacaron que el uso del cubrebocas sigue desempe\u00f1ando un papel fundamental para frenar la propagaci\u00f3n del virus, especialmente en el caso de las personas que corren un alto riesgo debido a la edad o a enfermedades subyacentes.&nbsp;<\/p>\n\n\n\n<p>En la actualidad, ning\u00fan estado impone su uso en espacios p\u00fablicos, aunque varios siguen exigiendo portarlos en entornos de alto riesgo, como hospitales y centros de atenci\u00f3n a largo plazo.&nbsp;<\/p>\n\n\n\n<p>En abril, un juez federal anul\u00f3 el requisito de uso de cubrebocas impuesto por el gobierno de Biden en el transporte p\u00fablico, las aerol\u00edneas y los centros de transporte. Se espera que el Departamento de Justicia apele la sentencia.&nbsp;<\/p>\n\n\n\n<p>Mientras tanto, un tercio de los estadounidenses ha conseguido evitar totalmente la infecci\u00f3n por el virus. Seg\u00fan el m\u00e9dico Peter Chin-Hong, director asociado de los campus regionales de la Universidad de California en San Francisco, hay cuatro factores que ayudan a explicar esta tendencia.&nbsp;<\/p>\n\n\n\n<p>Algunas personas pueden estar gen\u00e9ticamente dispuestas a tener una mayor resistencia al virus, algo que los m\u00e9dicos vieron durante los primeros a\u00f1os de la crisis del VIH\/SIDA. Estas personas podr\u00edan desempe\u00f1ar un papel en la futura investigaci\u00f3n sobre tratamientos de la COVID, se\u00f1al\u00f3 Chin-Hong. El comportamiento podr\u00eda ser otro factor, &#8220;ya que algunas personas del mismo hogar pueden tomar m\u00e1s precauciones&#8221; en cuanto a usar un cubrebocas o tener contacto estrecho con otras personas. El momento en que se administran las vacunas tambi\u00e9n influye, ya que los riesgos de infecci\u00f3n han fluctuado a lo largo de la pandemia.&nbsp;<\/p>\n\n\n\n<p>Por \u00faltimo, este m\u00e9dico explic\u00f3 que algunas personas pueden haber estado infectadas y simplemente no se han dado cuenta, ya sea porque eran asintom\u00e1ticas o porque nunca se hicieron la prueba. \u00c9l cree que las inspecciones de las aguas residuales pueden ayudar a aclarar el panorama en torno a las tasas reales de infecci\u00f3n. A diferencia de lo que ocurre con las pruebas y las declaraciones de los propios afectados, las aguas residuales pueden ayudar a los investigadores a comprender el grado de propagaci\u00f3n del virus en una comunidad.&nbsp;<\/p>\n\n\n\n<p>&#8220;Por ejemplo, en California, el nivel del virus en las aguas residuales es muy similar (a los niveles del COVID notificados) en enero, cuando m\u00e1s personas se hac\u00edan las pruebas&#8221;, explic\u00f3 Chin-Hong. Seg\u00fan estos datos, las tasas actuales de casos ser\u00edan muy superiores a las 130 mil infecciones diarias que se notifican ahora.<\/p>\n\n\n\n<p>Una oleada estival del virus respiratorio sincitial (VRS), que puede causar s\u00edntomas similares a los del COVID-19, tambi\u00e9n podr\u00eda explicar por qu\u00e9 mucha gente ha recibido resultados negativos en sus kits de pruebas caseras, dijo Shaffner: &#8220;Las pruebas r\u00e1pidas tambi\u00e9n son menos aptas para dar un resultado positivo en esta era del BA5&#8230; por eso los CDC siguen centr\u00e1ndose en las hospitalizaciones, porque nos recuerdan que existe este importante problema de salud p\u00fablica&#8221;.<\/p>\n\n\n\n<p>Terapias como PAXLOVID han demostrado su eficacia en la prevenci\u00f3n de enfermedades m\u00e1s graves, sobre todo entre los adultos mayores. Y existe un anticuerpo monoclonal que puede administrarse a algunas personas resistentes a esa terapia. Pero los expertos insisten en que las vacunas siguen siendo la herramienta m\u00e1s esencial para combatir el virus: &#8220;Ahora tenemos demasiadas muertes, como 430 al d\u00eda&#8221;, dice Chin-Hong. &#8220;Tenemos que controlar (el virus) y tenemos las herramientas para hacerlo ahora mismo&#8221;.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No es el momento de bajar la guardia ante el COVID-19, afirman expertos Expertos en salud afirman que, aunque m\u00e1s personas se vacunen con refuerzos, el coronavirus ha llegado para quedarse. Y advierten que las futuras variantes probablemente mantendr\u00e1n en vilo a los m\u00e9dicos e investigadores que trabajan para mantener a raya tanto las infecciones [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":52474,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_popups_has_disabled_popups":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3519,3572],"tags":[18556],"coauthors":[18445],"class_list":["post-52586","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-salud-noticias","tag-covid-19-en","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>No es momento de bajar la guardia ante el COVID-19, afirman expertos - El Tecolote<\/title>\n<meta name=\"description\" content=\"No es el momento de bajar la guardia ante el COVID-19, afirman expertos Expertos en salud afirman que, aunque m\u00e1s personas se vacunen con refuerzos, el\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltecolote.org\/content\/es\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"No es momento de bajar la guardia ante el COVID-19, afirman expertos - El Tecolote\" \/>\n<meta property=\"og:description\" content=\"No es el momento de bajar la guardia ante el COVID-19, afirman expertos Expertos en salud afirman que, aunque m\u00e1s personas se vacunen con refuerzos, el\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltecolote.org\/content\/es\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\/\" \/>\n<meta property=\"og:site_name\" content=\"El Tecolote\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTecoloteSF\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-11T23:23:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-11T23:23:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2022\/08\/coronavirus-Layered-mattthewafflecatPixabay-_web.jpg?fit=1085%2C485&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1085\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"El Tecolote Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:site\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Tecolote Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\\\/\"},\"author\":{\"name\":\"El Tecolote Staff\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\"},\"headline\":\"No es momento de bajar la guardia ante el COVID-19, afirman expertos\",\"datePublished\":\"2022-08-11T23:23:27+00:00\",\"dateModified\":\"2022-08-11T23:23:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\\\/\"},\"wordCount\":1238,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/coronavirus-Layered-mattthewafflecatPixabay-_web.jpg?fit=1085%2C485&quality=89&ssl=1\",\"keywords\":[\"COVID-19\"],\"articleSection\":[\"Noticias\",\"Salud\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\\\/\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\\\/\",\"name\":\"No es momento de bajar la guardia ante el COVID-19, afirman expertos - El Tecolote\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/coronavirus-Layered-mattthewafflecatPixabay-_web.jpg?fit=1085%2C485&quality=89&ssl=1\",\"datePublished\":\"2022-08-11T23:23:27+00:00\",\"dateModified\":\"2022-08-11T23:23:36+00:00\",\"description\":\"No es el momento de bajar la guardia ante el COVID-19, afirman expertos Expertos en salud afirman que, aunque m\u00e1s personas se vacunen con refuerzos, el\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/coronavirus-Layered-mattthewafflecatPixabay-_web.jpg?fit=1085%2C485&quality=89&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/coronavirus-Layered-mattthewafflecatPixabay-_web.jpg?fit=1085%2C485&quality=89&ssl=1\",\"width\":1085,\"height\":485},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"name\":\"El Tecolote\",\"description\":\"San Francisco&#039;s Latinx newspaper since 1970\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\",\"name\":\"El Tecolote\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"width\":400,\"height\":400,\"caption\":\"El Tecolote\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTecoloteSF\\\/\",\"https:\\\/\\\/x.com\\\/eltecolotesf\",\"https:\\\/\\\/www.instagram.com\\\/eltecolotesf\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\",\"name\":\"El Tecolote Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"caption\":\"El Tecolote Staff\"},\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/author\\\/web-editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"No es momento de bajar la guardia ante el COVID-19, afirman expertos - El Tecolote","description":"No es el momento de bajar la guardia ante el COVID-19, afirman expertos Expertos en salud afirman que, aunque m\u00e1s personas se vacunen con refuerzos, el","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltecolote.org\/content\/es\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\/","og_locale":"en_US","og_type":"article","og_title":"No es momento de bajar la guardia ante el COVID-19, afirman expertos - El Tecolote","og_description":"No es el momento de bajar la guardia ante el COVID-19, afirman expertos Expertos en salud afirman que, aunque m\u00e1s personas se vacunen con refuerzos, el","og_url":"https:\/\/eltecolote.org\/content\/es\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\/","og_site_name":"El Tecolote","article_publisher":"https:\/\/www.facebook.com\/ElTecoloteSF\/","article_published_time":"2022-08-11T23:23:27+00:00","article_modified_time":"2022-08-11T23:23:36+00:00","og_image":[{"width":1085,"height":485,"url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2022\/08\/coronavirus-Layered-mattthewafflecatPixabay-_web.jpg?fit=1085%2C485&ssl=1","type":"image\/jpeg"}],"author":"El Tecolote Staff","twitter_card":"summary_large_image","twitter_creator":"@eltecolotesf","twitter_site":"@eltecolotesf","twitter_misc":{"Written by":"El Tecolote Staff","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/eltecolote.org\/content\/es\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\/#article","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/es\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\/"},"author":{"name":"El Tecolote Staff","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e"},"headline":"No es momento de bajar la guardia ante el COVID-19, afirman expertos","datePublished":"2022-08-11T23:23:27+00:00","dateModified":"2022-08-11T23:23:36+00:00","mainEntityOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\/"},"wordCount":1238,"commentCount":0,"publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2022\/08\/coronavirus-Layered-mattthewafflecatPixabay-_web.jpg?fit=1085%2C485&quality=89&ssl=1","keywords":["COVID-19"],"articleSection":["Noticias","Salud"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eltecolote.org\/content\/es\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eltecolote.org\/content\/es\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\/","url":"https:\/\/eltecolote.org\/content\/es\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\/","name":"No es momento de bajar la guardia ante el COVID-19, afirman expertos - El Tecolote","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\/#primaryimage"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2022\/08\/coronavirus-Layered-mattthewafflecatPixabay-_web.jpg?fit=1085%2C485&quality=89&ssl=1","datePublished":"2022-08-11T23:23:27+00:00","dateModified":"2022-08-11T23:23:36+00:00","description":"No es el momento de bajar la guardia ante el COVID-19, afirman expertos Expertos en salud afirman que, aunque m\u00e1s personas se vacunen con refuerzos, el","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltecolote.org\/content\/es\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eltecolote.org\/content\/es\/no-es-momento-de-bajar-la-guardia-ante-el-covid-19-afirman-expertos\/#primaryimage","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2022\/08\/coronavirus-Layered-mattthewafflecatPixabay-_web.jpg?fit=1085%2C485&quality=89&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2022\/08\/coronavirus-Layered-mattthewafflecatPixabay-_web.jpg?fit=1085%2C485&quality=89&ssl=1","width":1085,"height":485},{"@type":"WebSite","@id":"https:\/\/eltecolote.org\/content\/#website","url":"https:\/\/eltecolote.org\/content\/","name":"El Tecolote","description":"San Francisco&#039;s Latinx newspaper since 1970","publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltecolote.org\/content\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/eltecolote.org\/content\/#organization","name":"El Tecolote","url":"https:\/\/eltecolote.org\/content\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","width":400,"height":400,"caption":"El Tecolote"},"image":{"@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTecoloteSF\/","https:\/\/x.com\/eltecolotesf","https:\/\/www.instagram.com\/eltecolotesf\/"]},{"@type":"Person","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e","name":"El Tecolote Staff","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d","url":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","caption":"El Tecolote Staff"},"url":"https:\/\/eltecolote.org\/content\/author\/web-editor\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"El Tecolote","distributor_original_site_url":"https:\/\/eltecolote.org\/content","push-errors":false,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2022\/08\/coronavirus-Layered-mattthewafflecatPixabay-_web.jpg?fit=1085%2C485&quality=89&ssl=1","_links":{"self":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/52586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/comments?post=52586"}],"version-history":[{"count":1,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/52586\/revisions"}],"predecessor-version":[{"id":52587,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/52586\/revisions\/52587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media\/52474"}],"wp:attachment":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media?parent=52586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/categories?post=52586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/tags?post=52586"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/coauthors?post=52586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}