{"id":50125,"date":"2021-10-21T00:44:21","date_gmt":"2021-10-21T07:44:21","guid":{"rendered":"http:\/\/eltecolote.org\/content\/?p=50125"},"modified":"2021-10-22T15:41:07","modified_gmt":"2021-10-22T22:41:07","slug":"mas-mujeres-son-blanco-de-xenofobia","status":"publish","type":"post","link":"https:\/\/eltecolote.org\/content\/es\/mas-mujeres-son-blanco-de-xenofobia\/","title":{"rendered":"M\u00e1s mujeres son blanco de xenofobia"},"content":{"rendered":"\n<p><br>Mujeres musulmanas, asi\u00e1ticas y latinas son las principales v\u00edctimas de agresiones xen\u00f3fobas en los EEUU en un contexto de aumento en los cr\u00edmenes de odio contra inmigrantes. El fen\u00f3meno, observan expertos convocados por Ethnic Media Services, obedece a que los grupos marginados terminan siendo el chivo expiatorio de todo lo que funciona mal en el pa\u00eds. Pero, \u00bfpor qu\u00e9 las mujeres?<\/p>\n\n\n\n<p>De acuerdo a la nueva encuesta \u2018Islamofobia a los ojos de los musulmanes\u2019, las mujeres (76,7%) tienen m\u00e1s probabilidades que los hombres (58,6%) de ser v\u00edctimas de la islamofobia, y el 91% de ellas respondi\u00f3 que la islamofobia afecta su bienestar emocional y mental frente a un 84% en el caso de los hombres.<\/p>\n\n\n\n<p>\u201cLas mujeres son vistas como un s\u00edmbolo de una cultura visible (al usar el hiyab), externa y opuesta\u201d, dijo Basima Sisemore, investigadora del programa de justicia global en el instituto Othering &amp; Belonging Institute de la UC Berkeley que realiz\u00f3 la encuesta. \u201cY esa cultura es el Islam y el este, y los musulmanes que supuestamente est\u00e1n en desacuerdo con los ideales occidentales y los valores democr\u00e1ticos\u201d.<\/p>\n\n\n\n<p>La encuesta es el primer estudio nacional que pregunta a los musulmanes estadounidenses (alrededor de 3.5 millones de personas) sus percepciones y experiencias en relaci\u00f3n con la islamofobia. Fue realizada en 50 estados y participaron 1,123 encuestados.<\/p>\n\n\n\n<p>El 62% de todos los encuestados dijo que ellos mismos, familiares, amigos o miembros de su comunidad, han sido afectados por pol\u00edticas federales o estatales que discriminan a los musulmanes desproporcionadamente.<\/p>\n\n\n\n<p>La islamofobia, dice Sisemore, ya exist\u00eda antes de los ataques del 11 de septiembre de 2001 y se remonta al inicio de la naci\u00f3n ya que un 20% de la poblaci\u00f3n de esclavos africanos era musulmana. Viene siendo perpetrada por actos individuales de violencia, pero tambi\u00e9n de manera institucionalizada por \u201cel racismo estructural\u201d de los EEUU con medidas como \u201cel veto de viaje para los musulmanes, los programas para contrarrestar el extremismo violento (CVE, en ingl\u00e9s) o incluso la legislaci\u00f3n contra la Sharia\u201d.<\/p>\n\n\n\n<p>\u201cEl feminismo liberal e imperialista alimenta la narrativa falsa y peligrosa de las mujeres musulmanas como oprimidas\u201d, continu\u00f3 Sisemore. \u201cEse feminismo dice que las mujeres no tienen igualdad bajo el Islam, y son vistas como que necesitan ser salvadas de violentos y opresivos hombres musulmanes, lo cual es una narrativa muy peligrosa que se desarroll\u00f3 durante las invasiones de Irak y Afganist\u00e1n como un medio para obtener apoyo p\u00fablico para la narrativa del salvador blanco\u201d.<\/p>\n\n\n\n<p>Si bien en algunos pa\u00edses isl\u00e1micos las mujeres necesitan salir acompa\u00f1adas por sus maridos o tienen severas restricciones a sus derechos, Sisemore dice que estos son \u201cejemplos extremos\u201d y que los medios podr\u00edan destacar otros aspectos de la cultura musulmana ya que \u201clas mujeres juegan un papel intr\u00ednseco en todos los sectores de la sociedad\u201d.<\/p>\n\n\n\n<p>De acuerdo a Elsadig Elsheikh, director del programa de justicia global en el instituto Othering &amp; Belonging en UC Berkeley, en algunos pa\u00edses africanos son las mujeres las que han liderado la lucha contra las dictaduras e invasiones, y que en Oriente hay casos ejemplares de liderazgo como el de Sheikh Hasina, actual primer ministra en Bangladesh, y Benazir Bhutto, primera mujer en encabezar un gobierno democr\u00e1tico en un pa\u00eds de mayor\u00eda musulmana como Pakist\u00e1n.<\/p>\n\n\n\n<p>\u201cNo estoy muy seguro de que la representaci\u00f3n de las mujeres en la mayor\u00eda de las democracias liberales de Occidente supere el 20%\u201d, dijo Elsheikh.<\/p>\n\n\n\n<p>El activista mencion\u00f3 que otro hallazgo preocupante de la encuesta es que casi un tercio o m\u00e1s de los musulmanes han escondido o intentado ocultar su identidad religiosa, \u201cporque la islamofobia ha hecho que su lugar de culto haya sido relacionado con el terrorismo y ya ni siquiera se involucran entre ellos mismos\u2026 si veo un tipo con un turbante en la cabeza, tambi\u00e9n estoy lleno de rabia contra aquellos porque vendr\u00e1n a bombardear nuestro pa\u00eds\u201d.<\/p>\n\n\n\n<p>Muchos musulmanes se autocensuran evitando hablar de sus creencias o lugar de origen y en el caso de las mujeres \u201ccasi nueve de cada 10 mujeres hacen eso en su vida diaria, tratan de evitar decir lo que piensan\u201d.<\/p>\n\n\n\n<p>Para Elsheikh los musulmanes y otros grupos marginados, \u201cparecen ser el chivo expiatorio de todo lo que est\u00e1 mal en los EEUU\u201d.<\/p>\n\n\n\n<p>Esta experiencia se repite entre las comunidades asi\u00e1tico-americanas que han sido objeto de una ola de incidentes racistas y xen\u00f3fobos relacionados con el origen del COVID-19 en Asia. De acuerdo con el centro Stop AAPI Hate, desde marzo de 2020 hasta junio de 2021 se han reportado m\u00e1s de 9 mil incidentes en contra de esta comunidad y m\u00e1s del 66% de esos ataques han sido contra mujeres asi\u00e1tico-americanas, incluidas ni\u00f1as en edad escolar.<br>\u201cCon esa idea de que los EEUU vuelva a ser blanco, los dem\u00e1s somos invasores extranjeros y grupos enteros de personas son considerados de segunda clase, menos que humanos\u201d, dijo Helen Zia, activista de la comunidad AAPI, autora y periodista.<\/p>\n\n\n\n<p>\u201cSume a eso los ataques contra las mujeres basados en el g\u00e9nero, lo que pone a las mujeres inmigrantes a afrontar m\u00faltiples peligros por ser quienes son\u201d. Zia mencion\u00f3 la masacre en Atlanta, Georgia, que acab\u00f3 con la vida de seis mujeres asi\u00e1tico-americanas que trabajaban en spas y dijo que los incidentes de odio aunque no se documentaron por g\u00e9nero, datan de 1980.<\/p>\n\n\n\n<p>\u201cLa sexualizaci\u00f3n de las mujeres asi\u00e1ticas y de las mujeres \u00e9tnicas en general, juega un papel en este tipo de incidentes\u201d dijo Zia. Lo m\u00e1s complicado es que las mujeres denuncien \u201cporque saben que en la sociedad en general est\u00e1n disminuidas, son avergonzadas y culpadas incluso pueden enfrentar un estigma dentro de su propia comunidad\u201d.<\/p>\n\n\n\n<p>Entre la comunidad latina, la explotaci\u00f3n laboral y sexual sucede en silencio por la amenaza latente de una deportaci\u00f3n. Las trabajadoras agr\u00edcolas latinas e ind\u00edgenas, en particular las inmigrantes provenientes de M\u00e9xico, Centro y Sudam\u00e9rica escapan a diversas formas de violencia en sus pa\u00edses de origen que, al buscar refugio en los EEUU, contin\u00faan siendo victimizadas.<\/p>\n\n\n\n<p>\u201cLas latinas han enfrentado mucha violencia sexual, especialmente en el campo, considerando la din\u00e1mica que existe con su estatus legal\u201d, refiri\u00f3 Irene de Barraicua, directora de operaciones de L\u00edderes Campesinas, una red de trabajadoras agr\u00edcolas que apoya a estas mujeres en su solicitud de asilo.<\/p>\n\n\n\n<p>\u201cTienen miedo a represalias y a la deportaci\u00f3n y no buscan ayuda por temor a ser consideradas una carga p\u00fablica\u201d, agreg\u00f3 Barraicua. \u201cDurante la pandemia fueron las primeras en ser despedidas cuando las empresas y los agricultores tuvieron que parar o quer\u00edan mantener a los trabajadores m\u00e1s r\u00e1pidos\u201d.<\/p>\n\n\n\n<p>La l\u00edder dice que todas estas formas de violencia s\u00f3lo tendr\u00e1n fin cuando \u201cveamos una reforma migratoria justa\u201d y para ello \u201ccontinuaremos levantando estas voces\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mujeres musulmanas, asi\u00e1ticas y latinas son las principales v\u00edctimas de agresiones xen\u00f3fobas en los EEUU en un contexto de aumento en los cr\u00edmenes de odio contra inmigrantes. El fen\u00f3meno, observan expertos convocados por Ethnic Media Services, obedece a que los grupos marginados terminan siendo el chivo expiatorio de todo lo que funciona mal en el [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":50126,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_popups_has_disabled_popups":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3519],"tags":[19001],"coauthors":[18445],"class_list":["post-50125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-xenofobia-2","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e1s mujeres son blanco de xenofobia - El Tecolote<\/title>\n<meta name=\"description\" content=\"Mujeres musulmanas, asi\u00e1ticas y latinas son las principales v\u00edctimas de agresiones xen\u00f3fobas en los EEUU en un contexto de aumento en los cr\u00edmenes de odio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltecolote.org\/content\/es\/mas-mujeres-son-blanco-de-xenofobia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s mujeres son blanco de xenofobia - El Tecolote\" \/>\n<meta property=\"og:description\" content=\"Mujeres musulmanas, asi\u00e1ticas y latinas son las principales v\u00edctimas de agresiones xen\u00f3fobas en los EEUU en un contexto de aumento en los cr\u00edmenes de odio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltecolote.org\/content\/es\/mas-mujeres-son-blanco-de-xenofobia\/\" \/>\n<meta property=\"og:site_name\" content=\"El Tecolote\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTecoloteSF\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-21T07:44:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-22T22:41:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/10\/Wavy_Ppl-09_Single-10_web.jpg?fit=1200%2C1200&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"El Tecolote Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:site\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Tecolote Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/mas-mujeres-son-blanco-de-xenofobia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/mas-mujeres-son-blanco-de-xenofobia\\\/\"},\"author\":{\"name\":\"El Tecolote Staff\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\"},\"headline\":\"M\u00e1s mujeres son blanco de xenofobia\",\"datePublished\":\"2021-10-21T07:44:21+00:00\",\"dateModified\":\"2021-10-22T22:41:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/mas-mujeres-son-blanco-de-xenofobia\\\/\"},\"wordCount\":1166,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/mas-mujeres-son-blanco-de-xenofobia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Wavy_Ppl-09_Single-10_web.jpg?fit=1200%2C1200&quality=89&ssl=1\",\"keywords\":[\"xenofobia\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/mas-mujeres-son-blanco-de-xenofobia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/mas-mujeres-son-blanco-de-xenofobia\\\/\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/mas-mujeres-son-blanco-de-xenofobia\\\/\",\"name\":\"M\u00e1s mujeres son blanco de xenofobia - El Tecolote\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/mas-mujeres-son-blanco-de-xenofobia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/mas-mujeres-son-blanco-de-xenofobia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Wavy_Ppl-09_Single-10_web.jpg?fit=1200%2C1200&quality=89&ssl=1\",\"datePublished\":\"2021-10-21T07:44:21+00:00\",\"dateModified\":\"2021-10-22T22:41:07+00:00\",\"description\":\"Mujeres musulmanas, asi\u00e1ticas y latinas son las principales v\u00edctimas de agresiones xen\u00f3fobas en los EEUU en un contexto de aumento en los cr\u00edmenes de odio\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/mas-mujeres-son-blanco-de-xenofobia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/mas-mujeres-son-blanco-de-xenofobia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Wavy_Ppl-09_Single-10_web.jpg?fit=1200%2C1200&quality=89&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Wavy_Ppl-09_Single-10_web.jpg?fit=1200%2C1200&quality=89&ssl=1\",\"width\":1200,\"height\":1200,\"caption\":\"Illustration: vectorjuice\\\/freepik.com\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"name\":\"El Tecolote\",\"description\":\"San Francisco&#039;s Latinx newspaper since 1970\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\",\"name\":\"El Tecolote\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"width\":400,\"height\":400,\"caption\":\"El Tecolote\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTecoloteSF\\\/\",\"https:\\\/\\\/x.com\\\/eltecolotesf\",\"https:\\\/\\\/www.instagram.com\\\/eltecolotesf\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\",\"name\":\"El Tecolote Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"caption\":\"El Tecolote Staff\"},\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/author\\\/web-editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s mujeres son blanco de xenofobia - El Tecolote","description":"Mujeres musulmanas, asi\u00e1ticas y latinas son las principales v\u00edctimas de agresiones xen\u00f3fobas en los EEUU en un contexto de aumento en los cr\u00edmenes de odio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltecolote.org\/content\/es\/mas-mujeres-son-blanco-de-xenofobia\/","og_locale":"en_US","og_type":"article","og_title":"M\u00e1s mujeres son blanco de xenofobia - El Tecolote","og_description":"Mujeres musulmanas, asi\u00e1ticas y latinas son las principales v\u00edctimas de agresiones xen\u00f3fobas en los EEUU en un contexto de aumento en los cr\u00edmenes de odio","og_url":"https:\/\/eltecolote.org\/content\/es\/mas-mujeres-son-blanco-de-xenofobia\/","og_site_name":"El Tecolote","article_publisher":"https:\/\/www.facebook.com\/ElTecoloteSF\/","article_published_time":"2021-10-21T07:44:21+00:00","article_modified_time":"2021-10-22T22:41:07+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/10\/Wavy_Ppl-09_Single-10_web.jpg?fit=1200%2C1200&ssl=1","type":"image\/jpeg"}],"author":"El Tecolote Staff","twitter_card":"summary_large_image","twitter_creator":"@eltecolotesf","twitter_site":"@eltecolotesf","twitter_misc":{"Written by":"El Tecolote Staff","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/eltecolote.org\/content\/es\/mas-mujeres-son-blanco-de-xenofobia\/#article","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/es\/mas-mujeres-son-blanco-de-xenofobia\/"},"author":{"name":"El Tecolote Staff","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e"},"headline":"M\u00e1s mujeres son blanco de xenofobia","datePublished":"2021-10-21T07:44:21+00:00","dateModified":"2021-10-22T22:41:07+00:00","mainEntityOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/mas-mujeres-son-blanco-de-xenofobia\/"},"wordCount":1166,"commentCount":0,"publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/mas-mujeres-son-blanco-de-xenofobia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/10\/Wavy_Ppl-09_Single-10_web.jpg?fit=1200%2C1200&quality=89&ssl=1","keywords":["xenofobia"],"articleSection":["Noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eltecolote.org\/content\/es\/mas-mujeres-son-blanco-de-xenofobia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eltecolote.org\/content\/es\/mas-mujeres-son-blanco-de-xenofobia\/","url":"https:\/\/eltecolote.org\/content\/es\/mas-mujeres-son-blanco-de-xenofobia\/","name":"M\u00e1s mujeres son blanco de xenofobia - El Tecolote","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/mas-mujeres-son-blanco-de-xenofobia\/#primaryimage"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/mas-mujeres-son-blanco-de-xenofobia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/10\/Wavy_Ppl-09_Single-10_web.jpg?fit=1200%2C1200&quality=89&ssl=1","datePublished":"2021-10-21T07:44:21+00:00","dateModified":"2021-10-22T22:41:07+00:00","description":"Mujeres musulmanas, asi\u00e1ticas y latinas son las principales v\u00edctimas de agresiones xen\u00f3fobas en los EEUU en un contexto de aumento en los cr\u00edmenes de odio","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltecolote.org\/content\/es\/mas-mujeres-son-blanco-de-xenofobia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eltecolote.org\/content\/es\/mas-mujeres-son-blanco-de-xenofobia\/#primaryimage","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/10\/Wavy_Ppl-09_Single-10_web.jpg?fit=1200%2C1200&quality=89&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/10\/Wavy_Ppl-09_Single-10_web.jpg?fit=1200%2C1200&quality=89&ssl=1","width":1200,"height":1200,"caption":"Illustration: vectorjuice\/freepik.com"},{"@type":"WebSite","@id":"https:\/\/eltecolote.org\/content\/#website","url":"https:\/\/eltecolote.org\/content\/","name":"El Tecolote","description":"San Francisco&#039;s Latinx newspaper since 1970","publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltecolote.org\/content\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/eltecolote.org\/content\/#organization","name":"El Tecolote","url":"https:\/\/eltecolote.org\/content\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","width":400,"height":400,"caption":"El Tecolote"},"image":{"@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTecoloteSF\/","https:\/\/x.com\/eltecolotesf","https:\/\/www.instagram.com\/eltecolotesf\/"]},{"@type":"Person","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e","name":"El Tecolote Staff","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d","url":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","caption":"El Tecolote Staff"},"url":"https:\/\/eltecolote.org\/content\/author\/web-editor\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"El Tecolote","distributor_original_site_url":"https:\/\/eltecolote.org\/content","push-errors":false,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/10\/Wavy_Ppl-09_Single-10_web.jpg?fit=1200%2C1200&quality=89&ssl=1","_links":{"self":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/50125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/comments?post=50125"}],"version-history":[{"count":1,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/50125\/revisions"}],"predecessor-version":[{"id":50127,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/50125\/revisions\/50127"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media\/50126"}],"wp:attachment":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media?parent=50125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/categories?post=50125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/tags?post=50125"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/coauthors?post=50125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}