{"id":47438,"date":"2021-02-26T10:54:41","date_gmt":"2021-02-26T18:54:41","guid":{"rendered":"http:\/\/eltecolote.org\/content\/?p=47438"},"modified":"2021-02-26T11:20:35","modified_gmt":"2021-02-26T19:20:35","slug":"ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa","status":"publish","type":"post","link":"https:\/\/eltecolote.org\/content\/es\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\/","title":{"rendered":"Ataques a estadounidenses de origen asi\u00e1tico: la historia completa"},"content":{"rendered":"\n<p>Es doloroso ver el video en que Vicha Ratanapakdee, de 91 a\u00f1os, es empujado al suelo y asesinado. As\u00ed como tambi\u00e9n duele ver continuamente videos similares de violencia aparentemente aleatoria, brotando en todo el pa\u00eds. Duele lo suficiente como para grabarse en la memoria, en uno de los a\u00f1os m\u00e1s devastadores y traum\u00e1ticos de la historia.<\/p>\n\n\n\n<p>Resulta particularmente doloroso mirar a trav\u00e9s del lente de un miembro de una sociedad que, literalmente, acaba de experimentar un ajuste de cuentas colosal sobre las divisiones raciales; una sociedad que no es ajena a las minor\u00edas atacadas ni a las diversas formas de violencia aleatoria y masiva. Es dif\u00edcil ver a un miembro de esa sociedad, cuyo pasado y presente est\u00e1 incrustado con el racismo y la xenofobia, revitalizarse por una administraci\u00f3n presidencial racista y durante una pandemia.<\/p>\n\n\n\n<p>Muchos noticieros r\u00e1pidamente etiquetaron esos eventos como un &#8220;aumento en los cr\u00edmenes de odio contra los estadounidenses de origen asi\u00e1tico en todo el pa\u00eds&#8221; y los empataron con rostros de color tratando de inculparlos. En febrero, por supuesto, en plena intersecci\u00f3n del Mes de la Historia Negra y el A\u00f1o Nuevo Lunar. Adem\u00e1s de atraer la atenci\u00f3n nacional y de celebridades por la irrupci\u00f3n de este odio, motiv\u00f3 el llamado a la solidaridad negra y asi\u00e1tica. Aunque en realidad existe poca evidencia que demuestre que estos ataques fueron por motivos raciales.<\/p>\n\n\n\n<p>Estos clips son instant\u00e1neas breves y horribles que parecen f\u00e1ciles de entender, pero terminan conduciendo a una historia m\u00e1s larga pero fragmentada: clips vagos y descontextualizados, invitando al espectador a completar la informaci\u00f3n faltante. Algunos vieron los videos como la historia de una poblaci\u00f3n vulnerable siendo atacada, una escalada extrema de odio hacia los estadounidenses de origen asi\u00e1tico, que durante mucho tiempo han sido vilipendiados y oprimidos. Muchos estadounidenses de origen asi\u00e1tico vieron ese video como la gota que colm\u00f3 el vaso y se sintieron inspirados para luchar contra algo que ha persistido demasiado. Mientras que otros lo vieron como una oportunidad para mostrar su anti negritud y, nuevamente, convertir en chivo expiatorio a otra comunidad minoritaria.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Los temas de raza y racismo no deben minimizarse, aunque no sean el panorama completo<\/p><\/blockquote><\/figure>\n\n\n\n<p>Es natural ver los videos y disgustarse, sentir una repulsi\u00f3n visceral por la simplemente horrenda violaci\u00f3n de la decencia humana. Creo que es noble estar enfurecido, sentir el llamado a la acci\u00f3n, anhelar cambios y exigir resultados inmediatos. Pero ante la obviedad de la raza en juego, puede ser f\u00e1cil enfocarse solo en eso, sin pensarse m\u00e1s all\u00e1, y correrse el riesgo de perder de vista la realidad profunda y amplia de la situaci\u00f3n.<\/p>\n\n\n\n<p>Los temas de raza y racismo no deben minimizarse, aunque no sean el panorama completo. \u00bfQu\u00e9 pasa si preguntamos algo m\u00e1s que solo su pa\u00eds de origen y el color de su piel en la historia? Por ejemplo, el patr\u00f3n de un aumento de robos y asaltos en los barrios chinos cada A\u00f1o Nuevo Lunar; o sobre el historial de enfermedades mentales y antecedentes penales del hombre que mat\u00f3 al Ratanapakdee, Antoine Watson; o el impacto de la extrema tensi\u00f3n financiera tras el colapso econ\u00f3mico que millones est\u00e1n sufriendo actualmente en este pa\u00eds.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"377\" height=\"480\" src=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Asian-commentary-1.jpg?resize=377%2C480&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-47376\" srcset=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Asian-commentary-1.jpg?resize=377%2C480&amp;quality=89&amp;ssl=1 377w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Asian-commentary-1.jpg?resize=197%2C250&amp;quality=89&amp;ssl=1 197w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Asian-commentary-1.jpg?resize=768%2C977&amp;quality=89&amp;ssl=1 768w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Asian-commentary-1.jpg?resize=370%2C471&amp;quality=89&amp;ssl=1 370w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Asian-commentary-1.jpg?resize=800%2C1018&amp;quality=89&amp;ssl=1 800w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Asian-commentary-1.jpg?resize=185%2C235&amp;quality=89&amp;ssl=1 185w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Asian-commentary-1.jpg?resize=740%2C941&amp;quality=89&amp;ssl=1 740w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Asian-commentary-1.jpg?resize=20%2C25&amp;quality=89&amp;ssl=1 20w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Asian-commentary-1.jpg?resize=400%2C509&amp;quality=89&amp;ssl=1 400w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Asian-commentary-1.jpg?resize=600%2C763&amp;quality=89&amp;ssl=1 600w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Asian-commentary-1.jpg?resize=38%2C48&amp;quality=89&amp;ssl=1 38w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Asian-commentary-1.jpg?w=805&amp;quality=89&amp;ssl=1 805w\" sizes=\"auto, (max-width: 377px) 100vw, 377px\" \/><figcaption>Illustration: Kristina Micotti<\/figcaption><\/figure><\/div>\n\n\n\n<p>La historia que no se cuenta aqu\u00ed es la de un pa\u00eds rico en donde abunda la pobreza, la disparidad racial, la desigualdad de clase, las comunidades de minor\u00edas interraciales, desesperadamente desatendidas, con una cultura que carece de atenci\u00f3n, recursos y protecci\u00f3n para sus miembros m\u00e1s vulnerables. Estos factores no se pueden eliminar de la historia porque forman el tejido de la sociedad que es escena y escenario a la vez. Necesitamos ver el contexto de la historia como un todo, para comprenderla realmente.<\/p>\n\n\n\n<p>Un video de un oficial arrodillado sobre el cuello de George Floyd es lo que se necesit\u00f3 para movilizar al p\u00fablico para finalmente crear un cambio y conciencia sobre el grado de racismo en nuestro pa\u00eds. Pero ese video solo rasca la superficie de una profunda historia y cultura de violencia, odio y opresi\u00f3n racial contra los afroamericanos. El efecto perjudicial de esa historia abarca y supera el alcance de la brutalidad policial justa por s\u00ed sola.<\/p>\n\n\n\n<p>Si estos terribles videos virales son lo que se necesita para finalmente traer visibilidad a la comunidad AAPI, para romper algunos mitos de las minor\u00edas modelo, entonces, por supuesto, agradezco el apoyo. Los cr\u00edmenes de odio contra la AAPI reci\u00e9n ahora est\u00e1n comenzando a enfocarse y la respuesta de apoyo y solidaridad mostrada por tantos ha sido alentadora. Esta es una gran oportunidad para sembrar sanaci\u00f3n y solidaridad entre todas las minor\u00edas y grupos raciales en este momento, pero no podemos detenernos all\u00ed.<\/p>\n\n\n\n<p>Como naci\u00f3n, estamos sufriendo mucho. Todos hemos experimentado o pasando por alg\u00fan tipo de trauma. Somos sensibles al ver a otros que son vulnerables, estamos hartos de presenciar el odio y el racismo, y tenemos hambre por denunciar esas fuerzas cuando las vemos.<\/p>\n\n\n\n<p>Pero los estadounidenses de origen asi\u00e1tico no son las \u00fanicas v\u00edctimas aqu\u00ed, todos lo somos. No solo estamos fallando en la curaci\u00f3n de las divisiones raciales, estamos fall\u00e1ndole a las comunidades de bajos ingresos, cantidades masivas de ciudadanos sin vivienda, al no brindar ayuda a la salud mental, a nuestros ancianos, vulnerables, marginados y oprimidos, y al no construir fuertes lazos en nuestras comunidades. Debemos tener en cuenta todas esas fallas y deficiencias sociales que llevan a un individuo a cometer un crimen.<\/p>\n\n\n\n<p>Puede ser peligroso y enga\u00f1oso reaccionar de forma instintiva. En cambio, al mantener una mentalidad comunitaria, podemos ampliar nuestra perspectiva para apreciar con precisi\u00f3n cu\u00e1les son los problemas, evitar errores del pasado y permitirnos responder con soluciones verdaderamente productivas que construyan una comunidad m\u00e1s segura y m\u00e1s receptiva para todos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es doloroso ver el video en que Vicha Ratanapakdee, de 91 a\u00f1os, es empujado al suelo y asesinado. As\u00ed como tambi\u00e9n duele ver continuamente videos similares de violencia aparentemente aleatoria, brotando en todo el pa\u00eds. Duele lo suficiente como para grabarse en la memoria, en uno de los a\u00f1os m\u00e1s devastadores y traum\u00e1ticos de la [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":47376,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_popups_has_disabled_popups":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[3531],"tags":[],"coauthors":[18445],"class_list":["post-47438","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voces","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ataques a estadounidenses de origen asi\u00e1tico: la historia completa - El Tecolote<\/title>\n<meta name=\"description\" content=\"Es doloroso ver el video en que Vicha Ratanapakdee, de 91 a\u00f1os, es empujado al suelo y asesinado. As\u00ed como tambi\u00e9n duele ver continuamente videos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltecolote.org\/content\/es\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ataques a estadounidenses de origen asi\u00e1tico: la historia completa - El Tecolote\" \/>\n<meta property=\"og:description\" content=\"Es doloroso ver el video en que Vicha Ratanapakdee, de 91 a\u00f1os, es empujado al suelo y asesinado. As\u00ed como tambi\u00e9n duele ver continuamente videos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltecolote.org\/content\/es\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\/\" \/>\n<meta property=\"og:site_name\" content=\"El Tecolote\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTecoloteSF\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-26T18:54:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-26T19:20:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Asian-commentary-1.jpg?fit=805%2C1024&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"805\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"El Tecolote Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:site\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Tecolote Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\\\/\"},\"author\":{\"name\":\"El Tecolote Staff\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\"},\"headline\":\"Ataques a estadounidenses de origen asi\u00e1tico: la historia completa\",\"datePublished\":\"2021-02-26T18:54:41+00:00\",\"dateModified\":\"2021-02-26T19:20:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\\\/\"},\"wordCount\":1023,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Asian-commentary-1.jpg?fit=805%2C1024&quality=89&ssl=1\",\"articleSection\":[\"Voces\"],\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\\\/\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\\\/\",\"name\":\"Ataques a estadounidenses de origen asi\u00e1tico: la historia completa - El Tecolote\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Asian-commentary-1.jpg?fit=805%2C1024&quality=89&ssl=1\",\"datePublished\":\"2021-02-26T18:54:41+00:00\",\"dateModified\":\"2021-02-26T19:20:35+00:00\",\"description\":\"Es doloroso ver el video en que Vicha Ratanapakdee, de 91 a\u00f1os, es empujado al suelo y asesinado. As\u00ed como tambi\u00e9n duele ver continuamente videos\",\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Asian-commentary-1.jpg?fit=805%2C1024&quality=89&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Asian-commentary-1.jpg?fit=805%2C1024&quality=89&ssl=1\",\"width\":805,\"height\":1024,\"caption\":\"Illustration: Kristina Micotti\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"name\":\"El Tecolote\",\"description\":\"San Francisco's Latinx newspaper since 1970\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\",\"name\":\"El Tecolote\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"width\":400,\"height\":400,\"caption\":\"El Tecolote\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTecoloteSF\\\/\",\"https:\\\/\\\/x.com\\\/eltecolotesf\",\"https:\\\/\\\/www.instagram.com\\\/eltecolotesf\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\",\"name\":\"El Tecolote Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"caption\":\"El Tecolote Staff\"},\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/author\\\/web-editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ataques a estadounidenses de origen asi\u00e1tico: la historia completa - El Tecolote","description":"Es doloroso ver el video en que Vicha Ratanapakdee, de 91 a\u00f1os, es empujado al suelo y asesinado. As\u00ed como tambi\u00e9n duele ver continuamente videos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltecolote.org\/content\/es\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\/","og_locale":"en_US","og_type":"article","og_title":"Ataques a estadounidenses de origen asi\u00e1tico: la historia completa - El Tecolote","og_description":"Es doloroso ver el video en que Vicha Ratanapakdee, de 91 a\u00f1os, es empujado al suelo y asesinado. As\u00ed como tambi\u00e9n duele ver continuamente videos","og_url":"https:\/\/eltecolote.org\/content\/es\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\/","og_site_name":"El Tecolote","article_publisher":"https:\/\/www.facebook.com\/ElTecoloteSF\/","article_published_time":"2021-02-26T18:54:41+00:00","article_modified_time":"2021-02-26T19:20:35+00:00","og_image":[{"width":805,"height":1024,"url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Asian-commentary-1.jpg?fit=805%2C1024&ssl=1","type":"image\/jpeg"}],"author":"El Tecolote Staff","twitter_card":"summary_large_image","twitter_creator":"@eltecolotesf","twitter_site":"@eltecolotesf","twitter_misc":{"Written by":"El Tecolote Staff","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/eltecolote.org\/content\/es\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\/#article","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/es\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\/"},"author":{"name":"El Tecolote Staff","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e"},"headline":"Ataques a estadounidenses de origen asi\u00e1tico: la historia completa","datePublished":"2021-02-26T18:54:41+00:00","dateModified":"2021-02-26T19:20:35+00:00","mainEntityOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\/"},"wordCount":1023,"commentCount":0,"publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Asian-commentary-1.jpg?fit=805%2C1024&quality=89&ssl=1","articleSection":["Voces"],"inLanguage":"en","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eltecolote.org\/content\/es\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eltecolote.org\/content\/es\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\/","url":"https:\/\/eltecolote.org\/content\/es\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\/","name":"Ataques a estadounidenses de origen asi\u00e1tico: la historia completa - El Tecolote","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\/#primaryimage"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Asian-commentary-1.jpg?fit=805%2C1024&quality=89&ssl=1","datePublished":"2021-02-26T18:54:41+00:00","dateModified":"2021-02-26T19:20:35+00:00","description":"Es doloroso ver el video en que Vicha Ratanapakdee, de 91 a\u00f1os, es empujado al suelo y asesinado. As\u00ed como tambi\u00e9n duele ver continuamente videos","inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltecolote.org\/content\/es\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\/"]}]},{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/eltecolote.org\/content\/es\/ataques-a-estadounidenses-de-origen-asiatico-la-historia-completa\/#primaryimage","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Asian-commentary-1.jpg?fit=805%2C1024&quality=89&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Asian-commentary-1.jpg?fit=805%2C1024&quality=89&ssl=1","width":805,"height":1024,"caption":"Illustration: Kristina Micotti"},{"@type":"WebSite","@id":"https:\/\/eltecolote.org\/content\/#website","url":"https:\/\/eltecolote.org\/content\/","name":"El Tecolote","description":"San Francisco's Latinx newspaper since 1970","publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltecolote.org\/content\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en"},{"@type":"Organization","@id":"https:\/\/eltecolote.org\/content\/#organization","name":"El Tecolote","url":"https:\/\/eltecolote.org\/content\/","logo":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","width":400,"height":400,"caption":"El Tecolote"},"image":{"@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTecoloteSF\/","https:\/\/x.com\/eltecolotesf","https:\/\/www.instagram.com\/eltecolotesf\/"]},{"@type":"Person","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e","name":"El Tecolote Staff","image":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d","url":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","caption":"El Tecolote Staff"},"url":"https:\/\/eltecolote.org\/content\/author\/web-editor\/"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"El Tecolote","distributor_original_site_url":"https:\/\/eltecolote.org\/content","push-errors":false,"_links":{"self":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/47438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/comments?post=47438"}],"version-history":[{"count":1,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/47438\/revisions"}],"predecessor-version":[{"id":47439,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/47438\/revisions\/47439"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media\/47376"}],"wp:attachment":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media?parent=47438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/categories?post=47438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/tags?post=47438"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/coauthors?post=47438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}