{"id":47422,"date":"2021-02-26T00:26:40","date_gmt":"2021-02-26T08:26:40","guid":{"rendered":"http:\/\/eltecolote.org\/content\/?p=47422"},"modified":"2021-02-26T00:26:45","modified_gmt":"2021-02-26T08:26:45","slug":"defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12","status":"publish","type":"post","link":"https:\/\/eltecolote.org\/content\/es\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\/","title":{"rendered":"Defensores exigen incluir estudios \u00e1rabes y palestinos en la curr\u00edcula del nivel K-12"},"content":{"rendered":"\n<p>Despu\u00e9s de que en las revisiones al Curr\u00edculo Modelo de Estudios \u00c9tnicos (ESMC) para los estudiantes californianos de nivel primaria y secundaria se excluyeran los estudios \u00e1rabe americanos, docentes y defensores de esos estudios est\u00e1n exigiendo la restauraci\u00f3n del curr\u00edculo a su forma original.&nbsp;&nbsp;<\/p>\n\n\n\n<p>La AB-2016 \u2014una ley que fue firmada por el entonces gobernador Jerry Brown\u2014 desarroll\u00f3 un plan de estudios modelo sobre estudios \u00e9tnicos para los distritos escolares del nivel primaria y secundaria que decidieron adoptar un plan por lecciones. Para garantizar una aut\u00e9ntica ense\u00f1anza de dichos estudios, el comit\u00e9 asesor del ESMC cre\u00f3 y desarroll\u00f3 la primera versi\u00f3n, presentada a la Comisi\u00f3n de Calidad Educativa (IQC) del Departamento de Educaci\u00f3n de California para ser revisada.&nbsp;<\/p>\n\n\n\n<p>Sin embargo, el IQC hizo varias revisiones que el comit\u00e9 asesor del ESMC consider\u00f3 no aut\u00e9nticas para el modelo de plan de estudios propuesto. En concreto, estas revisiones omitieron la inclusi\u00f3n de los estudios \u00e1rabe americanos en la asignatura de estudios asi\u00e1tico americanos, e incluyeron cambios terminol\u00f3gicos y lenguaje contradictorio, seg\u00fan Theresa Monta\u00f1o, quien form\u00f3 parte del comit\u00e9 asesor de ESMC creador del primer borrador del plan de estudios.&nbsp;<\/p>\n\n\n\n<p>&#8220;Estoy indignada de que en este proceso para desarrollar un plan de estudios que realmente fuera sobre nuestras voces en el centro, un plan de estudios que realmente fuera sobre la abolici\u00f3n completa de la supremac\u00eda blanca, un plan de estudios que fuera sobre nuestra liberaci\u00f3n, ahora se haya diluido&#8221;, dijo Allyson Tintiangco-Cubales, co presidenta de la junta consultiva del ESMC y docente desde hace mucho tiempo en la Universidad Estatal de San Francisco.&nbsp;<\/p>\n\n\n\n<p>Para resaltar los problemas de estas revisiones, el comit\u00e9 asesor lanz\u00f3 la Coalici\u00f3n para Salvar los Estudios \u00c1rabe-Americanos en protesta contra la tercera versi\u00f3n editada del ESMC, ya que no refleja con precisi\u00f3n los valores, pedagog\u00edas y principios de los estudios \u00e9tnicos, especialmente en lo que respecta a los estudios \u00e1rabe americanos.<\/p>\n\n\n\n<p>El 2 de febrero, la Coalici\u00f3n organiz\u00f3 un seminario web sobre \u2018La lucha por los estudios \u00e9tnicos en California\u2019, con la participaci\u00f3n de la oradora principal Angela Davis. Destacando la importancia de preservar una aut\u00e9ntica educaci\u00f3n de estudios \u00e9tnicos y su impacto en los negros, ind\u00edgenas y personas de color (BIPOC), el seminario web cont\u00f3 con los profesores Nadine Naber, Andrew Jolivette, Jeff Duncan-Andrade, Russell Jeung, Theresa Monta\u00f1o, Allyson Tintiangco-Cubales y Jason Ferreira.&nbsp;<\/p>\n\n\n\n<p>Todos los ponentes denunciaron la modificaci\u00f3n del plan de estudios, especialmente la exclusi\u00f3n de los estudios palestinos. Esta exclusi\u00f3n se basa en algunos comentarios p\u00fablicos realizados en contra de la ratificaci\u00f3n del plan de estudios ya mencionado, con la inclusi\u00f3n de estudios \u00e1rabe americanos y estudios palestinos.&nbsp;<\/p>\n\n\n\n<p>Los que se oponen a la inclusi\u00f3n de los estudios palestinos en el ESMC han tachado de antisemita cualquier inclusi\u00f3n de Palestina debido a las reivindicaciones conflictivas entre Israel y Palestina sobre la tierra y la naci\u00f3n. Debido a estas reivindicaciones, algunos consideran que la inclusi\u00f3n de Palestina borrar\u00eda las historias, legados y luchas jud\u00edas, reforzando el antisemitismo.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/protest_for_Palestine_004_WEB-1.jpg?resize=574%2C380&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-47377\" width=\"574\" height=\"380\" srcset=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/protest_for_Palestine_004_WEB-1.jpg?resize=600%2C397&amp;quality=89&amp;ssl=1 600w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/protest_for_Palestine_004_WEB-1.jpg?resize=360%2C238&amp;quality=89&amp;ssl=1 360w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/protest_for_Palestine_004_WEB-1.jpg?resize=768%2C508&amp;quality=89&amp;ssl=1 768w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/protest_for_Palestine_004_WEB-1.jpg?resize=370%2C245&amp;quality=89&amp;ssl=1 370w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/protest_for_Palestine_004_WEB-1.jpg?resize=800%2C530&amp;quality=89&amp;ssl=1 800w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/protest_for_Palestine_004_WEB-1.jpg?resize=20%2C13&amp;quality=89&amp;ssl=1 20w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/protest_for_Palestine_004_WEB-1.jpg?resize=185%2C122&amp;quality=89&amp;ssl=1 185w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/protest_for_Palestine_004_WEB-1.jpg?resize=740%2C490&amp;quality=89&amp;ssl=1 740w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/protest_for_Palestine_004_WEB-1.jpg?resize=400%2C265&amp;quality=89&amp;ssl=1 400w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/protest_for_Palestine_004_WEB-1.jpg?resize=73%2C48&amp;quality=89&amp;ssl=1 73w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/protest_for_Palestine_004_WEB-1.jpg?w=1000&amp;quality=89&amp;ssl=1 1000w\" sizes=\"auto, (max-width: 574px) 100vw, 574px\" \/><figcaption>Miembros de la comunidad palestina protestan afuera de la sede del Consulado Israeli en San Francisco, el 7 de julio de 2014. Foto: El Tecolote Archives\/Ramsey El-Qare<\/figcaption><\/figure><\/div>\n\n\n\n<p>Sin embargo, una declaraci\u00f3n emitida por Jud\u00edos para la Inclusi\u00f3n de los Estudios \u00c1rabe-Americanos en los Estudios \u00c9tnicos dijo &#8220;se oponen firmemente a los intentos de aquellos en la comunidad jud\u00eda, incluidos los legisladores jud\u00edos, de acusar falsamente de antisemitismo y sesgo anti-jud\u00edo con el fin de bloquear la inclusi\u00f3n de los estudios \u00e1rabe-americanos incluyendo informaci\u00f3n sobre Palestina. Nuestra comprensi\u00f3n de la importancia de incluir los estudios \u00e1rabe-americanos se ve reforzada por nuestras propias experiencias con el antisemitismo&#8230;.&#8221;&nbsp;<\/p>\n\n\n\n<p>Otras organizaciones jud\u00edas, como la Voz Jud\u00eda por la Paz, tambi\u00e9n han expresado su solidaridad con los educadores de estudios \u00e9tnicos.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Al proporcionar una educaci\u00f3n culturalmente relevante que conecta con las experiencias de los estudiantes, los estudios \u00e9tnicos ponen de relieve las historias de los BIPOC y los logros, las historias y las luchas de la comunidad. Y los defensores dicen que los recortes realizados en la \u00faltima versi\u00f3n de ese plan de estudios, espec\u00edficamente en los estudios \u00e1rabes, amenazan la base misma de los estudios \u00e9tnicos, omitiendo las historias, la di\u00e1spora y las realidades actuales de los pueblos \u00e1rabes.<\/p>\n\n\n\n<p>&#8220;La lucha de hoy para mantener la integridad del Plan de Estudios Modelo de Estudios \u00c9tnicos de California es la siguiente fase de la lucha para defender los estudios \u00e9tnicos, en particular contra las objeciones a la inclusi\u00f3n de contenidos sobre los palestino americanos en la parte de estudios \u00e1rabe americanos del plan de estudios&#8221;, dijo la aclamada acad\u00e9mica y educadora Angela Davis. &#8220;El campo de los estudios \u00e9tnicos no est\u00e1 completo sin la inclusi\u00f3n de contenidos relacionados con Palestina, los palestinos y los palestino americanos&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>&#8220;Estoy indignada de que en este proceso para desarrollar un plan de estudios que realmente fuera sobre nuestras voces en el centro, un plan de estudios que realmente fuera sobre la abolici\u00f3n completa de la supremac\u00eda blanca, un plan de estudios que fuera sobre nuestra liberaci\u00f3n, ahora se haya diluido&#8221;<\/p><cite>Allyson Tintiangco-Cubales<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Todos los oradores se\u00f1alaron la importancia de la educaci\u00f3n culturalmente relevante e inclusiva, ya que es fundamental para los estudios \u00e9tnicos, para ense\u00f1ar a los estudiantes con identidades marginadas que las historias transnacionales de sus comunidades son hermosas, resistentes y parte importante de su vida cotidiana.<\/p>\n\n\n\n<p>&#8220;No hay nada en el trabajo de los estudios \u00e9tnicos que tenga que ver con la exclusi\u00f3n de otros&#8221;, dijo Duncan-Andrade durante el seminario web. &#8220;Es una elecci\u00f3n para dar prioridad a los que no la han tenido, porque si no lo haces, no lo har\u00e1s&#8230; Si no decimos intencionadamente que vamos a priorizar a los que hemos empujado a los m\u00e1rgenes desde el mismo inicio de este estado-naci\u00f3n, entonces no lo haremos&#8230; Los Estudios \u00c9tnicos lo convierten en una prioridad, porque cuando los m\u00e1s vulnerables est\u00e1n bien, todos podemos estar bien&#8221;.<\/p>\n\n\n\n<p>A trav\u00e9s de la educaci\u00f3n sobre diferentes movimientos sociales y luchas por la liberaci\u00f3n a lo largo del tiempo, los estudiantes aprenden de las historias radicales y poderosas de los BIPOC fomentando un plan de estudios que sirve a todos los alumnos por igual. Los estudios \u00e9tnicos y su legado transformador deben ser representados aut\u00e9nticamente en lugar de ser cambiados en contra del asesoramiento de los educadores.&nbsp;<\/p>\n\n\n\n<p>El cuarto borrador del ESMC por parte del Departamento de Educaci\u00f3n de California se presentar\u00e1 en marzo, y la Coalici\u00f3n para Salvar los Estudios \u00c1rabe-Americanos, en colaboraci\u00f3n con los consejos consultivos originales del ESMC, ha enviado una carta rechazando este cambio de plan de estudios, exigiendo una aut\u00e9ntica educaci\u00f3n en esta materia.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de que en las revisiones al Curr\u00edculo Modelo de Estudios \u00c9tnicos (ESMC) para los estudiantes californianos de nivel primaria y secundaria se excluyeran los estudios \u00e1rabe americanos, docentes y defensores de esos estudios est\u00e1n exigiendo la restauraci\u00f3n del curr\u00edculo a su forma original.&nbsp;&nbsp; La AB-2016 \u2014una ley que fue firmada por el entonces gobernador [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":47377,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_popups_has_disabled_popups":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[3519],"tags":[],"coauthors":[18445],"class_list":["post-47422","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Defensores exigen incluir estudios \u00e1rabes y palestinos en la curr\u00edcula del nivel K-12 - El Tecolote<\/title>\n<meta name=\"description\" content=\"Despu\u00e9s de que en las revisiones al Curr\u00edculo Modelo de Estudios \u00c9tnicos (ESMC) para los estudiantes californianos de nivel primaria y secundaria se\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltecolote.org\/content\/es\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Defensores exigen incluir estudios \u00e1rabes y palestinos en la curr\u00edcula del nivel K-12 - El Tecolote\" \/>\n<meta property=\"og:description\" content=\"Despu\u00e9s de que en las revisiones al Curr\u00edculo Modelo de Estudios \u00c9tnicos (ESMC) para los estudiantes californianos de nivel primaria y secundaria se\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltecolote.org\/content\/es\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\/\" \/>\n<meta property=\"og:site_name\" content=\"El Tecolote\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTecoloteSF\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-26T08:26:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-26T08:26:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/protest_for_Palestine_004_WEB-1.jpg?fit=1000%2C662&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"662\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"El Tecolote Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:site\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Tecolote Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\\\/\"},\"author\":{\"name\":\"El Tecolote Staff\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\"},\"headline\":\"Defensores exigen incluir estudios \u00e1rabes y palestinos en la curr\u00edcula del nivel K-12\",\"datePublished\":\"2021-02-26T08:26:40+00:00\",\"dateModified\":\"2021-02-26T08:26:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\\\/\"},\"wordCount\":1197,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/protest_for_Palestine_004_WEB-1.jpg?fit=1000%2C662&quality=89&ssl=1\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\\\/\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\\\/\",\"name\":\"Defensores exigen incluir estudios \u00e1rabes y palestinos en la curr\u00edcula del nivel K-12 - El Tecolote\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/protest_for_Palestine_004_WEB-1.jpg?fit=1000%2C662&quality=89&ssl=1\",\"datePublished\":\"2021-02-26T08:26:40+00:00\",\"dateModified\":\"2021-02-26T08:26:45+00:00\",\"description\":\"Despu\u00e9s de que en las revisiones al Curr\u00edculo Modelo de Estudios \u00c9tnicos (ESMC) para los estudiantes californianos de nivel primaria y secundaria se\",\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/protest_for_Palestine_004_WEB-1.jpg?fit=1000%2C662&quality=89&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/protest_for_Palestine_004_WEB-1.jpg?fit=1000%2C662&quality=89&ssl=1\",\"width\":1000,\"height\":662,\"caption\":\"Miembros de la comunidad palestina protestan afuera de la sede del Consulado Israeli en San Francisco, el 7 de julio de 2014. Foto: El Tecolote Archives\\\/Ramsey El-Qare\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"name\":\"El Tecolote\",\"description\":\"San Francisco's Latinx newspaper since 1970\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\",\"name\":\"El Tecolote\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"width\":400,\"height\":400,\"caption\":\"El Tecolote\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTecoloteSF\\\/\",\"https:\\\/\\\/x.com\\\/eltecolotesf\",\"https:\\\/\\\/www.instagram.com\\\/eltecolotesf\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\",\"name\":\"El Tecolote Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"caption\":\"El Tecolote Staff\"},\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/author\\\/web-editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Defensores exigen incluir estudios \u00e1rabes y palestinos en la curr\u00edcula del nivel K-12 - El Tecolote","description":"Despu\u00e9s de que en las revisiones al Curr\u00edculo Modelo de Estudios \u00c9tnicos (ESMC) para los estudiantes californianos de nivel primaria y secundaria se","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltecolote.org\/content\/es\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\/","og_locale":"en_US","og_type":"article","og_title":"Defensores exigen incluir estudios \u00e1rabes y palestinos en la curr\u00edcula del nivel K-12 - El Tecolote","og_description":"Despu\u00e9s de que en las revisiones al Curr\u00edculo Modelo de Estudios \u00c9tnicos (ESMC) para los estudiantes californianos de nivel primaria y secundaria se","og_url":"https:\/\/eltecolote.org\/content\/es\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\/","og_site_name":"El Tecolote","article_publisher":"https:\/\/www.facebook.com\/ElTecoloteSF\/","article_published_time":"2021-02-26T08:26:40+00:00","article_modified_time":"2021-02-26T08:26:45+00:00","og_image":[{"width":1000,"height":662,"url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/protest_for_Palestine_004_WEB-1.jpg?fit=1000%2C662&ssl=1","type":"image\/jpeg"}],"author":"El Tecolote Staff","twitter_card":"summary_large_image","twitter_creator":"@eltecolotesf","twitter_site":"@eltecolotesf","twitter_misc":{"Written by":"El Tecolote Staff","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/eltecolote.org\/content\/es\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\/#article","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/es\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\/"},"author":{"name":"El Tecolote Staff","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e"},"headline":"Defensores exigen incluir estudios \u00e1rabes y palestinos en la curr\u00edcula del nivel K-12","datePublished":"2021-02-26T08:26:40+00:00","dateModified":"2021-02-26T08:26:45+00:00","mainEntityOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\/"},"wordCount":1197,"commentCount":0,"publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/protest_for_Palestine_004_WEB-1.jpg?fit=1000%2C662&quality=89&ssl=1","articleSection":["Noticias"],"inLanguage":"en","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eltecolote.org\/content\/es\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eltecolote.org\/content\/es\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\/","url":"https:\/\/eltecolote.org\/content\/es\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\/","name":"Defensores exigen incluir estudios \u00e1rabes y palestinos en la curr\u00edcula del nivel K-12 - El Tecolote","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\/#primaryimage"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/protest_for_Palestine_004_WEB-1.jpg?fit=1000%2C662&quality=89&ssl=1","datePublished":"2021-02-26T08:26:40+00:00","dateModified":"2021-02-26T08:26:45+00:00","description":"Despu\u00e9s de que en las revisiones al Curr\u00edculo Modelo de Estudios \u00c9tnicos (ESMC) para los estudiantes californianos de nivel primaria y secundaria se","inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltecolote.org\/content\/es\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\/"]}]},{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/eltecolote.org\/content\/es\/defensores-exigen-incluir-estudios-arabes-y-palestinos-en-la-curricula-del-nivel-k-12\/#primaryimage","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/protest_for_Palestine_004_WEB-1.jpg?fit=1000%2C662&quality=89&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/protest_for_Palestine_004_WEB-1.jpg?fit=1000%2C662&quality=89&ssl=1","width":1000,"height":662,"caption":"Miembros de la comunidad palestina protestan afuera de la sede del Consulado Israeli en San Francisco, el 7 de julio de 2014. Foto: El Tecolote Archives\/Ramsey El-Qare"},{"@type":"WebSite","@id":"https:\/\/eltecolote.org\/content\/#website","url":"https:\/\/eltecolote.org\/content\/","name":"El Tecolote","description":"San Francisco's Latinx newspaper since 1970","publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltecolote.org\/content\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en"},{"@type":"Organization","@id":"https:\/\/eltecolote.org\/content\/#organization","name":"El Tecolote","url":"https:\/\/eltecolote.org\/content\/","logo":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","width":400,"height":400,"caption":"El Tecolote"},"image":{"@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTecoloteSF\/","https:\/\/x.com\/eltecolotesf","https:\/\/www.instagram.com\/eltecolotesf\/"]},{"@type":"Person","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e","name":"El Tecolote Staff","image":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d","url":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","caption":"El Tecolote Staff"},"url":"https:\/\/eltecolote.org\/content\/author\/web-editor\/"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"El Tecolote","distributor_original_site_url":"https:\/\/eltecolote.org\/content","push-errors":false,"_links":{"self":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/47422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/comments?post=47422"}],"version-history":[{"count":2,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/47422\/revisions"}],"predecessor-version":[{"id":47424,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/47422\/revisions\/47424"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media\/47377"}],"wp:attachment":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media?parent=47422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/categories?post=47422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/tags?post=47422"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/coauthors?post=47422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}