{"id":47418,"date":"2021-02-26T00:01:51","date_gmt":"2021-02-26T08:01:51","guid":{"rendered":"http:\/\/eltecolote.org\/content\/?p=47418"},"modified":"2021-02-26T00:01:56","modified_gmt":"2021-02-26T08:01:56","slug":"garantizar-a-todos-el-acceso-a-recursos","status":"publish","type":"post","link":"https:\/\/eltecolote.org\/content\/es\/garantizar-a-todos-el-acceso-a-recursos\/","title":{"rendered":"Garantizar a todos el acceso a recursos"},"content":{"rendered":"\n<p>La COVID ha afectado nuestra econom\u00eda de manera incalculable y el impacto de esta crisis la seguiremos padeciendo en los pr\u00f3ximos a\u00f1os. Si bien millones de californianos han sufrido por el desempleo durante casi un a\u00f1o, las comunidades de color y las comunidades de inmigrantes son las que han soportado la carga m\u00e1s pesada.<\/p>\n\n\n\n<p>La persistente crisis econ\u00f3mica ha sido particularmente aguda para los trabajadores de las industrias de la hospitalidad, el turismo y los servicios. Y los trabajadores inmigrantes y de color a menudo constituyen la gran mayor\u00eda de esa fuerza laboral.<\/p>\n\n\n\n<p>Normalmente, el seguro de desempleo proporciona una red de seguridad crucial para ayudar a los trabajadores a capear la tormenta, pero los actuales desaf\u00edos en la agencia de desempleo de California han dificultado mucho la obtenci\u00f3n de beneficios. Hemos visto un fraude desenfrenado y a millones de californianos luchando por obtener los beneficios que les corresponden. El Departamento de Desarrollo del Empleo (EDD, por sus siglas en ingl\u00e9s), la agencia responsable de distribuir el seguro de desempleo, no ha logrado satisfacer las necesidades de millones de californianos durante esta crisis econ\u00f3mica. Si bien los problemas en ese departamento han existido durante d\u00e9cadas, han sido especialmente obvios y dolorosos durante este tiempo.<\/p>\n\n\n\n<p>Obtener acceso a esos beneficios puede ser un proceso dif\u00edcil y frustrante para cualquiera, pero estos problemas se agravan para los californianos monoling\u00fces cuya lengua materna no es el ingl\u00e9s. De hecho, los desaf\u00edos son tan importantes que el informe de un equipo asignado por el gobernador concluy\u00f3 que los solicitantes del EDD que no hablan ingl\u00e9s enfrentan \u201cbarreras insuperables\u201d para recibir beneficios. Si bien esa agencia ofrece algunos formularios y servicios en espa\u00f1ol, no son lo suficientemente completos para ser efectivos.<\/p>\n\n\n\n<p>El a\u00f1o pasado, mi oficina ayud\u00f3 a cientos de electores a navegar el proceso del seguro de desempleo, obtener actualizaciones cr\u00edticas y garantizar que las personas obtengan los recursos necesarios para sobrevivir en este momento excepcionalmente dif\u00edcil. Mi personal biling\u00fce ha ayudado a muchos electores cuyo primer idioma no es el ingl\u00e9s y que enfrentan desaf\u00edos extraordinarios al intentar acceder a los beneficios de desempleo que les corresponden legalmente. Muchos han intentado llamar a la l\u00ednea telef\u00f3nica en espa\u00f1ol, pero el EDD rara vez responde. Hemos visto a electores de habla hispana a los que no se les ha pagado en meses, que est\u00e1n al borde de perder su vivienda y que no pueden llevar comida a la mesa.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Normalmente, el seguro de desempleo proporciona una red de seguridad crucial para ayudar a los trabajadores a capear la tormenta, pero los actuales desaf\u00edos en la agencia de desempleo de California han dificultado mucho la obtenci\u00f3n de beneficios.<\/p><\/blockquote><\/figure>\n\n\n\n<p>Como hijo de inmigrantes y ex abogado de derechos civiles, me desconcierta ver c\u00f3mo los servicios gubernamentales cr\u00edticos no son accesibles para todos. Hay siete millones de californianos con dominio limitado del ingl\u00e9s que llaman hogar a California. En San Francisco, uno de cada diez hogares habla espa\u00f1ol y, de ellos, un tercio tiene un dominio limitado del ingl\u00e9s. En California y San Francisco, la necesidad de un acceso ling\u00fc\u00edstico culturalmente competente en los servicios p\u00fablicos ha sido enorme, especialmente durante esta \u00e9poca de crisis. La falta de acceso al idioma en las agencias de servicio p\u00fablico ha exacerbado a\u00fan m\u00e1s las disparidades existentes que hemos visto a lo largo de la pandemia.<\/p>\n\n\n\n<p>Por todas estas razones, mis colegas y yo presentamos recientemente un paquete de proyectos de ley para reformar el EDD. Para asegurar que todos los californianos tengan acceso a beneficios p\u00fablicos cruciales. Estoy redactando el Proyecto de Ley de la Asamblea 401 para abordar el acceso al idioma en esa instancia, la cual le requerir\u00eda identificar de manera proactiva las necesidades ling\u00fc\u00edsticas del solicitante; proporcionar traducci\u00f3n ampliada de solicitudes, documentos vitales y avisos de esa agencia; comunicarse con los reclamantes en su idioma preferido de manera oportuna; aumentar el servicio de atenci\u00f3n telef\u00f3nica multiling\u00fce; y establecer un proceso de revisi\u00f3n comunitaria de los esfuerzos de traducci\u00f3n del EDD para garantizar la accesibilidad. Estamos trabajando con una amplia coalici\u00f3n de defensores en este esfuerzo, incluidos Legal Aid at Work, Center for Workers Rights, Asian Americans Advancing Justice-California y Mixteco Ind\u00edgena Community Organizing Project.<\/p>\n\n\n\n<p>Los problemas en el EDD son vastos y requerir\u00e1n una amplia revisi\u00f3n y aportes legislativos. Sin embargo, si la AB 401 se convierte en ley, funcionar\u00eda para llenar una brecha significativa en los servicios para los residentes de San Francisco y California con dominio limitado del ingl\u00e9s.<\/p>\n\n\n\n<p>A menudo se dice que la medida de la grandeza de una sociedad depende de c\u00f3mo se trata a los que menos tienen en nuestras comunidades. Tenemos la esperanza de que al aprobar la AB 401, nuestro estado avance para que todas las personas, independientemente de su cultura, herencia o capacidad ling\u00fc\u00edstica, puedan confiar en que su gobierno ayudar\u00e1 en tiempos dif\u00edciles.<\/p>\n\n\n\n<p>Mientras tanto, si necesita ayuda con el EDD, no dude en comunicarse a mi oficina de lunes a viernes de 9:00 a.m. a 5:00 p.m. al 415-557-3013.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La COVID ha afectado nuestra econom\u00eda de manera incalculable y el impacto de esta crisis la seguiremos padeciendo en los pr\u00f3ximos a\u00f1os. Si bien millones de californianos han sufrido por el desempleo durante casi un a\u00f1o, las comunidades de color y las comunidades de inmigrantes son las que han soportado la carga m\u00e1s pesada. La [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":47419,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_popups_has_disabled_popups":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[3531],"tags":[],"coauthors":[18445],"class_list":["post-47418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voces","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Garantizar a todos el acceso a recursos - El Tecolote<\/title>\n<meta name=\"description\" content=\"La COVID ha afectado nuestra econom\u00eda de manera incalculable y el impacto de esta crisis la seguiremos padeciendo en los pr\u00f3ximos a\u00f1os. Si bien millones\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltecolote.org\/content\/es\/garantizar-a-todos-el-acceso-a-recursos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Garantizar a todos el acceso a recursos - El Tecolote\" \/>\n<meta property=\"og:description\" content=\"La COVID ha afectado nuestra econom\u00eda de manera incalculable y el impacto de esta crisis la seguiremos padeciendo en los pr\u00f3ximos a\u00f1os. Si bien millones\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltecolote.org\/content\/es\/garantizar-a-todos-el-acceso-a-recursos\/\" \/>\n<meta property=\"og:site_name\" content=\"El Tecolote\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTecoloteSF\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-26T08:01:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-26T08:01:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Untitled-design-9-1.png?fit=1080%2C1080&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"El Tecolote Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:site\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Tecolote Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/garantizar-a-todos-el-acceso-a-recursos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/garantizar-a-todos-el-acceso-a-recursos\\\/\"},\"author\":{\"name\":\"El Tecolote Staff\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\"},\"headline\":\"Garantizar a todos el acceso a recursos\",\"datePublished\":\"2021-02-26T08:01:51+00:00\",\"dateModified\":\"2021-02-26T08:01:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/garantizar-a-todos-el-acceso-a-recursos\\\/\"},\"wordCount\":897,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/garantizar-a-todos-el-acceso-a-recursos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Untitled-design-9-1.png?fit=1080%2C1080&quality=80&ssl=1\",\"articleSection\":[\"Voces\"],\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/garantizar-a-todos-el-acceso-a-recursos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/garantizar-a-todos-el-acceso-a-recursos\\\/\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/garantizar-a-todos-el-acceso-a-recursos\\\/\",\"name\":\"Garantizar a todos el acceso a recursos - El Tecolote\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/garantizar-a-todos-el-acceso-a-recursos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/garantizar-a-todos-el-acceso-a-recursos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Untitled-design-9-1.png?fit=1080%2C1080&quality=80&ssl=1\",\"datePublished\":\"2021-02-26T08:01:51+00:00\",\"dateModified\":\"2021-02-26T08:01:56+00:00\",\"description\":\"La COVID ha afectado nuestra econom\u00eda de manera incalculable y el impacto de esta crisis la seguiremos padeciendo en los pr\u00f3ximos a\u00f1os. Si bien millones\",\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/garantizar-a-todos-el-acceso-a-recursos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/garantizar-a-todos-el-acceso-a-recursos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Untitled-design-9-1.png?fit=1080%2C1080&quality=80&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Untitled-design-9-1.png?fit=1080%2C1080&quality=80&ssl=1\",\"width\":1080,\"height\":1080},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"name\":\"El Tecolote\",\"description\":\"San Francisco's Latinx newspaper since 1970\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\",\"name\":\"El Tecolote\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"width\":400,\"height\":400,\"caption\":\"El Tecolote\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTecoloteSF\\\/\",\"https:\\\/\\\/x.com\\\/eltecolotesf\",\"https:\\\/\\\/www.instagram.com\\\/eltecolotesf\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\",\"name\":\"El Tecolote Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"caption\":\"El Tecolote Staff\"},\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/author\\\/web-editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Garantizar a todos el acceso a recursos - El Tecolote","description":"La COVID ha afectado nuestra econom\u00eda de manera incalculable y el impacto de esta crisis la seguiremos padeciendo en los pr\u00f3ximos a\u00f1os. Si bien millones","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltecolote.org\/content\/es\/garantizar-a-todos-el-acceso-a-recursos\/","og_locale":"en_US","og_type":"article","og_title":"Garantizar a todos el acceso a recursos - El Tecolote","og_description":"La COVID ha afectado nuestra econom\u00eda de manera incalculable y el impacto de esta crisis la seguiremos padeciendo en los pr\u00f3ximos a\u00f1os. Si bien millones","og_url":"https:\/\/eltecolote.org\/content\/es\/garantizar-a-todos-el-acceso-a-recursos\/","og_site_name":"El Tecolote","article_publisher":"https:\/\/www.facebook.com\/ElTecoloteSF\/","article_published_time":"2021-02-26T08:01:51+00:00","article_modified_time":"2021-02-26T08:01:56+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Untitled-design-9-1.png?fit=1080%2C1080&ssl=1","type":"image\/png"}],"author":"El Tecolote Staff","twitter_card":"summary_large_image","twitter_creator":"@eltecolotesf","twitter_site":"@eltecolotesf","twitter_misc":{"Written by":"El Tecolote Staff","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/eltecolote.org\/content\/es\/garantizar-a-todos-el-acceso-a-recursos\/#article","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/es\/garantizar-a-todos-el-acceso-a-recursos\/"},"author":{"name":"El Tecolote Staff","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e"},"headline":"Garantizar a todos el acceso a recursos","datePublished":"2021-02-26T08:01:51+00:00","dateModified":"2021-02-26T08:01:56+00:00","mainEntityOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/garantizar-a-todos-el-acceso-a-recursos\/"},"wordCount":897,"commentCount":0,"publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/garantizar-a-todos-el-acceso-a-recursos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Untitled-design-9-1.png?fit=1080%2C1080&quality=80&ssl=1","articleSection":["Voces"],"inLanguage":"en","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eltecolote.org\/content\/es\/garantizar-a-todos-el-acceso-a-recursos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eltecolote.org\/content\/es\/garantizar-a-todos-el-acceso-a-recursos\/","url":"https:\/\/eltecolote.org\/content\/es\/garantizar-a-todos-el-acceso-a-recursos\/","name":"Garantizar a todos el acceso a recursos - El Tecolote","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/garantizar-a-todos-el-acceso-a-recursos\/#primaryimage"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/garantizar-a-todos-el-acceso-a-recursos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Untitled-design-9-1.png?fit=1080%2C1080&quality=80&ssl=1","datePublished":"2021-02-26T08:01:51+00:00","dateModified":"2021-02-26T08:01:56+00:00","description":"La COVID ha afectado nuestra econom\u00eda de manera incalculable y el impacto de esta crisis la seguiremos padeciendo en los pr\u00f3ximos a\u00f1os. Si bien millones","inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltecolote.org\/content\/es\/garantizar-a-todos-el-acceso-a-recursos\/"]}]},{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/eltecolote.org\/content\/es\/garantizar-a-todos-el-acceso-a-recursos\/#primaryimage","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Untitled-design-9-1.png?fit=1080%2C1080&quality=80&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/02\/Untitled-design-9-1.png?fit=1080%2C1080&quality=80&ssl=1","width":1080,"height":1080},{"@type":"WebSite","@id":"https:\/\/eltecolote.org\/content\/#website","url":"https:\/\/eltecolote.org\/content\/","name":"El Tecolote","description":"San Francisco's Latinx newspaper since 1970","publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltecolote.org\/content\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en"},{"@type":"Organization","@id":"https:\/\/eltecolote.org\/content\/#organization","name":"El Tecolote","url":"https:\/\/eltecolote.org\/content\/","logo":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","width":400,"height":400,"caption":"El Tecolote"},"image":{"@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTecoloteSF\/","https:\/\/x.com\/eltecolotesf","https:\/\/www.instagram.com\/eltecolotesf\/"]},{"@type":"Person","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e","name":"El Tecolote Staff","image":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d","url":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","caption":"El Tecolote Staff"},"url":"https:\/\/eltecolote.org\/content\/author\/web-editor\/"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"El Tecolote","distributor_original_site_url":"https:\/\/eltecolote.org\/content","push-errors":false,"_links":{"self":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/47418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/comments?post=47418"}],"version-history":[{"count":1,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/47418\/revisions"}],"predecessor-version":[{"id":47420,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/47418\/revisions\/47420"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media\/47419"}],"wp:attachment":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media?parent=47418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/categories?post=47418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/tags?post=47418"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/coauthors?post=47418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}