{"id":44955,"date":"2020-08-13T12:07:14","date_gmt":"2020-08-13T19:07:14","guid":{"rendered":"http:\/\/eltecolote.org\/content\/?p=44955"},"modified":"2020-08-13T12:07:18","modified_gmt":"2020-08-13T19:07:18","slug":"sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo","status":"publish","type":"post","link":"https:\/\/eltecolote.org\/content\/es\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\/","title":{"rendered":"Sin tregua el ataque de Trump a  Inmigrantes, al DACA y al Censo"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Durante una videoconferencia llevada a cabo el 7 de agosto, presentada por Ethnic Media Services, expertos en inmigraci\u00f3n citaron m\u00e1s de cuatrocientos cambios en la pol\u00edtica de inmigraci\u00f3n por parte de la actual administraci\u00f3n desde que esta comenz\u00f3 en enero de 2017.<\/p>\n\n\n\n<p>Aunque una parte significativa de los trabajadores esenciales del pa\u00eds son inmigrantes, ellos contin\u00faan siendo el blanco de Trump durante la pandemia. En los \u00faltimos meses se ha realizado una cantidad asombrosa de cambios en la pol\u00edtica de inmigraci\u00f3n a la Acci\u00f3n Diferida para los Llegados en la Infancia (DACA, por sus siglas en ingl\u00e9s), el Estatus de Protecci\u00f3n Temporal (TPS, tambi\u00e9n en ingl\u00e9s) y las visas de inmigraci\u00f3n. Estos cambios se han realizado en gran parte mediante proclamas presidenciales y \u00f3rdenes ejecutivas sin el aval del Congreso.<\/p>\n\n\n\n<p>El 28 de julio, el Departamento de Seguridad Nacional orden\u00f3 a los Servicios de Ciudadan\u00eda e Inmigraci\u00f3n de los (USCIS) rechazar cualquier solicitud nueva de DACA y exigir a los beneficiarios actuales renovar anualmente en lugar de cada dos a\u00f1os. USCIS tambi\u00e9n est\u00e1 rechazando todas las solicitudes de libertad condicional anticipada, que permite a los receptores DACA salir y volver a ingresar al pa\u00eds legalmente, excepto cuando existan \u2018circunstancias excepcionales\u2019. Estos cambios est\u00e1n vigentes mientras el DHS considere mantener, rescindir o modificar la normativa.<\/p>\n\n\n\n<p>\u201cHay un impulso para que el Congreso incluya la extensi\u00f3n autom\u00e1tica de DACA, del TPS, las autorizaciones de trabajo en los pr\u00f3ximos proyectos de ley de alivio a la COVID-19\u201d, dijo Ignacia Rodr\u00edguez Kmec del Centro Nacional de Leyes de Inmigraci\u00f3n (NILC). NILC recomienda que las personas que est\u00e9n considerando renovar su DACA consulten a un abogado o representante acreditado que pueda identificar cualquier se\u00f1al de alerta que pueda poner al solicitante en riesgo de rechazo a su tr\u00e1mite, incluyendo el riesgo a la deportaci\u00f3n y para saber si se es elegible a otra forma m\u00e1s permanente de alivio migratorio. Es especialmente importante consultar con un abogado cuando se tiene orden de deportaci\u00f3n previa, contacto anterior con la polic\u00eda, casos pendientes en la corte de inmigraci\u00f3n o planes de viajar con libertad condicional anticipada.<\/p>\n\n\n\n<p>\u201cLa pandemia s\u00f3lo ha acelerado los cambios que ha realizado esta administraci\u00f3n\u201d, dijo Sarah Pierce, analista de pol\u00edticas del Migration Policy Institute (MPI). En un informe de este instituto publicado el mes pasado, Pierce y Jessica Bolter describieron los tres cambios principales: el primero que tuvo lugar el 20 de marzo de 2020, cuando los Centros para el Control y la Prevenci\u00f3n de Enfermedades (CDC) ordenaron a todos los ciudadanos extranjeros sin autorizaci\u00f3n para ingresar a los EEUU ser devueltos a M\u00e9xico (o Canad\u00e1) o a sus pa\u00edses de origen. Seg\u00fan la orden, las detenciones mensuales se redujeron a la mitad entre marzo y abril, y las solicitudes de asilo se desplomaron, ya que los pocos que llegaron fueron expulsados sin la oportunidad de buscar refugio. El segundo fue cuando el presidente restringi\u00f3 la inmigraci\u00f3n permanente el 22 de abril de 2020 y, un mes despu\u00e9s, la restricci\u00f3n para los trabajadores temporales.<\/p>\n\n\n\n<p>\u201cAunque estas acciones, en gran parte administrativas, podr\u00edan, en teor\u00eda, ser deshechas por una administraci\u00f3n futura, este enfoque en capas, junto con el cambiante ritmo, hace probable que la presidencia de Trump cause efectos duraderos en el sistema de inmigraci\u00f3n de los EEUU\u201d,\u00a0 se lee en el informe.<\/p>\n\n\n\n<p><strong>Trump, antagonista del censo<\/strong><\/p>\n\n\n\n<p>Si bien la administraci\u00f3n Trump ha tenido como blanco de ataque a los inmigrantes a trav\u00e9s de pol\u00edticas particulares, tambi\u00e9n lo ha hecho mediante el levantamiento del Censo 2020.<\/p>\n\n\n\n<p>\u00c9ste, que anteriormente estaba programado para realizarse hasta el 31 de octubre de 2020, ahora se ha anticipado su t\u00e9rmino para el 30 de septiembre, lo que pone a las comunidades de color, incluidas las comunidades de inmigrantes, en riesgo de un conteo corto.<\/p>\n\n\n\n<p>A principios de 2018, la administraci\u00f3n Trump propuso agregar una pregunta sobre ciudadan\u00eda, que luego fuera rechazada por la Corte Suprema pero que fue claramente una t\u00e1ctica disuasiva a los inmigrantes de participar en el conteo. El siguiente paso del presidente fue la emisi\u00f3n de una orden ejecutiva en julio de 2019 prohibiendo a los inmigrantes indocumentados ser incluidos en el censo. Recientemente, emiti\u00f3 un memorando ejecutivo el 21 de julio de 2020, prohibiendo a los inmigrantes indocumentados participar en \u00e9l.<\/p>\n\n\n\n<p>\u201cEste memo ni siquiera vale el papel en el que est\u00e1 escrito\u201d, dijo el asamble\u00edsta Marc Berman (D-Menlo Park), presidente del Comit\u00e9 Selecto de la Asamblea sobre el Censo. \u201cTrump lo sabe, ni siquiera se atrevi\u00f3 a convertirlo en una Orden Ejecutiva. Es descaradamente inconstitucional. Ni siquiera es pr\u00e1ctico. La Corte Suprema descart\u00f3 la pregunta de ciudadan\u00eda de Trump fuera del censo, por lo que no hay forma de saber el estatus de las personas que responden. Si no es legal y no es pr\u00e1ctico, entonces obviamente es simplemente una propaganda para tratar de suprimir la participaci\u00f3n en el censo, que ha sido el objetivo de Trump todo el tiempo. Es realmente triste\u201d.<\/p>\n\n\n\n<p>El censo puede ser completado en l\u00ednea en el sitio web <a href=\"http:\/\/2020census.gov\">2020census.gov<\/a>, o v\u00eda telef\u00f3nica (en ingl\u00e9s) 844-330-2020 y (en espa\u00f1ol) 844-468-2020.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante una videoconferencia llevada a cabo el 7 de agosto, presentada por Ethnic Media Services, expertos en inmigraci\u00f3n citaron m\u00e1s de cuatrocientos cambios en la pol\u00edtica de inmigraci\u00f3n por parte de la actual administraci\u00f3n desde que esta comenz\u00f3 en enero de 2017. Aunque una parte significativa de los trabajadores esenciales del pa\u00eds son inmigrantes, ellos [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":41131,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_popups_has_disabled_popups":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3578,3519],"tags":[],"coauthors":[18445],"class_list":["post-44955","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inmigracion-noticias","category-noticias","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sin tregua el ataque de Trump a Inmigrantes, al DACA y al Censo - El Tecolote<\/title>\n<meta name=\"description\" content=\"Durante una videoconferencia llevada a cabo el 7 de agosto, presentada por Ethnic Media Services, expertos en inmigraci\u00f3n citaron m\u00e1s de cuatrocientos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltecolote.org\/content\/es\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sin tregua el ataque de Trump a Inmigrantes, al DACA y al Censo - El Tecolote\" \/>\n<meta property=\"og:description\" content=\"Durante una videoconferencia llevada a cabo el 7 de agosto, presentada por Ethnic Media Services, expertos en inmigraci\u00f3n citaron m\u00e1s de cuatrocientos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltecolote.org\/content\/es\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\/\" \/>\n<meta property=\"og:site_name\" content=\"El Tecolote\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTecoloteSF\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-13T19:07:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-13T19:07:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/07\/Trump-Census-Banerjee-WEB-1.jpg?fit=1721%2C1188&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1721\" \/>\n\t<meta property=\"og:image:height\" content=\"1188\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"El Tecolote Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:site\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Tecolote Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\\\/\"},\"author\":{\"name\":\"El Tecolote Staff\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\"},\"headline\":\"Sin tregua el ataque de Trump a Inmigrantes, al DACA y al Censo\",\"datePublished\":\"2020-08-13T19:07:14+00:00\",\"dateModified\":\"2020-08-13T19:07:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\\\/\"},\"wordCount\":910,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Trump-Census-Banerjee-WEB-1.jpg?fit=1721%2C1188&quality=89&ssl=1\",\"articleSection\":[\"Inmigraci\u00f3n\",\"Noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\\\/\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\\\/\",\"name\":\"Sin tregua el ataque de Trump a Inmigrantes, al DACA y al Censo - El Tecolote\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Trump-Census-Banerjee-WEB-1.jpg?fit=1721%2C1188&quality=89&ssl=1\",\"datePublished\":\"2020-08-13T19:07:14+00:00\",\"dateModified\":\"2020-08-13T19:07:18+00:00\",\"description\":\"Durante una videoconferencia llevada a cabo el 7 de agosto, presentada por Ethnic Media Services, expertos en inmigraci\u00f3n citaron m\u00e1s de cuatrocientos\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Trump-Census-Banerjee-WEB-1.jpg?fit=1721%2C1188&quality=89&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Trump-Census-Banerjee-WEB-1.jpg?fit=1721%2C1188&quality=89&ssl=1\",\"width\":1721,\"height\":1188,\"caption\":\"Ilustraci\u00f3n: Bhabna Banerjee\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"name\":\"El Tecolote\",\"description\":\"San Francisco&#039;s Latinx newspaper since 1970\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\",\"name\":\"El Tecolote\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"width\":400,\"height\":400,\"caption\":\"El Tecolote\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTecoloteSF\\\/\",\"https:\\\/\\\/x.com\\\/eltecolotesf\",\"https:\\\/\\\/www.instagram.com\\\/eltecolotesf\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\",\"name\":\"El Tecolote Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"caption\":\"El Tecolote Staff\"},\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/author\\\/web-editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sin tregua el ataque de Trump a Inmigrantes, al DACA y al Censo - El Tecolote","description":"Durante una videoconferencia llevada a cabo el 7 de agosto, presentada por Ethnic Media Services, expertos en inmigraci\u00f3n citaron m\u00e1s de cuatrocientos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltecolote.org\/content\/es\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\/","og_locale":"en_US","og_type":"article","og_title":"Sin tregua el ataque de Trump a Inmigrantes, al DACA y al Censo - El Tecolote","og_description":"Durante una videoconferencia llevada a cabo el 7 de agosto, presentada por Ethnic Media Services, expertos en inmigraci\u00f3n citaron m\u00e1s de cuatrocientos","og_url":"https:\/\/eltecolote.org\/content\/es\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\/","og_site_name":"El Tecolote","article_publisher":"https:\/\/www.facebook.com\/ElTecoloteSF\/","article_published_time":"2020-08-13T19:07:14+00:00","article_modified_time":"2020-08-13T19:07:18+00:00","og_image":[{"width":1721,"height":1188,"url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/07\/Trump-Census-Banerjee-WEB-1.jpg?fit=1721%2C1188&ssl=1","type":"image\/jpeg"}],"author":"El Tecolote Staff","twitter_card":"summary_large_image","twitter_creator":"@eltecolotesf","twitter_site":"@eltecolotesf","twitter_misc":{"Written by":"El Tecolote Staff","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/eltecolote.org\/content\/es\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\/#article","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/es\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\/"},"author":{"name":"El Tecolote Staff","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e"},"headline":"Sin tregua el ataque de Trump a Inmigrantes, al DACA y al Censo","datePublished":"2020-08-13T19:07:14+00:00","dateModified":"2020-08-13T19:07:18+00:00","mainEntityOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\/"},"wordCount":910,"commentCount":0,"publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/07\/Trump-Census-Banerjee-WEB-1.jpg?fit=1721%2C1188&quality=89&ssl=1","articleSection":["Inmigraci\u00f3n","Noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eltecolote.org\/content\/es\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eltecolote.org\/content\/es\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\/","url":"https:\/\/eltecolote.org\/content\/es\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\/","name":"Sin tregua el ataque de Trump a Inmigrantes, al DACA y al Censo - El Tecolote","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\/#primaryimage"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/07\/Trump-Census-Banerjee-WEB-1.jpg?fit=1721%2C1188&quality=89&ssl=1","datePublished":"2020-08-13T19:07:14+00:00","dateModified":"2020-08-13T19:07:18+00:00","description":"Durante una videoconferencia llevada a cabo el 7 de agosto, presentada por Ethnic Media Services, expertos en inmigraci\u00f3n citaron m\u00e1s de cuatrocientos","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltecolote.org\/content\/es\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eltecolote.org\/content\/es\/sin-tregua-el-ataque-de-trump-a-inmigrantes-al-daca-y-al-censo\/#primaryimage","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/07\/Trump-Census-Banerjee-WEB-1.jpg?fit=1721%2C1188&quality=89&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/07\/Trump-Census-Banerjee-WEB-1.jpg?fit=1721%2C1188&quality=89&ssl=1","width":1721,"height":1188,"caption":"Ilustraci\u00f3n: Bhabna Banerjee"},{"@type":"WebSite","@id":"https:\/\/eltecolote.org\/content\/#website","url":"https:\/\/eltecolote.org\/content\/","name":"El Tecolote","description":"San Francisco&#039;s Latinx newspaper since 1970","publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltecolote.org\/content\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/eltecolote.org\/content\/#organization","name":"El Tecolote","url":"https:\/\/eltecolote.org\/content\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","width":400,"height":400,"caption":"El Tecolote"},"image":{"@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTecoloteSF\/","https:\/\/x.com\/eltecolotesf","https:\/\/www.instagram.com\/eltecolotesf\/"]},{"@type":"Person","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e","name":"El Tecolote Staff","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d","url":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","caption":"El Tecolote Staff"},"url":"https:\/\/eltecolote.org\/content\/author\/web-editor\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"El Tecolote","distributor_original_site_url":"https:\/\/eltecolote.org\/content","push-errors":false,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/07\/Trump-Census-Banerjee-WEB-1.jpg?fit=1721%2C1188&quality=89&ssl=1","_links":{"self":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/44955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/comments?post=44955"}],"version-history":[{"count":2,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/44955\/revisions"}],"predecessor-version":[{"id":44959,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/44955\/revisions\/44959"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media\/41131"}],"wp:attachment":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media?parent=44955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/categories?post=44955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/tags?post=44955"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/coauthors?post=44955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}