{"id":44669,"date":"2020-07-16T13:23:21","date_gmt":"2020-07-16T20:23:21","guid":{"rendered":"http:\/\/eltecolote.org\/content\/?p=44669"},"modified":"2020-07-16T13:23:25","modified_gmt":"2020-07-16T20:23:25","slug":"la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia","status":"publish","type":"post","link":"https:\/\/eltecolote.org\/content\/es\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\/","title":{"rendered":"La Suprema Corte salva a DACA, sin embargo, los trabajadores esenciales contin\u00faan batallando durante la pandemia"},"content":{"rendered":"\n<p><em>Nota: Ante la preocupaci\u00f3n por la seguridad de la comunidad de indocumentados, los apellidos ser\u00e1n omitidos en esta historia para proteger el anonimato de nuestras fuentes.<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>En medio de una pandemia, la Corte Suprema de los EEUU dictamin\u00f3 el 18 de junio bloquear el intento de eliminaci\u00f3n de la Acci\u00f3n Diferida para la Llegada de Ni\u00f1os (DACA) por parte de la administraci\u00f3n de Trump.<br><\/p>\n\n\n\n<p>DACA es una pol\u00edtica emitida por el Departamento de Seguridad Nacional de los EEUU en 2012 que permite a ciertos indocumentados venidos a este pa\u00eds cuando ni\u00f1os, obtener una autorizaci\u00f3n de trabajo mientras que solicitan la consideraci\u00f3n de una acci\u00f3n diferida por un per\u00edodo de dos a\u00f1os. La acci\u00f3n diferida no proporciona un estatus legal y requiere su renovaci\u00f3n cada dos a\u00f1os.<br><\/p>\n\n\n\n<p>Este importante triunfo permite a los nuevos solicitantes candidatos, aprovechar la oportunidad y solicitar los beneficios que ofrece dicha pol\u00edtica.<br><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"864\" height=\"576\" src=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2017\/09\/DACA-Rally-SF_Drago-Renteria_10web-1.jpg?resize=864%2C576&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-35463\" srcset=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2017\/09\/DACA-Rally-SF_Drago-Renteria_10web-1.jpg?w=864&amp;quality=89&amp;ssl=1 864w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2017\/09\/DACA-Rally-SF_Drago-Renteria_10web-1.jpg?resize=600%2C400&amp;quality=89&amp;ssl=1 600w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2017\/09\/DACA-Rally-SF_Drago-Renteria_10web-1.jpg?resize=360%2C240&amp;quality=89&amp;ssl=1 360w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2017\/09\/DACA-Rally-SF_Drago-Renteria_10web-1.jpg?resize=768%2C512&amp;quality=89&amp;ssl=1 768w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2017\/09\/DACA-Rally-SF_Drago-Renteria_10web-1.jpg?w=370&amp;quality=89&amp;ssl=1 370w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2017\/09\/DACA-Rally-SF_Drago-Renteria_10web-1.jpg?w=400&amp;quality=89&amp;ssl=1 400w\" sizes=\"auto, (max-width: 864px) 100vw, 864px\" \/><figcaption>Miles se manifestaron en San Francisco el 5 de septiembre de 2017, horas despu\u00e9s de que el Fiscal General, Jeff Sessions, anunciara la terminaci\u00f3n de DACA. Al igual que otros programas destinados a apoyar a los inmigrantes, DACA ha estado bajo amenaza constante por la administraci\u00f3n Trump. Pero el 18 de junio de 2020, la Corte Suprema dictamin\u00f3 bloquear el intento de eliminarlo. Foto: Drago Renter\u00eda<\/figcaption><\/figure>\n\n\n\n<p>Recientemente, el Dreamer Fund \u2014un colectivo de San Francisco que recauda fondos y aboga por los estudiantes indocumentados\u2014 celebr\u00f3 una sesi\u00f3n virtual de preguntas y respuestas con el profesor de la Universidad de San Francisco, Bill Ong Hing. En ella, el acad\u00e9mico explic\u00f3 c\u00f3mo la decisi\u00f3n de la Corte Suprema permite al receptor de DACA un punto de apoyo temporal mientras que en alg\u00fan momento, tal vez en un futuro pr\u00f3ximo, el sistema aborde una reforma migratoria muy necesaria.<br><\/p>\n\n\n\n<p>\u201cNo hay una pol\u00edtica de privacidad\u201d, dijo Hing al tratar los posibles resultados si el programa fuera rescindido. Lo que significa que cada receptor de DACA estar\u00eda a merced de ICE y en riesgo de ser deportado. Para algunos, aun cuando tuvieran que enfrentar la deportaci\u00f3n en el futuro si DACA fuera revocada, los beneficios de trabajar ahora son m\u00e1s importantes y vale la pena el riesgo. Especialmente durante una pandemia toda vez que, por su estatus, los beneficiarios de DACA no califican para el desempleo ni para la asistencia del gobierno federal.<br><\/p>\n\n\n\n<p>Mientras que el gobierno federal neg\u00f3 la asistencia a los 649,070 beneficiarios que se calcula pagan impuestos, envi\u00f3 por error cheques de est\u00edmulo a casi 1.1 millones de personas muertas, un total de casi $1,400 millones de d\u00f3lares, dinero que te\u00f3ricamente podr\u00eda ser utilizado para ayudar a la comunidad de indocumentados.<br><\/p>\n\n\n\n<p>California dio un paso al frente y el 15 de abril anunci\u00f3 un fondo de ayuda para desastres de $125 millones de d\u00f3lares para beneficiar a la comunidad de indocumentados que perdieron sus trabajos. En San Francisco, la organizaci\u00f3n Young Workers United fund\u00f3 el UndocuFund, que proporciona asistencia financiera a la comunidad local de indocumentados.<br><\/p>\n\n\n\n<p>Maribel, de 30 a\u00f1os, una receptora de DACA, que trabaja para una organizaci\u00f3n de derechos de los inmigrantes al sur de California no se consideraba una trabajadora esencial. Entonces se dio cuenta de que estaba trabajando en esta pandemia para ayudar a la comunidad y que necesitaba ayuda para pagar sus necesidades y recibos.<br><\/p>\n\n\n\n<p>\u201cInicialmente [pens\u00e9] en los trabajadores que tenian trato directo con la gente, como los del sector salud, los trabajadores de tienda de comestibles, gente como mis padres que ten\u00edan que ir a las f\u00e1bricas o a limpiar. A ellos los consideraba trabajadores esenciales\u201d, dijo Maribel.<br><\/p>\n\n\n\n<p>Como las organizaciones ayudan a las familias indocumentadas, los requisitos suelen ser bastante dif\u00edciles de cumplir a veces. Pocos pueden calificar s\u00f3lo por unos $300 a $500 d\u00f3lares. Esta cantidad m\u00ednima ayuda a algunos, pero no lo suficiente para cubrir las crecientes facturas.<br><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-full is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/DACA_Estrada_3225_web-1.jpg?resize=347%2C520&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-44672\" width=\"347\" height=\"520\" srcset=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/DACA_Estrada_3225_web-1.jpg?w=1050&amp;quality=89&amp;ssl=1 1050w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/DACA_Estrada_3225_web-1.jpg?resize=167%2C250&amp;quality=89&amp;ssl=1 167w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/DACA_Estrada_3225_web-1.jpg?resize=320%2C480&amp;quality=89&amp;ssl=1 320w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/DACA_Estrada_3225_web-1.jpg?resize=768%2C1152&amp;quality=89&amp;ssl=1 768w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/DACA_Estrada_3225_web-1.jpg?resize=1024%2C1536&amp;quality=89&amp;ssl=1 1024w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/DACA_Estrada_3225_web-1.jpg?resize=370%2C555&amp;quality=89&amp;ssl=1 370w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/DACA_Estrada_3225_web-1.jpg?resize=800%2C1200&amp;quality=89&amp;ssl=1 800w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/DACA_Estrada_3225_web-1.jpg?resize=185%2C278&amp;quality=89&amp;ssl=1 185w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/DACA_Estrada_3225_web-1.jpg?resize=740%2C1110&amp;quality=89&amp;ssl=1 740w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/DACA_Estrada_3225_web-1.jpg?resize=20%2C30&amp;quality=89&amp;ssl=1 20w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/DACA_Estrada_3225_web-1.jpg?resize=400%2C600&amp;quality=89&amp;ssl=1 400w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/DACA_Estrada_3225_web-1.jpg?resize=600%2C900&amp;quality=89&amp;ssl=1 600w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/DACA_Estrada_3225_web-1.jpg?resize=32%2C48&amp;quality=89&amp;ssl=1 32w\" sizes=\"auto, (max-width: 347px) 100vw, 347px\" \/><figcaption>Noem\u00ed, de 32 a\u00f1os, del sur de California y receptora de DACA, en su casa. Fue despedida de su trabajo como asistente personal en marzo y ahora trabaja como gerente en un restaurante. Foto: Pamela Estrada<\/figcaption><\/figure><\/div>\n\n\n\n<p>Encontrar trabajos esenciales ahora es tan dif\u00edcil como encontrarlo antes de la COVID-19. La seguridad en el lugar de trabajo es importante y puede significar dejar un trabajo por otro. Noemi, de 32 a\u00f1os , otra receptora de DACA al sur de California fue despedida de su trabajo como asistente personal en marzo. La familia a la que estaba ayudando ahora estar\u00eda atada a su casa debido a la orden de confinamiento y que, por ende, no requer\u00eda de su ayuda. Noemi entonces tom\u00f3 un trabajo en una lavander\u00eda pero cuando su seguridad se vio comprometida por clientes que se negaban a usar cubrebocas, se encontr\u00f3 buscando un trabajo diferente, y encontr\u00f3 uno como gerente en un restaurante. Se da cuenta de que pagar el alquiler es crucial, ya que su compa\u00f1era de piso puede tener problemas para pagarlo.<br><\/p>\n\n\n\n<p>\u201cEl dinero es tan escaso que si no pueden pagar su parte [de la renta] ahora tenemos que pagarla y es como, \u00bfc\u00f3mo lo hacemos?\u201d, dijo. Tomar la decisi\u00f3n de trabajar para llegar a fin de mes no es nuevo para Noemi. Cuando estaba a punto de graduarse de la escuela secundaria tom\u00f3 la decisi\u00f3n de saltarse la preparatoria para asegurarse de que pod\u00eda ayudar en casa. \u201cSab\u00eda que mi familia no ten\u00eda dinero para pagarme la escuela\u201d. <\/p>\n\n\n\n<p>Noemi puede no tener un t\u00edtulo universitario pero eso no la ha alejado de otros sue\u00f1os. Es una t\u00e9cnica de belleza certificada que ofrece su tiempo a los asistentes al baile de graduaci\u00f3n que no tienen recursos para pagar por arreglarse. Comparte su pasado para demostrar que, como la \u00faltima vez, se esforzar\u00e1.<br><\/p>\n\n\n\n<p>Las luchas de los receptores de DACA y de los indocumentados var\u00edan. Ser indocumentado, ser un receptor de DACA es una experiencia tan diversa como los m\u00e1s de cien pa\u00edses de los que proceden todos y cada uno de ellos.<br><\/p>\n\n\n\n<p>El receptor de DACA Set Hern\u00e1ndez Rongkilyo, de 28 a\u00f1os, dice que trabajar en esta pandemia no es el mayor desastre de su vida: \u201cSiento que ser indocumentado es como vivir en una pandemia todo el tiempo. No puedes salir del pa\u00eds, no puedes volar, tienes que hacer todo virtualmente para ver a tu familia en el extranjero\u201d. La inspiraci\u00f3n llena su voz a trav\u00e9s de su historia y de c\u00f3mo lidiar con ser un receptor de DACA y con esta pandemia. Cuando se refieren a aquellos que les importan, se nota un cambio en su voz. Para Set, el miedo llega cuando tienen que pensar en la falta de cuidados de salud de su madre y hermanos menores mientras trabajan en esta pandemia. Se aseguran de que su padre en Filipinas reciba la ayuda financiera que le est\u00e1n mandan y que ellos est\u00e9n bien.<br><\/p>\n\n\n\n<p>Extra\u00f1amente durante la pandemia, una de sus mayores preocupaciones se produjo en medio de los levantamientos de Black Lives Matter tras la muerte de George Floyd. La preocupaci\u00f3n era sobre c\u00f3mo conducirse, c\u00f3mo ser solidario y c\u00f3mo educarse: \u201cS\u00f3lo pienso en toda la gente negra de mi vida que me ha apoyado de esa manera\u201d.<br><\/p>\n\n\n\n<p>Si bien el reciente fallo del Tribunal Supremo puede ser una peque\u00f1a victoria, estar fuera de las sombras s\u00f3lo significa tener que enfrentarse a otras cuestiones que deben abordarse. Mantener DACA en su lugar va m\u00e1s all\u00e1 de un permiso de trabajo: \u201cLos indocumentados no estamos indefensos. Nuestras experiencias son puestas a trav\u00e9s de ciertos lentes. Quiero que la gente sepa que somos s\u00f3lo personas\u201d, dijo Rongkilyo. \u201cSi DACA surgi\u00f3 fue gracias a estrategias tomadas por los indocumentados\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nota: Ante la preocupaci\u00f3n por la seguridad de la comunidad de indocumentados, los apellidos ser\u00e1n omitidos en esta historia para proteger el anonimato de nuestras fuentes. En medio de una pandemia, la Corte Suprema de los EEUU dictamin\u00f3 el 18 de junio bloquear el intento de eliminaci\u00f3n de la Acci\u00f3n Diferida para la Llegada de [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":44672,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_popups_has_disabled_popups":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3578,3519],"tags":[],"coauthors":[18445],"class_list":["post-44669","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inmigracion-noticias","category-noticias","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Suprema Corte salva a DACA, sin embargo, los trabajadores esenciales contin\u00faan batallando durante la pandemia - El Tecolote<\/title>\n<meta name=\"description\" content=\"Nota: Ante la preocupaci\u00f3n por la seguridad de la comunidad de indocumentados, los apellidos ser\u00e1n omitidos en esta historia para proteger el anonimato de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltecolote.org\/content\/es\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Suprema Corte salva a DACA, sin embargo, los trabajadores esenciales contin\u00faan batallando durante la pandemia - El Tecolote\" \/>\n<meta property=\"og:description\" content=\"Nota: Ante la preocupaci\u00f3n por la seguridad de la comunidad de indocumentados, los apellidos ser\u00e1n omitidos en esta historia para proteger el anonimato de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltecolote.org\/content\/es\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\/\" \/>\n<meta property=\"og:site_name\" content=\"El Tecolote\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTecoloteSF\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-16T20:23:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-16T20:23:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/DACA_Estrada_3225_web-1.jpg?fit=1050%2C1575&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1050\" \/>\n\t<meta property=\"og:image:height\" content=\"1575\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"El Tecolote Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:site\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Tecolote Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\\\/\"},\"author\":{\"name\":\"El Tecolote Staff\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\"},\"headline\":\"La Suprema Corte salva a DACA, sin embargo, los trabajadores esenciales contin\u00faan batallando durante la pandemia\",\"datePublished\":\"2020-07-16T20:23:21+00:00\",\"dateModified\":\"2020-07-16T20:23:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\\\/\"},\"wordCount\":1340,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/DACA_Estrada_3225_web-1.jpg?fit=1050%2C1575&quality=89&ssl=1\",\"articleSection\":[\"Inmigraci\u00f3n\",\"Noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\\\/\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\\\/\",\"name\":\"La Suprema Corte salva a DACA, sin embargo, los trabajadores esenciales contin\u00faan batallando durante la pandemia - El Tecolote\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/DACA_Estrada_3225_web-1.jpg?fit=1050%2C1575&quality=89&ssl=1\",\"datePublished\":\"2020-07-16T20:23:21+00:00\",\"dateModified\":\"2020-07-16T20:23:25+00:00\",\"description\":\"Nota: Ante la preocupaci\u00f3n por la seguridad de la comunidad de indocumentados, los apellidos ser\u00e1n omitidos en esta historia para proteger el anonimato de\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/DACA_Estrada_3225_web-1.jpg?fit=1050%2C1575&quality=89&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/DACA_Estrada_3225_web-1.jpg?fit=1050%2C1575&quality=89&ssl=1\",\"width\":1050,\"height\":1575,\"caption\":\"Noem\u00ed, de 32 a\u00f1os, del sur de California y receptora de DACA, en su casa. Fue despedida de su trabajo como asistente personal en marzo y ahora trabaja como gerente en un restaurante. Foto: Pamela Estrada\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"name\":\"El Tecolote\",\"description\":\"San Francisco&#039;s Latinx newspaper since 1970\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\",\"name\":\"El Tecolote\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"width\":400,\"height\":400,\"caption\":\"El Tecolote\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTecoloteSF\\\/\",\"https:\\\/\\\/x.com\\\/eltecolotesf\",\"https:\\\/\\\/www.instagram.com\\\/eltecolotesf\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\",\"name\":\"El Tecolote Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"caption\":\"El Tecolote Staff\"},\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/author\\\/web-editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Suprema Corte salva a DACA, sin embargo, los trabajadores esenciales contin\u00faan batallando durante la pandemia - El Tecolote","description":"Nota: Ante la preocupaci\u00f3n por la seguridad de la comunidad de indocumentados, los apellidos ser\u00e1n omitidos en esta historia para proteger el anonimato de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltecolote.org\/content\/es\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\/","og_locale":"en_US","og_type":"article","og_title":"La Suprema Corte salva a DACA, sin embargo, los trabajadores esenciales contin\u00faan batallando durante la pandemia - El Tecolote","og_description":"Nota: Ante la preocupaci\u00f3n por la seguridad de la comunidad de indocumentados, los apellidos ser\u00e1n omitidos en esta historia para proteger el anonimato de","og_url":"https:\/\/eltecolote.org\/content\/es\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\/","og_site_name":"El Tecolote","article_publisher":"https:\/\/www.facebook.com\/ElTecoloteSF\/","article_published_time":"2020-07-16T20:23:21+00:00","article_modified_time":"2020-07-16T20:23:25+00:00","og_image":[{"width":1050,"height":1575,"url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/DACA_Estrada_3225_web-1.jpg?fit=1050%2C1575&ssl=1","type":"image\/jpeg"}],"author":"El Tecolote Staff","twitter_card":"summary_large_image","twitter_creator":"@eltecolotesf","twitter_site":"@eltecolotesf","twitter_misc":{"Written by":"El Tecolote Staff","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/eltecolote.org\/content\/es\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\/#article","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/es\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\/"},"author":{"name":"El Tecolote Staff","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e"},"headline":"La Suprema Corte salva a DACA, sin embargo, los trabajadores esenciales contin\u00faan batallando durante la pandemia","datePublished":"2020-07-16T20:23:21+00:00","dateModified":"2020-07-16T20:23:25+00:00","mainEntityOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\/"},"wordCount":1340,"commentCount":0,"publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/DACA_Estrada_3225_web-1.jpg?fit=1050%2C1575&quality=89&ssl=1","articleSection":["Inmigraci\u00f3n","Noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eltecolote.org\/content\/es\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eltecolote.org\/content\/es\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\/","url":"https:\/\/eltecolote.org\/content\/es\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\/","name":"La Suprema Corte salva a DACA, sin embargo, los trabajadores esenciales contin\u00faan batallando durante la pandemia - El Tecolote","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\/#primaryimage"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/DACA_Estrada_3225_web-1.jpg?fit=1050%2C1575&quality=89&ssl=1","datePublished":"2020-07-16T20:23:21+00:00","dateModified":"2020-07-16T20:23:25+00:00","description":"Nota: Ante la preocupaci\u00f3n por la seguridad de la comunidad de indocumentados, los apellidos ser\u00e1n omitidos en esta historia para proteger el anonimato de","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltecolote.org\/content\/es\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eltecolote.org\/content\/es\/la-suprema-corte-salva-a-daca-sin-embargo-los-trabajadores-esenciales-continuan-batallando-durante-la-pandemia\/#primaryimage","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/DACA_Estrada_3225_web-1.jpg?fit=1050%2C1575&quality=89&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/DACA_Estrada_3225_web-1.jpg?fit=1050%2C1575&quality=89&ssl=1","width":1050,"height":1575,"caption":"Noem\u00ed, de 32 a\u00f1os, del sur de California y receptora de DACA, en su casa. Fue despedida de su trabajo como asistente personal en marzo y ahora trabaja como gerente en un restaurante. Foto: Pamela Estrada"},{"@type":"WebSite","@id":"https:\/\/eltecolote.org\/content\/#website","url":"https:\/\/eltecolote.org\/content\/","name":"El Tecolote","description":"San Francisco&#039;s Latinx newspaper since 1970","publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltecolote.org\/content\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/eltecolote.org\/content\/#organization","name":"El Tecolote","url":"https:\/\/eltecolote.org\/content\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","width":400,"height":400,"caption":"El Tecolote"},"image":{"@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTecoloteSF\/","https:\/\/x.com\/eltecolotesf","https:\/\/www.instagram.com\/eltecolotesf\/"]},{"@type":"Person","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e","name":"El Tecolote Staff","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d","url":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","caption":"El Tecolote Staff"},"url":"https:\/\/eltecolote.org\/content\/author\/web-editor\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"El Tecolote","distributor_original_site_url":"https:\/\/eltecolote.org\/content","push-errors":false,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/DACA_Estrada_3225_web-1.jpg?fit=1050%2C1575&quality=89&ssl=1","_links":{"self":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/44669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/comments?post=44669"}],"version-history":[{"count":2,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/44669\/revisions"}],"predecessor-version":[{"id":44673,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/44669\/revisions\/44673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media\/44672"}],"wp:attachment":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media?parent=44669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/categories?post=44669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/tags?post=44669"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/coauthors?post=44669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}