{"id":44458,"date":"2020-07-02T13:40:50","date_gmt":"2020-07-02T20:40:50","guid":{"rendered":"http:\/\/eltecolote.org\/content\/?p=44458"},"modified":"2020-07-02T13:40:52","modified_gmt":"2020-07-02T20:40:52","slug":"la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19","status":"publish","type":"post","link":"https:\/\/eltecolote.org\/content\/es\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\/","title":{"rendered":"La experiencia de una adolescente Navajo graduada durante la COVID-19"},"content":{"rendered":"\n<p>Se estima que la graduaci\u00f3n de la generaci\u00f3n 2020 del nivel preparatoria en los EEUU suma alrededor de 3.7 millones de egresados. Muchos buscar\u00e1n un t\u00edtulo universitario o tal vez capacitaci\u00f3n vocacional de alg\u00fan tipo y otros ingresar\u00e1n a un mercado laboral que es uno de los peores en la historia de este pa\u00eds. El Tecolote habl\u00f3 con una reci\u00e9n graduada de la escuela secundaria de la Naci\u00f3n Navajo, Nishonii Holiday, sobre este hito en su vida y c\u00f3mo su comunidad ha sido impactada por la COVID-19 en los \u00faltimos meses.<br><\/p>\n\n\n\n<p>Cuando se le pregunta su nombre completo para esta historia, ella dice sonriendo: \u201cOk, voy a presentarme y explicar\u201d. Cuando un nativo americano de la Naci\u00f3n Navajo se presenta, es m\u00e1s que solo decirle a alguien su nombre, se trata de compartir qui\u00e9nes son y de d\u00f3nde vienen. Esto comienza con sus clanes. Cada clan proviene de un \u00e1rea diferente de la Naci\u00f3n Navajo, con su propio significado y una historia. Cada persona pertenece a cuatro clanes diferentes.<br><\/p>\n\n\n\n<p>\u201cCuando conoces a alguien y le das la mano, le est\u00e1s contando toda tu historia\u201d, dijo Holiday, explicando que la historia de una persona es contada por su mano, con cada dedo representando un clan. \u201cEres tu pulgar y luego presentas a tus cuatro clanes. El primer dedo es para el clan de tu madre (nish\u0142\u012f\u0301), el segundo es el de tu padre (bashishchiin), el tercero, de tu abuelo materno (dashicheii) y el cuarto de tu abuelo paterno (dashinal\u00ed).<br><\/p>\n\n\n\n<p>\u201cEntonces, as\u00ed es como me presento\u201d, comienza Holiday. \u201cSh\u00ed \u00e9\u00ed (nombre) yinishy\u00e9 (me llamo) Nishonii Holiday; o, mi nombre es Nishonii Holiday, Coyote Pass Jemez, Blacksheep, Kiaoni, Folding Arm. Soy del Cap\u00edtulo Oljato de la Naci\u00f3n Navajo y me gradu\u00e9 de la Monument Valley High School, clase de 2020\u201d. Nishonii, si te est\u00e1s preguntando, significa hermoso.<br><\/p>\n\n\n\n<p>A pesar de los desaf\u00edos y dificultades que ha enfrentado a su corta edad, Holiday tiene una actitud tranquila y pac\u00edfica, optimista con una sensibilidad relajada que revela madurez a sus 17 a\u00f1os. Es la menor de siete hijos, nueve, si incluye dos hermanastros. Vive con su padre y uno de sus hermanos mayores en lo que se refiere como una ciudad peque\u00f1a a mediana, seg\u00fan los est\u00e1ndares de la naci\u00f3n navajo, de unas 200 personas. Su madre vive con sus abuelos en la siguiente ciudad, al igual que su madrastra, y el resto de sus hermanos viven en la reserva y en Salt Lake City, Utah.<br><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-full is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Nishonii_web.jpg?resize=395%2C493&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-44460\" width=\"395\" height=\"493\" srcset=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Nishonii_web.jpg?w=640&amp;quality=89&amp;ssl=1 640w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Nishonii_web.jpg?resize=200%2C250&amp;quality=89&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Nishonii_web.jpg?resize=384%2C480&amp;quality=89&amp;ssl=1 384w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Nishonii_web.jpg?resize=370%2C463&amp;quality=89&amp;ssl=1 370w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Nishonii_web.jpg?resize=185%2C231&amp;quality=89&amp;ssl=1 185w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Nishonii_web.jpg?resize=20%2C25&amp;quality=89&amp;ssl=1 20w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Nishonii_web.jpg?resize=400%2C500&amp;quality=89&amp;ssl=1 400w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Nishonii_web.jpg?resize=600%2C750&amp;quality=89&amp;ssl=1 600w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Nishonii_web.jpg?resize=38%2C48&amp;quality=89&amp;ssl=1 38w\" sizes=\"auto, (max-width: 395px) 100vw, 395px\" \/><figcaption>Nishonii Holiday. Cortes\u00eda: Nishonii Holiday<\/figcaption><\/figure><\/div>\n\n\n\n<p>Su padre es un soldador que, a menudo, est\u00e1 fuera de casa por su trabajo, por lo que depende principalmente de Holiday y su hermano mantener las cosas en la casa, incluso obtener agua del pozo propiedad de un t\u00edo varias veces a la semana y garantizar que se mantengan en funci\u00f3n el generador y la letrina. \u201cLa mayor\u00eda de las personas que viven en la reserva en la Naci\u00f3n Navajo no tienen servicio de agua corriente, electricidad o gas natural. Muchas personas dependen del propano para calentar su hogar y para calentar agua para cocinar y ba\u00f1arse. Algunos pueden tener uno u otro, la mayor\u00eda en el valle no tiene nada\u201d.<br><\/p>\n\n\n\n<p>Holiday comparte videos en Tik Tok de su vida en la reserva, incluida su rutina de lavado de cabello usando las jarras de agua que ella y su hermano llenan de sus viajes al pozo. La casa en la que ha estado viviendo durante los \u00faltimos tres a\u00f1os no tiene agua corriente ni electricidad, pero esperan tenerla este verano. \u201cTodo lleva mucho tiempo con el gobierno navajo, as\u00ed es como es\u201d, dijo. \u201cUn grupo de estudiantes de mi escuela fue a Washington DC y visit\u00f3 la oficina de la Naci\u00f3n Navajo, dijeron que hab\u00edan recibido todos estos fondos, pero no sabemos a d\u00f3nde fueron. No es que necesitemos donaciones, necesitamos acci\u00f3n\u201d.<br><\/p>\n\n\n\n<p>Cuando se le pregunt\u00f3 sobre los desaf\u00edos que enfrenta su gente durante la pandemia, ella tiene una respuesta compleja pero simple: \u201cLas personas que viven en la reserva en la Naci\u00f3n Navajo no conf\u00edan mucho en las personas de afuera. Los ancianos y los adultos no quieren la ayuda de los no nativos y no siempre siguen los consejos que les dan las personas que consideran extra\u00f1as. El gobierno navajo tampoco se comunica bien con la gente. Tambi\u00e9n tenemos mal acceso a Internet, por lo que es dif\u00edcil obtener informaci\u00f3n, especialmente cuando todo cambia constantemente. Todo esto hace que los j\u00f3venes se sientan impotentes y temerosos de que la preservaci\u00f3n de nuestra cultura y patrimonio se pierda sin que los mayores transmitan las tradiciones\u201d.<br><\/p>\n\n\n\n<p>Cuando la COVID-19 lleg\u00f3 a su comunidad, los recursos comenzaron a disminuir r\u00e1pidamente. Hay solo 13 tiendas de comestibles en toda la Naci\u00f3n Navajo, un \u00e1rea de aproximadamente 27 millas cuadradas con 173 mil personas. \u201cComenzaron a quedarse sin comida y suministros r\u00e1pidamente\u201d, dijo Holiday. \u201cLos nativos simplemente no son reconocidos, pero con la ayuda de celebridades como Sean Penn y Jason Momoa, obtuvimos el agua, la comida y los suministros que necesit\u00e1bamos. Finalmente, el gobierno navajo dio un paso al frente y abri\u00f3 bancos de alimentos. Por qu\u00e9 tom\u00f3 tanto tiempo, no lo sabemos, no dicen nada\u201d.<br><\/p>\n\n\n\n<p>El d\u00eda de graduaci\u00f3n para las escuelas secundarias en la Naci\u00f3n Navajo fue muy parecido al resto del pa\u00eds, sin incidentes: \u201cPodr\u00edamos hacer que la familia nos llevara a la graduaci\u00f3n, pero todo fue por separado. Fuimos uno por uno a tomarnos una foto con el director sosteniendo nuestro diploma, volvimos al auto y nos fuimos. No vi a mis amigos, mi familia no me vio obtener mi diploma, eso fue as\u00ed\u201d. Cuando se le pregunt\u00f3 si su escuela planeaba celebrar la graduaci\u00f3n m\u00e1s tarde, ella dijo: \u201cNo lo creo\u201d.<br><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"2016\" height=\"980\" src=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?resize=2016%2C980&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-44459\" srcset=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?w=2016&amp;quality=89&amp;ssl=1 2016w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?resize=360%2C175&amp;quality=89&amp;ssl=1 360w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?resize=600%2C292&amp;quality=89&amp;ssl=1 600w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?resize=768%2C373&amp;quality=89&amp;ssl=1 768w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?resize=1536%2C747&amp;quality=89&amp;ssl=1 1536w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?resize=370%2C180&amp;quality=89&amp;ssl=1 370w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?resize=800%2C389&amp;quality=89&amp;ssl=1 800w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?resize=185%2C90&amp;quality=89&amp;ssl=1 185w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?resize=740%2C360&amp;quality=89&amp;ssl=1 740w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?resize=20%2C10&amp;quality=89&amp;ssl=1 20w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?resize=400%2C194&amp;quality=89&amp;ssl=1 400w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?resize=1600%2C778&amp;quality=89&amp;ssl=1 1600w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?resize=99%2C48&amp;quality=89&amp;ssl=1 99w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption>Monument Valley, Utah. \nFoto: Nishonii Holiday\n<\/figcaption><\/figure><\/div>\n\n\n\n<p>\u201cLa Naci\u00f3n Navajo est\u00e1 un poco cerrada y mi padre fue despedido recientemente, as\u00ed que probablemente al menos pueda pasar tiempo con \u00e9l y mi hermano\u201d, dijo. Nishonii se dirige a Fort Lewis College en el oto\u00f1o, donde vivir\u00e1 en el campus y estudiar\u00e1 biolog\u00eda con planes de ir a la escuela de odontolog\u00eda. Ella quiere regresar a la Naci\u00f3n Navajo y ayudar a su gente. Trabajar\u00e1 con ni\u00f1os para ayudarlos a comprender la importancia de una buena salud dental. \u201cNecesitan saber que comen, hablan y sonr\u00eden con los dientes, por lo que deben cuidarlos bien\u201d, dijo Holiday.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se estima que la graduaci\u00f3n de la generaci\u00f3n 2020 del nivel preparatoria en los EEUU suma alrededor de 3.7 millones de egresados. Muchos buscar\u00e1n un t\u00edtulo universitario o tal vez capacitaci\u00f3n vocacional de alg\u00fan tipo y otros ingresar\u00e1n a un mercado laboral que es uno de los peores en la historia de este pa\u00eds. El [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":44459,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_popups_has_disabled_popups":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3569,3519],"tags":[],"coauthors":[18445],"class_list":["post-44458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion-es","category-noticias","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La experiencia de una adolescente Navajo graduada durante la COVID-19 - El Tecolote<\/title>\n<meta name=\"description\" content=\"Se estima que la graduaci\u00f3n de la generaci\u00f3n 2020 del nivel preparatoria en los EEUU suma alrededor de 3.7 millones de egresados. Muchos buscar\u00e1n un\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltecolote.org\/content\/es\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La experiencia de una adolescente Navajo graduada durante la COVID-19 - El Tecolote\" \/>\n<meta property=\"og:description\" content=\"Se estima que la graduaci\u00f3n de la generaci\u00f3n 2020 del nivel preparatoria en los EEUU suma alrededor de 3.7 millones de egresados. Muchos buscar\u00e1n un\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltecolote.org\/content\/es\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"El Tecolote\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTecoloteSF\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-02T20:40:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-02T20:40:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?fit=2016%2C980&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"2016\" \/>\n\t<meta property=\"og:image:height\" content=\"980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"El Tecolote Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:site\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Tecolote Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\\\/\"},\"author\":{\"name\":\"El Tecolote Staff\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\"},\"headline\":\"La experiencia de una adolescente Navajo graduada durante la COVID-19\",\"datePublished\":\"2020-07-02T20:40:50+00:00\",\"dateModified\":\"2020-07-02T20:40:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\\\/\"},\"wordCount\":1123,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?fit=2016%2C980&quality=89&ssl=1\",\"articleSection\":[\"Educaci\u00f3n\",\"Noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\\\/\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\\\/\",\"name\":\"La experiencia de una adolescente Navajo graduada durante la COVID-19 - El Tecolote\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?fit=2016%2C980&quality=89&ssl=1\",\"datePublished\":\"2020-07-02T20:40:50+00:00\",\"dateModified\":\"2020-07-02T20:40:52+00:00\",\"description\":\"Se estima que la graduaci\u00f3n de la generaci\u00f3n 2020 del nivel preparatoria en los EEUU suma alrededor de 3.7 millones de egresados. Muchos buscar\u00e1n un\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?fit=2016%2C980&quality=89&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?fit=2016%2C980&quality=89&ssl=1\",\"width\":2016,\"height\":980,\"caption\":\"Monument Valley, Utah. Foto: Nishonii Holiday\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"name\":\"El Tecolote\",\"description\":\"San Francisco&#039;s Latinx newspaper since 1970\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\",\"name\":\"El Tecolote\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"width\":400,\"height\":400,\"caption\":\"El Tecolote\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTecoloteSF\\\/\",\"https:\\\/\\\/x.com\\\/eltecolotesf\",\"https:\\\/\\\/www.instagram.com\\\/eltecolotesf\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\",\"name\":\"El Tecolote Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"caption\":\"El Tecolote Staff\"},\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/author\\\/web-editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La experiencia de una adolescente Navajo graduada durante la COVID-19 - El Tecolote","description":"Se estima que la graduaci\u00f3n de la generaci\u00f3n 2020 del nivel preparatoria en los EEUU suma alrededor de 3.7 millones de egresados. Muchos buscar\u00e1n un","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltecolote.org\/content\/es\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\/","og_locale":"en_US","og_type":"article","og_title":"La experiencia de una adolescente Navajo graduada durante la COVID-19 - El Tecolote","og_description":"Se estima que la graduaci\u00f3n de la generaci\u00f3n 2020 del nivel preparatoria en los EEUU suma alrededor de 3.7 millones de egresados. Muchos buscar\u00e1n un","og_url":"https:\/\/eltecolote.org\/content\/es\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\/","og_site_name":"El Tecolote","article_publisher":"https:\/\/www.facebook.com\/ElTecoloteSF\/","article_published_time":"2020-07-02T20:40:50+00:00","article_modified_time":"2020-07-02T20:40:52+00:00","og_image":[{"width":2016,"height":980,"url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?fit=2016%2C980&ssl=1","type":"image\/jpeg"}],"author":"El Tecolote Staff","twitter_card":"summary_large_image","twitter_creator":"@eltecolotesf","twitter_site":"@eltecolotesf","twitter_misc":{"Written by":"El Tecolote Staff","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/eltecolote.org\/content\/es\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\/#article","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/es\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\/"},"author":{"name":"El Tecolote Staff","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e"},"headline":"La experiencia de una adolescente Navajo graduada durante la COVID-19","datePublished":"2020-07-02T20:40:50+00:00","dateModified":"2020-07-02T20:40:52+00:00","mainEntityOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\/"},"wordCount":1123,"commentCount":0,"publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?fit=2016%2C980&quality=89&ssl=1","articleSection":["Educaci\u00f3n","Noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eltecolote.org\/content\/es\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eltecolote.org\/content\/es\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\/","url":"https:\/\/eltecolote.org\/content\/es\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\/","name":"La experiencia de una adolescente Navajo graduada durante la COVID-19 - El Tecolote","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?fit=2016%2C980&quality=89&ssl=1","datePublished":"2020-07-02T20:40:50+00:00","dateModified":"2020-07-02T20:40:52+00:00","description":"Se estima que la graduaci\u00f3n de la generaci\u00f3n 2020 del nivel preparatoria en los EEUU suma alrededor de 3.7 millones de egresados. Muchos buscar\u00e1n un","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltecolote.org\/content\/es\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eltecolote.org\/content\/es\/la-experiencia-de-una-adolescente-navajo-graduada-durante-la-covid-19\/#primaryimage","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?fit=2016%2C980&quality=89&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?fit=2016%2C980&quality=89&ssl=1","width":2016,"height":980,"caption":"Monument Valley, Utah. Foto: Nishonii Holiday"},{"@type":"WebSite","@id":"https:\/\/eltecolote.org\/content\/#website","url":"https:\/\/eltecolote.org\/content\/","name":"El Tecolote","description":"San Francisco&#039;s Latinx newspaper since 1970","publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltecolote.org\/content\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/eltecolote.org\/content\/#organization","name":"El Tecolote","url":"https:\/\/eltecolote.org\/content\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","width":400,"height":400,"caption":"El Tecolote"},"image":{"@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTecoloteSF\/","https:\/\/x.com\/eltecolotesf","https:\/\/www.instagram.com\/eltecolotesf\/"]},{"@type":"Person","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e","name":"El Tecolote Staff","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d","url":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","caption":"El Tecolote Staff"},"url":"https:\/\/eltecolote.org\/content\/author\/web-editor\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"El Tecolote","distributor_original_site_url":"https:\/\/eltecolote.org\/content","push-errors":false,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2020\/07\/Monument-Valley-UT_photo-by-Nishonii-Holiday_web.jpg?fit=2016%2C980&quality=89&ssl=1","_links":{"self":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/44458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/comments?post=44458"}],"version-history":[{"count":1,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/44458\/revisions"}],"predecessor-version":[{"id":44461,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/44458\/revisions\/44461"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media\/44459"}],"wp:attachment":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media?parent=44458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/categories?post=44458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/tags?post=44458"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/coauthors?post=44458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}