{"id":42240,"date":"2019-11-21T18:08:15","date_gmt":"2019-11-22T01:08:15","guid":{"rendered":"http:\/\/eltecolote.org\/content\/?p=42240"},"modified":"2019-11-21T18:08:21","modified_gmt":"2019-11-22T01:08:21","slug":"con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo","status":"publish","type":"post","link":"https:\/\/eltecolote.org\/content\/es\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\/","title":{"rendered":"Con una prometedora reforma a la justicia, Chesa Boudin perturba al status quo"},"content":{"rendered":"\n<p>Los partidarios del fiscal de distrito de San Francisco electo, Chesa Boudin, quien esperaba celebrar una victoria en la misma noche de las elecciones, tuvieron que esperar cuatro d\u00edas para que el conteo de votos fuera suficiente para asegurar una victoria. Pero el estado de \u00e1nimo en El R\u00edo el s\u00e1bado 9 de noviembre fue vibrante, y marc\u00f3 el final de una elecci\u00f3n muy re\u00f1ida que atrajo la atenci\u00f3n nacional y cientos de miles de d\u00f3lares.<\/p>\n\n\n\n<p>Aunque Boudin recibi\u00f3 casi 9 mil votos m\u00e1s que su oponente m\u00e1s cercano, solo tuvo alrededor del 36 por ciento de los votos en general. Por lo tanto, el sistema de votaci\u00f3n por orden de preferencia de San Francisco entr\u00f3 en acci\u00f3n, otorg\u00e1ndole votos a \u00e9l o a su oponente, Suzy Loftus, de acuerdo con las elecciones de segundo y tercer lugar de los votantes. Al final, gan\u00f3 por solo 2,831 votos.<\/p>\n\n\n\n<p>Entre los distintivos carteles de campa\u00f1a de Boudin en verde y naranja, sus partidarios tambi\u00e9n usaron camisetas y pines para otros candidatos progresistas, como el senador y candidato presidencial Bernie Sanders y Shahid Buttar, que se postula para representar a San Francisco en la C\u00e1mara de Representantes. La energ\u00eda que mantuvo la fiesta durante varias horas \u201cest\u00e1 poniendo viento a nuestras ventas\u201d, como lo expres\u00f3 su partidario Cody England. \u201cEsta energ\u00eda se transferir\u00e1 a las carreras progresivas en San Francisco y el \u00c1rea de la Bah\u00eda. Vemos que el progresismo est\u00e1 ganando y ya se esperaba en San Francisco\u201d, agreg\u00f3.<\/p>\n\n\n\n<p>La contienda para la fiscal\u00eda de distrito a menudo no recibe mucha atenci\u00f3n, pero en este caso, la fiesta de la victoria atrajo a algunos nombres importantes, como la ex supervisora y candidata a alcalde Jane Kim, el supervisor del Distrito 6 Matt Haney y el activista de Black Lives Matter, Shaun King.<\/p>\n\n\n\n<figure class=\"wp-block-image alignwide\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1832\" height=\"1221\" src=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/11\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?resize=1832%2C1221&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-42242\" srcset=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/11\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?w=1832&amp;quality=89&amp;ssl=1 1832w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/11\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?resize=360%2C240&amp;quality=89&amp;ssl=1 360w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/11\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?resize=768%2C512&amp;quality=89&amp;ssl=1 768w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/11\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?resize=600%2C400&amp;quality=89&amp;ssl=1 600w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/11\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?resize=370%2C247&amp;quality=89&amp;ssl=1 370w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/11\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?resize=800%2C533&amp;quality=89&amp;ssl=1 800w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/11\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?resize=20%2C13&amp;quality=89&amp;ssl=1 20w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/11\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?resize=185%2C123&amp;quality=89&amp;ssl=1 185w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/11\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?resize=740%2C493&amp;quality=89&amp;ssl=1 740w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/11\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?resize=1110%2C740&amp;quality=89&amp;ssl=1 1110w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/11\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?resize=400%2C267&amp;quality=89&amp;ssl=1 400w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/11\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?resize=1600%2C1066&amp;quality=89&amp;ssl=1 1600w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/11\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?resize=72%2C48&amp;quality=89&amp;ssl=1 72w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption>El fiscal de distrito electo, Chesa Boudin, y su prometida, Valerie Block, celebran la victoria en El R\u00edo, el 9 de noviembre de 2019. Foto: Beth LaBerge<\/figcaption><\/figure>\n\n\n\n<p>Sin embargo, el propio Boudin desapareci\u00f3 durante las primeras horas; ven\u00eda en un vuelo desde Nueva York cuando el Departamento de Elecciones public\u00f3 los resultados que mostraban su victoria. Pudo ver los resultados, y una avalancha de mensajes de texto de felicitaci\u00f3n. Muchos de esos textos llegaron a trav\u00e9s de un n\u00famero de Google Voice. \u201c[Los sistemas de Google] pensaron que estaba enviando correo no deseado por tantos mensajes que se estaban enviando. Entonces, mientras estaba en el avi\u00f3n, perd\u00ed uno de mis dos n\u00fameros\u201d, dijo Boudin.<\/p>\n\n\n\n<p>Boudin hab\u00eda ido a Nueva York a visitar a su padre, quien estuvo en prisi\u00f3n casi toda su vida. Esa experiencia \u201chizo que Chesa dedicara su carrera a hacer que nuestro pa\u00eds sea m\u00e1s seguro mediante la reforma de nuestro sistema de justicia penal\u201d, seg\u00fan el sitio web de su campa\u00f1a. Prometi\u00f3 enfatizar la \u201cjusticia restaurativa\u201d (un modelo de justicia que se enfoca en rehabilitar a los delincuentes a trav\u00e9s de la reconciliaci\u00f3n con las v\u00edctimas y la comunidad en general) en lugar del encarcelamiento y otros enfoques punitivos como la libertad condicional.<\/p>\n\n\n\n<p>Ese enfoque de la justicia penal llam\u00f3 la atenci\u00f3n de Brandon Harami, presidente de los Berniecratas de San Francisco. En particular, la oposici\u00f3n de Boudin a la fianza apel\u00f3 a Harami cuando se reunieron al principio de la campa\u00f1a para considerar si los Berniecratas respaldar\u00edan su candidatura.<\/p>\n\n\n\n<p>\u201cLa fianza es realmente un sistema que ayuda a los ricos a salir de la c\u00e1rcel m\u00e1s r\u00e1pido mientras que los pobres son encarcelados, tal vez incluso por un delito que ni siquiera cometieron\u201d, dijo Harami. \u201c\u00a1Chesa se ha comprometido a poner fin a la fianza y su elecci\u00f3n significa que le pondremos fin en San Francisco!\u201d<\/p>\n\n\n\n<p>Despu\u00e9s de esa conversaci\u00f3n, Berniecratas de la ciudad respaldaron a Boudin, junto con varias otras organizaciones locales, incluyendo la UESF, la Uni\u00f3n de Inquilinos de San Francisco, el Club Dem\u00f3crata Latino y el Local 1021 de SEIU.<\/p>\n\n\n\n<p>Adem\u00e1s de todos esos avales locales, la campa\u00f1a obtuvo un respaldo nacional de alto perfil, en las \u00faltimas semanas de la contienda. El 28 de octubre, el senador Bernie Sanders se tom\u00f3 un momento de su propia carrera para la nominaci\u00f3n dem\u00f3crata para presidente, para respaldar a Boudin, el \u00fanico candidato que apoy\u00f3 en California en 2019.<\/p>\n\n\n\n<p>Jane Kim, ahora miembro destacado del equipo de Sanders en California, explic\u00f3 por qu\u00e9 esta carrera fue tan importante para Sanders: \u201cLa reforma de la justicia penal es una parte clave de la plataforma del senador para postularse a la presidencia\u201d, dijo. Compar\u00f3 a Boudin con otros candidatos a fiscales de distrito que se han postulado recientemente en plataformas similares, como Larry Krasner, quien fue elegido fiscal de distrito para Filadelfia en noviembre de 2017, y Tiffany Cab\u00e1n, que lleg\u00f3 a solo 55 votos de ganar las primarias dem\u00f3cratas para convertirse en Fiscal de Distrito en Queens, Nueva York.<\/p>\n\n\n\n<p>\u201cLa gente ahora se ha dado cuenta de que si quiere ver una verdadera reforma de la justicia penal, tiene que suceder en la oficina del fiscal de distrito, por lo que se necesitaron a\u00f1os de trabajo para lograr estas victorias\u201d, dijo Kim.<\/p>\n\n\n\n<p>Boudin lleg\u00f3 a la fiesta alrededor de las 9:30 p.m. En su discurso de victoria, enfatiz\u00f3 la importancia del trabajo voluntario realizado por SF Rising Action Fund, que se describe en su sitio web como \u201cuna vibrante y joven alianza electoral que construye el poder pol\u00edtico de las comunidades de color de la clase trabajadora en San Francisco\u201d.<\/p>\n\n\n\n<p>Emily Lee, directora de SF Rising Action Fund, cit\u00f3 la responsabilidad policial como una raz\u00f3n importante para el apoyo de esa organizaci\u00f3n a Boudin. Con los asesinatos de alto perfil cometidos por el SFPD en los \u00faltimos a\u00f1os, los oficiales \u201cb\u00e1sicamente cometieron esos actos de asesinato con impunidad, y el fiscal nunca present\u00f3 cargos en ese momento\u201d, dijo. \u201c[Eso es] lo que Chesa representaba para nuestras comunidades &#8230; un fiscal que realmente responsabilice a la polic\u00eda&#8230; que no deje que los agentes salgan impunes [o] con solo una palmada en la mu\u00f1eca\u201d.<\/p>\n\n\n\n<p>Ella dijo que su trabajo en la campa\u00f1a de Boudin tambi\u00e9n ayudar\u00e1 a que la votaci\u00f3n se convierta en un h\u00e1bito entre las comunidades de color, para que esas comunidades est\u00e9n mejor representadas en las elecciones en 2020. \u201cSi puedes hacerlo un h\u00e1bito, entonces se har\u00e1 m\u00e1s y m\u00e1s a menudo\u201d, dijo.<\/p>\n\n\n\n<p>El principal oponente de Boudin, Suzy Loftus, cont\u00f3 con el apoyo de gran parte del aparato pol\u00edtico, incluido el Partido Dem\u00f3crata de San Francisco, los senadores de California y la alcaldesa London Breed. Cuando el Fiscal de Distrito George Gasc\u00f3n anunci\u00f3 el 3 de octubre que planeaba renunciar antes de las elecciones, Breed r\u00e1pidamente anunci\u00f3 que nombrar\u00eda a Loftus, convirti\u00e9ndola en titular, pocas semanas antes del d\u00eda de las elecciones.<\/p>\n\n\n\n<p>La medida provoc\u00f3 cr\u00edticas y protestas inmediatas. El cap\u00edtulo del norte de California de la ACLU se refiri\u00f3 a la medida como \u201cmaquinaci\u00f3n pol\u00edtica\u201d. El ex senador estatal Mark Leno, que se hab\u00eda alejado de la pol\u00edtica despu\u00e9s de una carrera fallida a la alcald\u00eda el a\u00f1o pasado, sali\u00f3 en apoyo de Boudin despu\u00e9s del nombramiento de Breed, que \u00e9l refiri\u00f3 al San Francisco Examiner como un \u201casalto a un proceso electoral justo\u201d.<\/p>\n\n\n\n<p>Carmello Tringali, un partidario de Boudin que estuvo en la fiesta el s\u00e1bado, calific\u00f3 aquel nombramiento de \u201cindignante\u201d y dijo que en \u00faltima instancia pudo haber ayudado a Boudin a ganar, debido a la reacci\u00f3n violenta a la medida.<\/p>\n\n\n\n<p>Se gastaron casi $2 millones en apoyo de los cuatro candidatos en la carrera de fiscales de distrito, incluidas las contribuciones a las campa\u00f1as y los gastos independientes. Las donaciones en apoyo de Boudin totalizaron alrededor de $958 mil, mientras que las donaciones para Loftus fueron de aproximadamente $587 mil.<\/p>\n\n\n\n<p>Otros $55 mil fueron invertidos no para apoyar a alg\u00fan candidato espec\u00edfico, sino en oposici\u00f3n a Boudin, y este monto fue cubierto en su mayor\u00eda por la Asociaci\u00f3n de Oficiales de Polic\u00eda de San Francisco.<\/p>\n\n\n\n<p><strong>El <\/strong><em>San Francisco Chronicle<\/em> inform\u00f3 que varias asociaciones de oficiales de polic\u00eda de otras ciudades tambi\u00e9n gastaron miles de d\u00f3lares para oponerse a Boudin, incluidos $150 mil del POA de Los \u00c1ngeles y $25 de la Asociaci\u00f3n Benevolente de Sargentos de Nueva York. Sin embargo, la columna no se public\u00f3 hasta mucho despu\u00e9s del d\u00eda de las elecciones, por lo que los votantes no pudieron tener eso en cuenta al hacer su elecci\u00f3n.<\/p>\n\n\n\n<p>El hecho de que las organizaciones policiales de otras ciudades y estados intentaron frustrar la elecci\u00f3n de Boudin habla de la amenaza que su campa\u00f1a representaba para el statu quo, y tambi\u00e9n de la batalla cuesta arriba que enfrentar\u00e1 reformar verdaderamente la justicia. Sin embargo, el nuevo fiscal de distrito de la ciudad, que asume el cargo en enero, se asegur\u00f3 de enfatizar que su elecci\u00f3n es parte de un mayor movimiento para el cambio:<\/p>\n\n\n\n<p>\u201cNo hay forma de que una persona, no importa qui\u00e9n, no importa cu\u00e1n duro trabajen, no importa cu\u00e1n inteligentes sean, pueda lograr el tipo de transformaci\u00f3n que los votantes eligieron en mi para dirigir\u201d, dijo Boudin. \u201cEso requiere un movimiento, Es por eso que estoy tan orgulloso de trabajar con estas otras organizaciones, para que me empujen a medida que avanzamos en los pr\u00f3ximos cuatro a\u00f1os\u201d.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los partidarios del fiscal de distrito de San Francisco electo, Chesa Boudin, quien esperaba celebrar una victoria en la misma noche de las elecciones, tuvieron que esperar cuatro d\u00edas para que el conteo de votos fuera suficiente para asegurar una victoria. Pero el estado de \u00e1nimo en El R\u00edo el s\u00e1bado 9 de noviembre fue [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":42242,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_popups_has_disabled_popups":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3519],"tags":[],"coauthors":[18445],"class_list":["post-42240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Con una prometedora reforma a la justicia, Chesa Boudin perturba al status quo - El Tecolote<\/title>\n<meta name=\"description\" content=\"Los partidarios del fiscal de distrito de San Francisco electo, Chesa Boudin, quien esperaba celebrar una victoria en la misma noche de las elecciones,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltecolote.org\/content\/es\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Con una prometedora reforma a la justicia, Chesa Boudin perturba al status quo - El Tecolote\" \/>\n<meta property=\"og:description\" content=\"Los partidarios del fiscal de distrito de San Francisco electo, Chesa Boudin, quien esperaba celebrar una victoria en la misma noche de las elecciones,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltecolote.org\/content\/es\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\/\" \/>\n<meta property=\"og:site_name\" content=\"El Tecolote\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTecoloteSF\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-22T01:08:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-22T01:08:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/11\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?fit=1832%2C1221&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1832\" \/>\n\t<meta property=\"og:image:height\" content=\"1221\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"El Tecolote Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:site\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Tecolote Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\\\/\"},\"author\":{\"name\":\"El Tecolote Staff\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\"},\"headline\":\"Con una prometedora reforma a la justicia, Chesa Boudin perturba al status quo\",\"datePublished\":\"2019-11-22T01:08:15+00:00\",\"dateModified\":\"2019-11-22T01:08:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\\\/\"},\"wordCount\":1637,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?fit=1832%2C1221&quality=89&ssl=1\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\\\/\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\\\/\",\"name\":\"Con una prometedora reforma a la justicia, Chesa Boudin perturba al status quo - El Tecolote\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?fit=1832%2C1221&quality=89&ssl=1\",\"datePublished\":\"2019-11-22T01:08:15+00:00\",\"dateModified\":\"2019-11-22T01:08:21+00:00\",\"description\":\"Los partidarios del fiscal de distrito de San Francisco electo, Chesa Boudin, quien esperaba celebrar una victoria en la misma noche de las elecciones,\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?fit=1832%2C1221&quality=89&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?fit=1832%2C1221&quality=89&ssl=1\",\"width\":1832,\"height\":1221,\"caption\":\"El fiscal de distrito electo, Chesa Boudin, y su prometida, Valerie Block, celebran la victoria en El R\u00edo, el 9 de noviembre de 2019. Foto: Beth LaBerge\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"name\":\"El Tecolote\",\"description\":\"San Francisco&#039;s Latinx newspaper since 1970\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\",\"name\":\"El Tecolote\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"width\":400,\"height\":400,\"caption\":\"El Tecolote\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTecoloteSF\\\/\",\"https:\\\/\\\/x.com\\\/eltecolotesf\",\"https:\\\/\\\/www.instagram.com\\\/eltecolotesf\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\",\"name\":\"El Tecolote Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"caption\":\"El Tecolote Staff\"},\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/author\\\/web-editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Con una prometedora reforma a la justicia, Chesa Boudin perturba al status quo - El Tecolote","description":"Los partidarios del fiscal de distrito de San Francisco electo, Chesa Boudin, quien esperaba celebrar una victoria en la misma noche de las elecciones,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltecolote.org\/content\/es\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\/","og_locale":"en_US","og_type":"article","og_title":"Con una prometedora reforma a la justicia, Chesa Boudin perturba al status quo - El Tecolote","og_description":"Los partidarios del fiscal de distrito de San Francisco electo, Chesa Boudin, quien esperaba celebrar una victoria en la misma noche de las elecciones,","og_url":"https:\/\/eltecolote.org\/content\/es\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\/","og_site_name":"El Tecolote","article_publisher":"https:\/\/www.facebook.com\/ElTecoloteSF\/","article_published_time":"2019-11-22T01:08:15+00:00","article_modified_time":"2019-11-22T01:08:21+00:00","og_image":[{"width":1832,"height":1221,"url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/11\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?fit=1832%2C1221&ssl=1","type":"image\/jpeg"}],"author":"El Tecolote Staff","twitter_card":"summary_large_image","twitter_creator":"@eltecolotesf","twitter_site":"@eltecolotesf","twitter_misc":{"Written by":"El Tecolote Staff","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/eltecolote.org\/content\/es\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\/#article","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/es\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\/"},"author":{"name":"El Tecolote Staff","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e"},"headline":"Con una prometedora reforma a la justicia, Chesa Boudin perturba al status quo","datePublished":"2019-11-22T01:08:15+00:00","dateModified":"2019-11-22T01:08:21+00:00","mainEntityOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\/"},"wordCount":1637,"commentCount":0,"publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/11\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?fit=1832%2C1221&quality=89&ssl=1","articleSection":["Noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eltecolote.org\/content\/es\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eltecolote.org\/content\/es\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\/","url":"https:\/\/eltecolote.org\/content\/es\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\/","name":"Con una prometedora reforma a la justicia, Chesa Boudin perturba al status quo - El Tecolote","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\/#primaryimage"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/11\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?fit=1832%2C1221&quality=89&ssl=1","datePublished":"2019-11-22T01:08:15+00:00","dateModified":"2019-11-22T01:08:21+00:00","description":"Los partidarios del fiscal de distrito de San Francisco electo, Chesa Boudin, quien esperaba celebrar una victoria en la misma noche de las elecciones,","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltecolote.org\/content\/es\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eltecolote.org\/content\/es\/con-una-prometedora-reforma-a-la-justicia-chesa-boudin-perturba-al-status-quo\/#primaryimage","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/11\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?fit=1832%2C1221&quality=89&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/11\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?fit=1832%2C1221&quality=89&ssl=1","width":1832,"height":1221,"caption":"El fiscal de distrito electo, Chesa Boudin, y su prometida, Valerie Block, celebran la victoria en El R\u00edo, el 9 de noviembre de 2019. Foto: Beth LaBerge"},{"@type":"WebSite","@id":"https:\/\/eltecolote.org\/content\/#website","url":"https:\/\/eltecolote.org\/content\/","name":"El Tecolote","description":"San Francisco&#039;s Latinx newspaper since 1970","publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltecolote.org\/content\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/eltecolote.org\/content\/#organization","name":"El Tecolote","url":"https:\/\/eltecolote.org\/content\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","width":400,"height":400,"caption":"El Tecolote"},"image":{"@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTecoloteSF\/","https:\/\/x.com\/eltecolotesf","https:\/\/www.instagram.com\/eltecolotesf\/"]},{"@type":"Person","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e","name":"El Tecolote Staff","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d","url":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","caption":"El Tecolote Staff"},"url":"https:\/\/eltecolote.org\/content\/author\/web-editor\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"El Tecolote","distributor_original_site_url":"https:\/\/eltecolote.org\/content","push-errors":false,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/11\/017_ElTecolote_ChesaBoudin_11092019_BethLaBerge-WEB-2.jpg?fit=1832%2C1221&quality=89&ssl=1","_links":{"self":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/42240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/comments?post=42240"}],"version-history":[{"count":2,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/42240\/revisions"}],"predecessor-version":[{"id":42243,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/42240\/revisions\/42243"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media\/42242"}],"wp:attachment":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media?parent=42240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/categories?post=42240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/tags?post=42240"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/coauthors?post=42240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}