{"id":41523,"date":"2019-09-12T12:49:11","date_gmt":"2019-09-12T19:49:11","guid":{"rendered":"http:\/\/eltecolote.org\/content\/?p=41523"},"modified":"2019-09-12T12:49:11","modified_gmt":"2019-09-12T19:49:11","slug":"cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap","status":"publish","type":"post","link":"https:\/\/eltecolote.org\/content\/es\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\/","title":{"rendered":"Cantante ind\u00edgena preserva su cultura del colonialismo mediante el rap"},"content":{"rendered":"<figure id=\"attachment_41525\" aria-describedby=\"caption-attachment-41525\" style=\"width: 1613px\" class=\"wp-caption aligncenter\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-41525\" src=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/09\/CalinaLawrence_F0A9484-WEB-1.jpg?resize=1613%2C1075&#038;quality=89&#038;ssl=1\" alt=\"\" width=\"1613\" height=\"1075\" srcset=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/09\/CalinaLawrence_F0A9484-WEB-1.jpg?w=1613&amp;quality=89&amp;ssl=1 1613w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/09\/CalinaLawrence_F0A9484-WEB-1.jpg?resize=600%2C400&amp;quality=89&amp;ssl=1 600w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/09\/CalinaLawrence_F0A9484-WEB-1.jpg?resize=360%2C240&amp;quality=89&amp;ssl=1 360w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/09\/CalinaLawrence_F0A9484-WEB-1.jpg?resize=768%2C512&amp;quality=89&amp;ssl=1 768w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/09\/CalinaLawrence_F0A9484-WEB-1.jpg?w=370&amp;quality=89&amp;ssl=1 370w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/09\/CalinaLawrence_F0A9484-WEB-1.jpg?w=400&amp;quality=89&amp;ssl=1 400w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-41525\" class=\"wp-caption-text\">La m\u00fasico Calina Lawrence, contempla el oc\u00e9ano en Lands End. Foto: Brianna Kalajian<\/figcaption><\/figure>\n<p class=\"p1\">Con m\u00fasica basada en el hip hop, la artista suquamish Calina Lawrence lleva un mensaje de resistencia y solidaridad al estudio de grabaci\u00f3n y al escenario, abogando por causas que golpean cerca de casa.<\/p>\n<p class=\"p6\">Nacida y criada en la reserva india de Port Madison, a sus 26 a\u00f1os celebra el legado dx\u02b7s\u0259q\u02b7\u0259b, una frase de Lushootseed que significa \u201clugar de agua salada clara\u201d, que ha sido el hogar de los Suquamish en la regi\u00f3n Puget Sound de Washington desde tiempos inmemoriales.<\/p>\n<p class=\"p6\">El 20 de agosto, lanz\u00f3 el video musical de su primer sencillo autoproducido \u2018\u0294\u0259sh\u0259li\u0294 ti tx\u02b7\u0259l\u0161ucid [Lushootseed is Alive]\u2019, que rinde homenaje a su herencia Suquamish. La canci\u00f3n comienza y termina con \u201c\u0294\u0259sx\u030cid \u010d\u0259l\u0259p [\u00bfC\u00f3mo est\u00e1n amigos?] \/ \u0294\u0259sw\u0259l\u0259x\u030c\u02b7 \u010d\u0259\u026b [Somos fuertes]\u201d, un di\u00e1logo que Lawrence espera alenta al p\u00fablico a perseverar en la vida.<\/p>\n<p class=\"p6\">\u201c\u00bfQu\u00e9 ser\u00eda si le preguntamos a alguien que amamos o a un grupo de personas que amamos, c\u00f3mo est\u00e1s? Y esa respuesta sea \u2018soy fuerte\u2019. No es algo que escucho a menudo, pero es algo que veo en sus acciones\u201d, dijo Lawrence.<\/p>\n<p class=\"p6\">Filmado en aldeas ancestrales a trav\u00e9s de la pen\u00ednsula de Kitsap, el video presenta a todo un equipo ind\u00edgena, incluido Kanion Productions, el director de fotograf\u00eda Tomas Karmelo Amaya y las voces del campamento cultural Suquamish.<\/p>\n<p class=\"p6\">\u201cDesear\u00eda que cada canci\u00f3n que escribiera pudiera venir de ese lugar de pura felicidad y risas\u201d, dijo Lawrence, quien escribi\u00f3 en coautor\u00eda la canci\u00f3n con su viejo amigo Joey Holmes Sr. \u201cFue como si fu\u00e9ramos ni\u00f1os libres de hablar este idioma a la intemperie y en la comodidad de nuestros hogares, y qui\u00e9n no puede estar contento de ello\u201d.<\/p>\n<p class=\"p6\">[su_youtube url=&#8221;https:\/\/www.youtube.com\/watch?v=xnuF2UkCqAs&#8221;]<\/p>\n<p class=\"p6\">Sin embargo, ese no fue siempre el caso durante generaciones que le antecedieron. D\u00e9cadas de esfuerzos de asimilaci\u00f3n en los EEUU resultaron en una p\u00e9rdida casi total del idioma, lo que oblig\u00f3 a miles de personas a abandonar su estilo de vida tradicional.<\/p>\n<p class=\"p6\">En 1819, el Congreso aprob\u00f3 la Ley del Fondo de Civilizaci\u00f3n, que buscaba asimilar a los j\u00f3venes ind\u00edgenas a la cultura occidental. En efecto, la pol\u00edtica autorizaba la separaci\u00f3n forzada de los ni\u00f1os nativos americanos de sus familias y llevados a internados lejanos. Las instituciones, creadas para figurativamente \u201cmatar al indio y salvar al hombre\u201d, como dijo un general, despojaron a los estudiantes de su cultura, idiomas y pr\u00e1cticas religiosas.<\/p>\n<p class=\"p6\">No fue sino hasta finales de la d\u00e9cada de 1970 que los legisladores prohibieron las pr\u00e1cticas atroces de expulsi\u00f3n a trav\u00e9s de la Ley de Bienestar Infantil India, que otorg\u00f3 a los gobiernos tribales m\u00e1s jurisdicci\u00f3n en asuntos de custodia de menores.<\/p>\n<p class=\"p6\">\u201cSolo puedo cantar esta canci\u00f3n en Lushootseed por cada nieto que lo habl\u00f3 en voz alta para asegurar que las leyes de los idiomas de estas tierras precedan a cualquier ley colonial que exista aqu\u00ed a trav\u00e9s de la guerra religiosa, la coerci\u00f3n, la migraci\u00f3n forzada, la esclavitud, la codicia y la violencia\u201d, dijo Lawrence en las redes sociales.<\/p>\n<p class=\"p6\">Para muchos ind\u00edgenas, el trauma hist\u00f3rico e intergeneracional permanece, aun cuando los sistemas de opresi\u00f3n y asimilaci\u00f3n se han dado, tambi\u00e9n lo han hecho la resistencia y la preservaci\u00f3n.<\/p>\n<p class=\"p6\">Hoy, Lushootseed se incorpora a todos los niveles de educaci\u00f3n en las escuelas suquamish desde el aprendizaje temprano hasta los programas de secundaria. La tribu tambi\u00e9n ofrece oportunidades semanales para que las familias y los miembros de la comunidad practiquen y estudien su idioma juntos. Este a\u00f1o, las Escuelas P\u00fablicas de Seattle (SPS, por sus siglas en ingl\u00e9s), el sistema escolar K-12 m\u00e1s grande de Washington, adopt\u00f3 un curr\u00edculo de estudios sociales que incorpora la historia y los asuntos de las tribus cercanas reconocidas por el gobierno federal, y aprob\u00f3 cinco idiomas de los nativos americanos para impartirse en la escuela secundaria, incluido el Lushootseed sure\u00f1o, Haida, Navajo, Nez Perce y Lakota.<\/p>\n<figure id=\"attachment_41526\" aria-describedby=\"caption-attachment-41526\" style=\"width: 1447px\" class=\"wp-caption aligncenter\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-41526\" src=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/09\/CalinaLawrence_F0A9194-WEB-1.jpg?resize=1447%2C1034&#038;quality=89&#038;ssl=1\" alt=\"\" width=\"1447\" height=\"1034\" srcset=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/09\/CalinaLawrence_F0A9194-WEB-1.jpg?w=1447&amp;quality=89&amp;ssl=1 1447w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/09\/CalinaLawrence_F0A9194-WEB-1.jpg?resize=600%2C429&amp;quality=89&amp;ssl=1 600w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/09\/CalinaLawrence_F0A9194-WEB-1.jpg?resize=350%2C250&amp;quality=89&amp;ssl=1 350w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/09\/CalinaLawrence_F0A9194-WEB-1.jpg?resize=768%2C549&amp;quality=89&amp;ssl=1 768w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/09\/CalinaLawrence_F0A9194-WEB-1.jpg?w=370&amp;quality=89&amp;ssl=1 370w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/09\/CalinaLawrence_F0A9194-WEB-1.jpg?w=400&amp;quality=89&amp;ssl=1 400w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-41526\" class=\"wp-caption-text\">La artista Calina Lawrence, nacida y criada en Washington State, que se identifica como parte de la cultura nativa americana del Pac\u00edfico Noroeste, posa para una fotograf\u00eda en su residencia en San Francisco, el 18 de agosto de 2019. Foto: Brianna Kalajian<\/figcaption><\/figure>\n<p class=\"p6\">\u201cExiste esta interesante iron\u00eda de las personas en este pa\u00eds, las personas que demandan inmigrantes espec\u00edficamente nativos de las Am\u00e9ricas para aprender ingl\u00e9s y, por el contrario la realidad es no (el aprenderlo). \u00bfQu\u00e9 est\u00e1n haciendo las personas para aprender los idiomas de cada paisaje particular en el que viven, idiomas que han existido mucho antes de los EEUU? Est\u00e1 all\u00ed y es accesible\u2026 \u00bfD\u00f3nde se coloca la gente con la incomodidad de no saber lo que digo en mis letras?\u201d, dijo Lawrence.<\/p>\n<p class=\"p6\">Lawrence es un artista de muchos g\u00e9neros, desde hip hop, R&amp;B, hasta soul y poes\u00eda. Esta cantante ind\u00edgena se gradu\u00f3 con honores de la Universidad de San Francisco, obtuvo una licenciatura en Artes Esc\u00e9nicas y Justicia Social y una especializaci\u00f3n en M\u00fasica. Lanz\u00f3 su primer \u00e1lbum en solitario \u2018Epicenter\u2019 en 2018, que inclu\u00eda temas favoritos como \u2018Songbird\u2019 y \u2018Don\u2019t count me out\u2019 con la tambi\u00e9n cantante ind\u00edgena Desirae Harp.<\/p>\n<p class=\"p6\">Con sede en el territorio Ohlone, Lawrence expresa su gratitud por la gente de Yelamu que vivi\u00f3 en la pen\u00ednsula de San Francisco mucho antes de la llegada de los misioneros espa\u00f1oles.<\/p>\n<p class=\"p6\">\u201cLos pueblos Ohlone son mayordomos fuertes y resistentes de este territorio. Incluso a trav\u00e9s del genocidio, han cultivado y mantenido un lugar hermoso para todos los que estamos aqu\u00ed para prosperar en el mundo actual. Como invitados, nuestro deber es mantener su visibilidad y liderazgo\u201d, dijo Lawrence.<\/p>\n<p class=\"p6\">Una defensora de movimientos como \u2018Stand with Standing Rock\u2019 y \u2018Protect Mauna Kea\u2019, sus rimas a menudo hablan de las injusticias sociales y ambientales que han afectado a las comunidades nativas: \u201cMauna Kea es algo que todo el mundo necesita estar atento porque ser\u00e1 un factor decisivo en la forma en que avanzamos\u201d, dijo la artista.<\/p>\n<p class=\"p6\">El destino de Mauna Kea sigue sin definirse, ya que miles de Kanaka Maoli (nativos hawaianos) contin\u00faan su lucha de ya una d\u00e9cada contra un observatorio de $1.4 mil millones programado para la construcci\u00f3n en su monta\u00f1a m\u00e1s sagrada. Si se construye, el Telescopio de treinta metros (TMT), como se le conoce, se convertir\u00eda en uno de los telescopios m\u00e1s grandes del mundo, con una altura de 18 pisos.<\/p>\n<p class=\"p6\">\u201cMauna Kea es donde encontr\u00e9 mucha de mi fuerza y permiso de la tierra para hacer la curaci\u00f3n que necesitaba\u201d, dijo Lawrence. \u201cLa familia que obtuve de la tierra de Hawai, las relaciones que he construido y el ejemplo que han dado realmente han cambiado mi vida\u201d.<\/p>\n<p class=\"p6\">Lawrence tambi\u00e9n se ha convertido en una fuerza reconocible en las acciones en el pa\u00eds, arrojando luz sobre los derechos de los tratados, los casos de mujeres ind\u00edgenas desaparecidas y asesinadas, y la tergiversaci\u00f3n de los nativos americanos en los principales medios de comunicaci\u00f3n.<\/p>\n<p class=\"p6\">El llamado a la acci\u00f3n en su territorio es \u2018No LNG in 253\u2019, que representa el c\u00f3digo de \u00e1rea para los residentes de la reserva india de Tacoma y Puyallup. En 2016, Puget Sound Energy anunci\u00f3 planes para construir una planta de gas natural licuado de 8 millones de galones en la desembocadura del r\u00edo Puyallup. Hoy, el proyecto est\u00e1 a un paso de finalizar, ignorando todas las protecciones garantizadas a las tribus cercanas bajo el Tratado de 1854 Medicine Creek.<\/p>\n<p class=\"p6\">\u201cSi no informamos a nuestra propia gente sobre nuestros derechos, nuestras obligaciones, nuestra autonom\u00eda, eso se pierde\u201d, dijo Lawrence. \u201cHay tantas maneras en que podemos ser creativos para difundir la palabra o prestar nuestras voces, recursos y cuerpos, pero este ser\u00e1 uno de esos momentos en los que es la \u00faltima resistencia para proteger el agua, el aire, nuestra Tierra y todas las fuentes de vida del capitalismo\u201d.<\/p>\n<p class=\"p6\">Como una ni\u00f1a que creci\u00f3 en el sistema de cuidado tutelar, Lawrence comprende lo que es ser una persona joven y sentir que no se le defiende. Pero con todo lo que est\u00e1 sucediendo en el mundo, ella sigue siendo optimista, inspirada por el liderazgo de las generaciones m\u00e1s j\u00f3venes y decidida a ayudar a elevar sus voces.<\/p>\n<p class=\"p6\">\u201cTenemos que pensar en lo que nuestras acciones de hoy har\u00e1n y ser\u00e1n para los j\u00f3venes\u201d, dijo. \u201cPensar en ellos en nuestras decisiones nos mantiene activos y es una ense\u00f1anza que debemos honrar\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con m\u00fasica basada en el hip hop, la artista suquamish Calina Lawrence lleva un mensaje de resistencia y solidaridad al estudio de grabaci\u00f3n y al escenario, abogando por causas que golpean cerca de casa. Nacida y criada en la reserva india de Port Madison, a sus 26 a\u00f1os celebra el legado dx\u02b7s\u0259q\u02b7\u0259b, una frase de [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":41525,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_popups_has_disabled_popups":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3519],"tags":[18272,18274,18276],"coauthors":[],"class_list":["post-41523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-calina-lawrence-es","tag-lushootseed-es","tag-suquamish-es","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cantante ind\u00edgena preserva su cultura del colonialismo mediante el rap - El Tecolote<\/title>\n<meta name=\"description\" content=\"Con m\u00fasica basada en el hip hop, la artista suquamish Calina Lawrence lleva un mensaje de resistencia y solidaridad al estudio de grabaci\u00f3n y al\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltecolote.org\/content\/es\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cantante ind\u00edgena preserva su cultura del colonialismo mediante el rap - El Tecolote\" \/>\n<meta property=\"og:description\" content=\"Con m\u00fasica basada en el hip hop, la artista suquamish Calina Lawrence lleva un mensaje de resistencia y solidaridad al estudio de grabaci\u00f3n y al\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltecolote.org\/content\/es\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\/\" \/>\n<meta property=\"og:site_name\" content=\"El Tecolote\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTecoloteSF\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-12T19:49:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/09\/CalinaLawrence_F0A9484-WEB-1.jpg?fit=1613%2C1075&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1613\" \/>\n\t<meta property=\"og:image:height\" content=\"1075\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"El Tecolote Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:site\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Tecolote Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\\\/\"},\"author\":{\"name\":\"El Tecolote Staff\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\"},\"headline\":\"Cantante ind\u00edgena preserva su cultura del colonialismo mediante el rap\",\"datePublished\":\"2019-09-12T19:49:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\\\/\"},\"wordCount\":1508,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/CalinaLawrence_F0A9484-WEB-1.jpg?fit=1613%2C1075&quality=89&ssl=1\",\"keywords\":[\"Calina Lawrence\",\"Lushootseed\",\"Suquamish\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\\\/\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\\\/\",\"name\":\"Cantante ind\u00edgena preserva su cultura del colonialismo mediante el rap - El Tecolote\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/CalinaLawrence_F0A9484-WEB-1.jpg?fit=1613%2C1075&quality=89&ssl=1\",\"datePublished\":\"2019-09-12T19:49:11+00:00\",\"description\":\"Con m\u00fasica basada en el hip hop, la artista suquamish Calina Lawrence lleva un mensaje de resistencia y solidaridad al estudio de grabaci\u00f3n y al\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/CalinaLawrence_F0A9484-WEB-1.jpg?fit=1613%2C1075&quality=89&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/CalinaLawrence_F0A9484-WEB-1.jpg?fit=1613%2C1075&quality=89&ssl=1\",\"width\":1613,\"height\":1075,\"caption\":\"La m\u00fasico Calina Lawrence, contempla el oc\u00e9ano en Lands End. Foto: Brianna Kalajian\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"name\":\"El Tecolote\",\"description\":\"San Francisco&#039;s Latinx newspaper since 1970\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\",\"name\":\"El Tecolote\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"width\":400,\"height\":400,\"caption\":\"El Tecolote\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTecoloteSF\\\/\",\"https:\\\/\\\/x.com\\\/eltecolotesf\",\"https:\\\/\\\/www.instagram.com\\\/eltecolotesf\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\",\"name\":\"El Tecolote Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"caption\":\"El Tecolote Staff\"},\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/author\\\/web-editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cantante ind\u00edgena preserva su cultura del colonialismo mediante el rap - El Tecolote","description":"Con m\u00fasica basada en el hip hop, la artista suquamish Calina Lawrence lleva un mensaje de resistencia y solidaridad al estudio de grabaci\u00f3n y al","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltecolote.org\/content\/es\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\/","og_locale":"en_US","og_type":"article","og_title":"Cantante ind\u00edgena preserva su cultura del colonialismo mediante el rap - El Tecolote","og_description":"Con m\u00fasica basada en el hip hop, la artista suquamish Calina Lawrence lleva un mensaje de resistencia y solidaridad al estudio de grabaci\u00f3n y al","og_url":"https:\/\/eltecolote.org\/content\/es\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\/","og_site_name":"El Tecolote","article_publisher":"https:\/\/www.facebook.com\/ElTecoloteSF\/","article_published_time":"2019-09-12T19:49:11+00:00","og_image":[{"width":1613,"height":1075,"url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/09\/CalinaLawrence_F0A9484-WEB-1.jpg?fit=1613%2C1075&ssl=1","type":"image\/jpeg"}],"author":"El Tecolote Staff","twitter_card":"summary_large_image","twitter_creator":"@eltecolotesf","twitter_site":"@eltecolotesf","twitter_misc":{"Written by":"El Tecolote Staff","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/eltecolote.org\/content\/es\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\/#article","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/es\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\/"},"author":{"name":"El Tecolote Staff","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e"},"headline":"Cantante ind\u00edgena preserva su cultura del colonialismo mediante el rap","datePublished":"2019-09-12T19:49:11+00:00","mainEntityOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\/"},"wordCount":1508,"commentCount":0,"publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/09\/CalinaLawrence_F0A9484-WEB-1.jpg?fit=1613%2C1075&quality=89&ssl=1","keywords":["Calina Lawrence","Lushootseed","Suquamish"],"articleSection":["Noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eltecolote.org\/content\/es\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eltecolote.org\/content\/es\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\/","url":"https:\/\/eltecolote.org\/content\/es\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\/","name":"Cantante ind\u00edgena preserva su cultura del colonialismo mediante el rap - El Tecolote","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\/#primaryimage"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/09\/CalinaLawrence_F0A9484-WEB-1.jpg?fit=1613%2C1075&quality=89&ssl=1","datePublished":"2019-09-12T19:49:11+00:00","description":"Con m\u00fasica basada en el hip hop, la artista suquamish Calina Lawrence lleva un mensaje de resistencia y solidaridad al estudio de grabaci\u00f3n y al","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltecolote.org\/content\/es\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eltecolote.org\/content\/es\/cantante-indigena-preserva-su-cultura-del-colonialismo-mediante-el-rap\/#primaryimage","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/09\/CalinaLawrence_F0A9484-WEB-1.jpg?fit=1613%2C1075&quality=89&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/09\/CalinaLawrence_F0A9484-WEB-1.jpg?fit=1613%2C1075&quality=89&ssl=1","width":1613,"height":1075,"caption":"La m\u00fasico Calina Lawrence, contempla el oc\u00e9ano en Lands End. Foto: Brianna Kalajian"},{"@type":"WebSite","@id":"https:\/\/eltecolote.org\/content\/#website","url":"https:\/\/eltecolote.org\/content\/","name":"El Tecolote","description":"San Francisco&#039;s Latinx newspaper since 1970","publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltecolote.org\/content\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/eltecolote.org\/content\/#organization","name":"El Tecolote","url":"https:\/\/eltecolote.org\/content\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","width":400,"height":400,"caption":"El Tecolote"},"image":{"@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTecoloteSF\/","https:\/\/x.com\/eltecolotesf","https:\/\/www.instagram.com\/eltecolotesf\/"]},{"@type":"Person","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e","name":"El Tecolote Staff","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d","url":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","caption":"El Tecolote Staff"},"url":"https:\/\/eltecolote.org\/content\/author\/web-editor\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"El Tecolote","distributor_original_site_url":"https:\/\/eltecolote.org\/content","push-errors":false,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/09\/CalinaLawrence_F0A9484-WEB-1.jpg?fit=1613%2C1075&quality=89&ssl=1","_links":{"self":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/41523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/comments?post=41523"}],"version-history":[{"count":1,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/41523\/revisions"}],"predecessor-version":[{"id":41524,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/41523\/revisions\/41524"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media\/41525"}],"wp:attachment":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media?parent=41523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/categories?post=41523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/tags?post=41523"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/coauthors?post=41523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}