{"id":40928,"date":"2019-06-20T14:19:34","date_gmt":"2019-06-20T21:19:34","guid":{"rendered":"http:\/\/eltecolote.org\/content\/?p=40928"},"modified":"2019-06-20T14:19:34","modified_gmt":"2019-06-20T21:19:34","slug":"desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible","status":"publish","type":"post","link":"https:\/\/eltecolote.org\/content\/es\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\/","title":{"rendered":"Desarrollo en la Misi\u00f3n proyectado para ser totalmente vivienda asequible"},"content":{"rendered":"<figure id=\"attachment_40929\" aria-describedby=\"caption-attachment-40929\" style=\"width: 1151px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/06\/1515VanNess-D7K_3997-1.jpg?quality=89&#038;ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-40929\" src=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/06\/1515VanNess-D7K_3997-1.jpg?resize=1151%2C822&#038;quality=89&#038;ssl=1\" alt=\"\" width=\"1151\" height=\"822\" srcset=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/06\/1515VanNess-D7K_3997-1.jpg?w=1151&amp;quality=89&amp;ssl=1 1151w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/06\/1515VanNess-D7K_3997-1.jpg?resize=600%2C428&amp;quality=89&amp;ssl=1 600w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/06\/1515VanNess-D7K_3997-1.jpg?resize=350%2C250&amp;quality=89&amp;ssl=1 350w, https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/06\/1515VanNess-D7K_3997-1.jpg?resize=768%2C548&amp;quality=89&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><figcaption id=\"caption-attachment-40929\" class=\"wp-caption-text\">La alcaldesa London Breed anunci\u00f3 el 11 de junio que la Ciudad destinar\u00e1 el proyecto 1515 de South Van Ness a vivienda accesible. Foto: David Mamaril Horowitz<\/figcaption><\/figure>\n<p class=\"p1\"><b><\/b>La propuesta controversial para el desarrollo de viviendas ubicado en el 1515 de la avenida South Van Ness (apodado por sus detractores como \u2018el desastre tit\u00e1nico de South Van Ness\u2019), parece haberse convertido esta semana en una gran victoria para los activistas de vivienda de la Misi\u00f3n.<\/p>\n<p class=\"p6\">Despu\u00e9s de a\u00f1os de protestas de la comunidad en contra del proyecto, la alcaldesa London Breed anunci\u00f3 el 11 de junio que la ciudad adquiri\u00f3 la propiedad del desarrollador inmobiliario Lennar Multifamily Communities LLC. En el sitio actualmente desocupado de casi 3 mil metros cuadrados, San Francisco va a \u201cpotencialmente construir 150 nuevas unidades familiares\u201d \u2014todas permanentemente costeables y probablemente sirviendo a familias que ganen entre 35 y 80 por ciento del ingreso medio en la zona, de acuerdo al comunicado de prensa de la oficina de la alcaldesa.<\/p>\n<p class=\"p6\">Las unidades econ\u00f3micas, las cuales se unir\u00e1n a otras novecientas actualmente en construcci\u00f3n en la Misi\u00f3n, ser\u00e1n pagadas por los reembolsos de impuestos a la propiedad, as\u00ed como por el fondo JumpStart de la Comisi\u00f3n Metropolitana de Transporte, de acuerdo con dicho comunicado.<\/p>\n<p class=\"p6\">\u201cSi no queremos que San Francisco contin\u00fae cambiando de manera tan significativa, donde ya no reconocemos a los vecindarios, vamos a tener que hacer una inversi\u00f3n agresiva en vivienda econ\u00f3mica\u201d, dijo Breed y agreg\u00f3: \u201cDe eso se trata el d\u00eda de hoy\u201d.<\/p>\n<p class=\"p6\">Roberto Hern\u00e1ndez, originario de San Francisco, quien dirige la campa\u00f1a \u201cOur Mission No Eviction\u201d (Nuestra Misi\u00f3n sin desalojo), ha esperado cinco a\u00f1os para este anuncio. \u201cMantuve mi mirada en \u00e9l y nunca vi la gr\u00faa venir a excavar un hoyo\u201d, dijo Hern\u00e1ndez. \u201cEso me dio esperanzas\u201d.<\/p>\n<p class=\"p6\">Protestar en contra del desarrollo parec\u00eda, hasta hace poco, una causa perdida. Luego de que miembros de la comunidad rechazaran en repetidas ocasiones la propuesta del proyecto de Lennar de 157 unidades, el desarrollador propuso incluir 25 por ciento de vivienda econ\u00f3mica, pagar $1 mill\u00f3n a un distrito cultural y ofrecer espacios a nivel de piso m\u00e1s econ\u00f3micos.<\/p>\n<p class=\"p6\">La Junta de Supervisores finalmente aprob\u00f3 el proyecto en 2017, pero nunca comenz\u00f3 su construcci\u00f3n. Hern\u00e1ndez ha visto el cambio del vecindario a trav\u00e9s de los a\u00f1os, con amigos siendo forzados a irse. Luego de recientemente participar en un tour por la Misi\u00f3n de low-rider junto con Breed, en un punto se detuvieron en el 1515 de la avenida Van Ness.<\/p>\n<p class=\"p6\">Myrna Melgar, presidenta de la Comisi\u00f3n de Planeaci\u00f3n de San Francisco, tambi\u00e9n reafirm\u00f3 la importancia de proveer vivienda econ\u00f3mica: \u201cQuiero a mi familia cerca; quiero a mi comunidad alrededor m\u00edo. Es lo que hace que valga la pena vivir\u201d, dijo Melgar. \u201cCreo que no hay nada m\u00e1s importante ahora que construir vivienda econ\u00f3mica\u201d.<\/p>\n<p class=\"p6\">Breed aprovech\u00f3 la oportunidad para impulsar el bono, propuesto por ella y el presidente de la Junta de Supervisores, Norman Yee, de $600 millones para vivienda econ\u00f3mica, el cual estar\u00e1 en la boleta electoral este noviembre: \u201cTenemos el dinero para comprar el terreno, pero necesitamos recursos para construirlo\u201d, dijo Breed. \u201cNuestro futuro depende de ello. No quiero lo que nos pas\u00f3 a tantos de nosotros que crecimos en esta ciudad: nacimos y fuimos criados aqu\u00ed, y luego nos volteamos y miramos, y nos quedamos preguntando, \u2018D\u00f3nde est\u00e1 nuestra comunidad?\u2019\u201d<\/p>\n<p class=\"p6\">Una vez que la Junta apruebe la compra del terreno \u2014y se identifique el financiamiento para la construcci\u00f3n\u2014, San Francisco elegir\u00e1 un desarrollador para dirigir el proyecto. Una vez completado, ser\u00e1 el octavo proyecto de vivienda econ\u00f3mica en la Misi\u00f3n, llevando el conteo de unidades econ\u00f3micas del vecindario a m\u00e1s de mil.<b> <\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La propuesta controversial para el desarrollo de viviendas ubicado en el 1515 de la avenida South Van Ness (apodado por sus detractores como \u2018el desastre tit\u00e1nico de South Van Ness\u2019), parece haberse convertido esta semana en una gran victoria para los activistas de vivienda de la Misi\u00f3n. Despu\u00e9s de a\u00f1os de protestas de la comunidad [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":40929,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_popups_has_disabled_popups":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[3519,3575],"tags":[9209],"coauthors":[],"class_list":["post-40928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-vivienda-es","tag-1515-south-van-ness-es","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Desarrollo en la Misi\u00f3n proyectado para ser totalmente vivienda asequible - El Tecolote<\/title>\n<meta name=\"description\" content=\"La propuesta controversial para el desarrollo de viviendas ubicado en el 1515 de la avenida South Van Ness (apodado por sus detractores como \u2018el desastre\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltecolote.org\/content\/es\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desarrollo en la Misi\u00f3n proyectado para ser totalmente vivienda asequible - El Tecolote\" \/>\n<meta property=\"og:description\" content=\"La propuesta controversial para el desarrollo de viviendas ubicado en el 1515 de la avenida South Van Ness (apodado por sus detractores como \u2018el desastre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltecolote.org\/content\/es\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\/\" \/>\n<meta property=\"og:site_name\" content=\"El Tecolote\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTecoloteSF\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-20T21:19:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/06\/1515VanNess-D7K_3997-1.jpg?fit=1151%2C822&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1151\" \/>\n\t<meta property=\"og:image:height\" content=\"822\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"El Tecolote Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:site\" content=\"@eltecolotesf\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Tecolote Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\\\/\"},\"author\":{\"name\":\"El Tecolote Staff\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\"},\"headline\":\"Desarrollo en la Misi\u00f3n proyectado para ser totalmente vivienda asequible\",\"datePublished\":\"2019-06-20T21:19:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\\\/\"},\"wordCount\":655,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/1515VanNess-D7K_3997-1.jpg?fit=1151%2C822&quality=89&ssl=1\",\"keywords\":[\"1515 South Van Ness\"],\"articleSection\":[\"Noticias\",\"Vivienda\"],\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\\\/\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\\\/\",\"name\":\"Desarrollo en la Misi\u00f3n proyectado para ser totalmente vivienda asequible - El Tecolote\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/1515VanNess-D7K_3997-1.jpg?fit=1151%2C822&quality=89&ssl=1\",\"datePublished\":\"2019-06-20T21:19:34+00:00\",\"description\":\"La propuesta controversial para el desarrollo de viviendas ubicado en el 1515 de la avenida South Van Ness (apodado por sus detractores como \u2018el desastre\",\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/es\\\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/1515VanNess-D7K_3997-1.jpg?fit=1151%2C822&quality=89&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/1515VanNess-D7K_3997-1.jpg?fit=1151%2C822&quality=89&ssl=1\",\"width\":1151,\"height\":822,\"caption\":\"La alcaldesa London Breed anunci\u00f3 el 11 de junio que la Ciudad destinar\u00e1 el proyecto 1515 de South Van Ness a vivienda accesible. Foto: David Mamaril Horowitz\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#website\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"name\":\"El Tecolote\",\"description\":\"San Francisco's Latinx newspaper since 1970\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#organization\",\"name\":\"El Tecolote\",\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eltecolote.org\\\/content\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/ETlogo-1.jpg?fit=400%2C400&ssl=1\",\"width\":400,\"height\":400,\"caption\":\"El Tecolote\"},\"image\":{\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTecoloteSF\\\/\",\"https:\\\/\\\/x.com\\\/eltecolotesf\",\"https:\\\/\\\/www.instagram.com\\\/eltecolotesf\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/#\\\/schema\\\/person\\\/08828d10185eba96895a8363a269410e\",\"name\":\"El Tecolote Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g\",\"caption\":\"El Tecolote Staff\"},\"url\":\"https:\\\/\\\/eltecolote.org\\\/content\\\/author\\\/web-editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desarrollo en la Misi\u00f3n proyectado para ser totalmente vivienda asequible - El Tecolote","description":"La propuesta controversial para el desarrollo de viviendas ubicado en el 1515 de la avenida South Van Ness (apodado por sus detractores como \u2018el desastre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltecolote.org\/content\/es\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\/","og_locale":"en_US","og_type":"article","og_title":"Desarrollo en la Misi\u00f3n proyectado para ser totalmente vivienda asequible - El Tecolote","og_description":"La propuesta controversial para el desarrollo de viviendas ubicado en el 1515 de la avenida South Van Ness (apodado por sus detractores como \u2018el desastre","og_url":"https:\/\/eltecolote.org\/content\/es\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\/","og_site_name":"El Tecolote","article_publisher":"https:\/\/www.facebook.com\/ElTecoloteSF\/","article_published_time":"2019-06-20T21:19:34+00:00","og_image":[{"width":1151,"height":822,"url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/06\/1515VanNess-D7K_3997-1.jpg?fit=1151%2C822&ssl=1","type":"image\/jpeg"}],"author":"El Tecolote Staff","twitter_card":"summary_large_image","twitter_creator":"@eltecolotesf","twitter_site":"@eltecolotesf","twitter_misc":{"Written by":"El Tecolote Staff","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/eltecolote.org\/content\/es\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\/#article","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/es\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\/"},"author":{"name":"El Tecolote Staff","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e"},"headline":"Desarrollo en la Misi\u00f3n proyectado para ser totalmente vivienda asequible","datePublished":"2019-06-20T21:19:34+00:00","mainEntityOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\/"},"wordCount":655,"commentCount":0,"publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/06\/1515VanNess-D7K_3997-1.jpg?fit=1151%2C822&quality=89&ssl=1","keywords":["1515 South Van Ness"],"articleSection":["Noticias","Vivienda"],"inLanguage":"en","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eltecolote.org\/content\/es\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eltecolote.org\/content\/es\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\/","url":"https:\/\/eltecolote.org\/content\/es\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\/","name":"Desarrollo en la Misi\u00f3n proyectado para ser totalmente vivienda asequible - El Tecolote","isPartOf":{"@id":"https:\/\/eltecolote.org\/content\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltecolote.org\/content\/es\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\/#primaryimage"},"image":{"@id":"https:\/\/eltecolote.org\/content\/es\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/06\/1515VanNess-D7K_3997-1.jpg?fit=1151%2C822&quality=89&ssl=1","datePublished":"2019-06-20T21:19:34+00:00","description":"La propuesta controversial para el desarrollo de viviendas ubicado en el 1515 de la avenida South Van Ness (apodado por sus detractores como \u2018el desastre","inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltecolote.org\/content\/es\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\/"]}]},{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/eltecolote.org\/content\/es\/desarrollo-en-la-mision-proyectado-para-ser-totalmente-vivienda-asequible\/#primaryimage","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/06\/1515VanNess-D7K_3997-1.jpg?fit=1151%2C822&quality=89&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2019\/06\/1515VanNess-D7K_3997-1.jpg?fit=1151%2C822&quality=89&ssl=1","width":1151,"height":822,"caption":"La alcaldesa London Breed anunci\u00f3 el 11 de junio que la Ciudad destinar\u00e1 el proyecto 1515 de South Van Ness a vivienda accesible. Foto: David Mamaril Horowitz"},{"@type":"WebSite","@id":"https:\/\/eltecolote.org\/content\/#website","url":"https:\/\/eltecolote.org\/content\/","name":"El Tecolote","description":"San Francisco's Latinx newspaper since 1970","publisher":{"@id":"https:\/\/eltecolote.org\/content\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltecolote.org\/content\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en"},{"@type":"Organization","@id":"https:\/\/eltecolote.org\/content\/#organization","name":"El Tecolote","url":"https:\/\/eltecolote.org\/content\/","logo":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eltecolote.org\/content\/wp-content\/uploads\/2021\/05\/ETlogo-1.jpg?fit=400%2C400&ssl=1","width":400,"height":400,"caption":"El Tecolote"},"image":{"@id":"https:\/\/eltecolote.org\/content\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTecoloteSF\/","https:\/\/x.com\/eltecolotesf","https:\/\/www.instagram.com\/eltecolotesf\/"]},{"@type":"Person","@id":"https:\/\/eltecolote.org\/content\/#\/schema\/person\/08828d10185eba96895a8363a269410e","name":"El Tecolote Staff","image":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g6afcb607783e095e4cf6be807353924d","url":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9534c92c8c908364e186a64d93efc86f62367109d1b07a3454facde655968589?s=96&d=mm&r=g","caption":"El Tecolote Staff"},"url":"https:\/\/eltecolote.org\/content\/author\/web-editor\/"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"El Tecolote","distributor_original_site_url":"https:\/\/eltecolote.org\/content","push-errors":false,"_links":{"self":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/40928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/comments?post=40928"}],"version-history":[{"count":1,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/40928\/revisions"}],"predecessor-version":[{"id":40930,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/posts\/40928\/revisions\/40930"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media\/40929"}],"wp:attachment":[{"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/media?parent=40928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/categories?post=40928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/tags?post=40928"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/eltecolote.org\/content\/wp-json\/wp\/v2\/coauthors?post=40928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}